﻿{"id":7289,"date":"2024-06-05T04:00:00","date_gmt":"2024-06-05T04:00:00","guid":{"rendered":"https:\/\/gpph-group.com\/?p=7289"},"modified":"2025-02-21T06:49:25","modified_gmt":"2025-02-21T06:49:25","slug":"incontro-di-appassionati-di-saldatura-terza-edizione-di-integration-forumgpphpl","status":"publish","type":"post","link":"https:\/\/gpph-group.com\/it\/notizia\/incontro-di-appassionati-di-saldatura-terza-edizione-di-integration-forumgpphpl\/","title":{"rendered":"Incontro di appassionati di saldatura - Terza edizione di Integration Forum.GPPH.pl"},"content":{"rendered":"<p><strong>Incontro di appassionati di saldatura - Terza edizione di Integration Forum.GPPH.pl<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\" translation-block\">L'evento annuale di integrazione organizzato da GPPH, dedicato agli utenti di Forum.GPPH.pl, \u00e8 ormai storia. L'<strong>evento si \u00e8 tenuto per la terza volta e ha riunito un numero record di persone legate al settore della saldatura<\/strong>. L'evento, che ogni anno suscita grande interesse, \u00e8 stato un'occasione per fare preziose conoscenze e condividere esperienze che possono aprire le porte a nuove opportunit\u00e0 di cooperazione e sviluppo. Lo <strong>scopo dell'evento \u00e8 stato riassunto da Krzysztof Rze\u017anik, co-proprietario di GPPH<\/strong>: <em>\"Abbiamo creato il nostro social network per riunire le persone del settore della lavorazione dei metalli. Volevamo che avessero un luogo dedicato, diverso da quelli che hanno avuto finora. Gli utenti del nostro forum fanno amicizia tra loro nel mondo virtuale. Sappiamo anche che queste persone comunicano tra loro per telefono. Qui possono conoscersi di persona, passare del tempo insieme. Questi legami che si creano tra loro possono influenzare meglio il loro lavoro quotidiano e le amicizie che sappiamo si formano qui e continuano fino ad oggi\".<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-1024x683.jpeg\" alt=\"Partecipanti alla terza edizione del Forum Integration nel 2024\u00a0\" class=\"wp-image-7298\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-1024x683.jpeg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-600x400.jpeg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-64x43.jpeg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-300x200.jpeg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-768x512.jpeg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-18x12.jpeg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10.jpeg 1386w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Partecipanti alla terza edizione del Forum Integration nel 2024<\/em>\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\" translation-block\">Come nelle precedenti edizioni, anche quest'anno il <strong>Forum Integration \u00e8 stato suddiviso in una parte ufficiale, <\/strong>tenutasi presso lo showroom GPPH, <strong>e in una parte di intrattenimento<\/strong>, svoltasi nel ristorante. L'inizio dell'evento \u00e8 stato inaugurato dai proprietari dell'azienda:<\/p>\n\n\n\n<p class=\" translation-block\"><strong>Wies\u0142aw Piechota<\/strong>: \"Vorremmo <em>dare a tutti voi il benvenuto a un cos\u00ec grande raduno per la terza edizione del forum GPPH. Spero che farete molte nuove e fruttuose conoscenze e che trascorrerete il vostro tempo nel miglior modo possibile\".<\/em><\/p>\n\n\n\n<p class=\" translation-block\"><strong>Krzysztof Rze\u017anik<\/strong>: <em>\"Il nostro obiettivo oggi \u00e8 conoscere ancora meglio le persone che non abbiamo visto di persona e conoscere quelle con cui siamo entrati in contatto solo online\".<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-1024x576.jpeg\" alt=\"Partecipanti al Forum Intagration durante la presentazione dei prodotti GPPH\u00a0\" class=\"wp-image-7297\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-1024x576.jpeg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-600x337.jpeg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-64x36.jpeg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-300x169.jpeg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-768x432.jpeg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-18x10.jpeg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11.jpeg 1387w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Partecipanti al Forum Intagration durante la presentazione dei prodotti GPPH<\/em>\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\" translation-block\">Come \u00e8 emerso, gli utenti della comunit\u00e0 online dell'azienda hanno effettivamente stabilito molti contatti preziosi tra loro. Alla domanda: \"<strong>Hai fatto nuove amicizie grazie al nostro forum?<\/strong>\", hanno risposto: \"Per quanto possibile, ho incontrato soprattutto persone di persona, non solo scrivendo e cliccando, ma anche fisicamente\", \"Grazie al forum s\u00ec, per quanto possibile. Ci sono persone eccezionali del settore della saldatura che possono scambiare esperienze tra loro\".<\/p>\n\n\n\n<p>Nella prima parte dell'incontro, il reparto vendite di GPPH ha presentato tutti i prodotti che fanno parte dell'offerta dell'azienda e, in anteprima, le novit\u00e0. Inoltre, \u00e8 stato presentato un filmato sulla storia dell'azienda e, nel frattempo, ogni partecipante all'evento ha avuto l'opportunit\u00e0 di esercitarsi nella costruzione da competizione, che apparir\u00e0 alla fiera STOM di Kielce dal 19 al 22 marzo 2024. Dopo la parte ufficiale, tutti si sono diretti al ristorante, dove, oltre a una cena celebrativa e a una festa fino all'alba, un ospite speciale attendeva i partecipanti: il cantante stand-up Arkadiusz \"Jaksa\" Jakszewicz. Al mattino, prima di tornare a casa, tutti si sono ritrovati per fare colazione insieme.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-1024x683.jpeg\" alt=\"Prove dei partecipanti prima della gara &quot;Realizza una struttura il pi\u00f9 velocemente possibile e vinci un tavolo da saldatura&quot;.\u00a0\" class=\"wp-image-7299\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-1024x683.jpeg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-600x400.jpeg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-64x43.jpeg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-300x200.jpeg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-768x512.jpeg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-18x12.jpeg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12.jpeg 1385w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Prove dei partecipanti prima della gara \"Realizza una struttura il pi\u00f9 velocemente possibile e vinci un tavolo da saldatura\".<\/em>\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\" translation-block\">La terza edizione del <strong>Forum Integration ha registrato un record di presenze<\/strong>: <em>\"Siamo molto soddisfatti dell'affluenza che abbiamo avuto per la terza edizione dell'incontro dei forumer del GPPH. Possiamo vedere quante persone sono venute da tutto il Paese. Ci risulta che siano venuti anche dalla parte pi\u00f9 lontana del Paese, cio\u00e8 dal mare. \u00c8 una distanza enorme per venire a vedere i nostri prodotti e incontrare i forumisti. Siamo molto, molto orgogliosi di questo. Abbiamo clienti che vengono da noi, sostenitori, persone che hanno acquistato i nostri prodotti e anche persone che stanno per acquistarli. Quindi \u00e8 il luogo perfetto per conoscere i nostri prodotti e le persone che li realizzano\". - <\/em>Wieslaw Piechota, comproprietario di GPPH, conclude.<\/p>\n\n\n\n<p>Guarda la copertura video di Integration: <a href=\"https:\/\/www.youtube.com\/watch?v=LeqlImoBkBE&#038;t\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.youtube.com\/watch?v=LeqlImoBkBE&amp;t<\/a>&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>L'evento annuale di integrazione organizzato da GPPH, dedicato agli utenti di Forum.GPPH.pl, \u00e8 ormai storia. L'evento si \u00e8 tenuto per la terza volta e ha riunito un numero record di persone legate al settore della saldatura. L'evento, che ogni anno suscita grande interesse, \u00e8 stato un'occasione per fare preziose conoscenze e condividere esperienze che possono aprire le porte a nuove opportunit\u00e0 di cooperazione e sviluppo. <\/p>","protected":false},"author":4,"featured_media":7298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-7289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/posts\/7289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/comments?post=7289"}],"version-history":[{"count":0,"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/posts\/7289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/media\/7298"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/media?parent=7289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/categories?post=7289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/it\/wp-json\/wp\/v2\/tags?post=7289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}