﻿{"id":37129,"date":"2026-06-12T07:36:00","date_gmt":"2026-06-12T05:36:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=37129"},"modified":"2026-06-15T09:27:47","modified_gmt":"2026-06-15T07:27:47","slug":"outlet-table-de-soudage-smart-12mm-1500x1480mm-systeme-fi16-grille-diagonale-w12","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/fr\/p\/magasin-dusine\/outlet-table-de-soudage-smart-12mm-1500x1480mm-systeme-fi16-grille-diagonale-w12\/","title":{"rendered":"[OUTLET] Table de soudage SMART 12 mm 1500x1480 mm - syst\u00e8me \u03c616, grille DIAG"},"content":{"rendered":"<p>Les tables de soudage sont l\u2019outil id\u00e9al partout o\u00f9 la pr\u00e9cision et la r\u00e9p\u00e9tabilit\u00e9 sont essentielles. Le plateau de 12 mm d\u2019\u00e9paisseur, dot\u00e9 d\u2019un renfort nervur\u00e9 dense, garantit une parfaite plan\u00e9it\u00e9 et une grande stabilit\u00e9, m\u00eame pour les structures les plus lourdes. Le syst\u00e8me de trous \u03c616 frais\u00e9s et chanfrein\u00e9s dispos\u00e9s en grille diagonale facilite le montage des outils, ce qui acc\u00e9l\u00e8re et simplifie le travail.<\/p>\n<p><strong>Caract\u00e9ristiques principales de la table :<\/strong><\/p>\n<ul>\n<li>Plateau de 12 mm d\u2019\u00e9paisseur avec un nervurage dense, garantissant une surface de travail parfaitement plane.<\/li>\n<li>Dimensions : 1500 \u00d7 1480 mm, 2 nervures longitudinales et 2 nervures transversales, garantissant la stabilit\u00e9 pendant l'utilisation et la r\u00e9sistance \u00e0 la d\u00e9formation.<\/li>\n<li>Grille diagonale, syst\u00e8me \u03c616<\/li>\n<\/ul>\n<p>Le plateau est en outre \u00e9quip\u00e9 d\u2019un marquage grav\u00e9 en grille de 100\u00d7100 mm, facilitant le positionnement pr\u00e9cis des structures et le montage des outils, garantissant une grande pr\u00e9cision \u00e0 chaque op\u00e9ration.<\/p>\n<p><strong>Options de pieds :\u00a0<\/strong><\/p>\n<ul>\n<li>Sur pieds fixes \u2013 assurent une grande stabilit\u00e9 et une capacit\u00e9 de charge \u00e9lev\u00e9e.<\/li>\n<li>Sur roulettes \u2013 id\u00e9al pour les travaux n\u00e9cessitant la mobilit\u00e9 de la table.<\/li>\n<\/ul>\n<p>En achetant ce produit, vous pouvez choisir une version avec pieds fixes ou sur roulettes.<\/p>\n<p>Les pieds de la table, fabriqu\u00e9s \u00e0 partir d\u2019un profil\u00e9 de 60x60 mm, supportent une charge maximale de 2000 kg. La table reste ainsi stable m\u00eame sous de fortes charges.<\/p>\n<p class=\" translation-block\">En achetant une table outlet, vous d\u00e9clarez avoir <strong>pris connaissance de son \u00e9tat r\u00e9el<\/strong> et <strong>l\u2019accepter sans droit \u00e0 r\u00e9clamation<\/strong>. Conform\u00e9ment \u00e0 l\u2019article 557 \u00a7 1 du Code civil polonais, le vendeur est exon\u00e9r\u00e9 de responsabilit\u00e9 pour vices cach\u00e9s si l\u2019acheteur avait connaissance du d\u00e9faut au moment de la conclusion du contrat.<\/p>\n<p>Vous souhaitez en savoir plus sur les tables de soudage traditionnelles GPPH ? Consultez les informations sur la page d\u00e9di\u00e9e <a href=\"https:\/\/gpph-group.com\/fr\/produits\/table-de-soudage-traditionnelle\/\">tables de soudage traditionnelles.<\/a><a href=\"https:\/\/gpph-group.com\/fr\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0<\/a><\/p>\n<p id=\"defekty\"><strong>ATTENTION : La table pr\u00e9sente un d\u00e9faut :\u00a0<\/strong><\/p>\n<ul>\n<li>Coin ab\u00eem\u00e9<\/li>\n<\/ul>\n<p>Les photos des d\u00e9fauts sont pr\u00e9sent\u00e9es ci-dessous<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-683x1024.jpg\" alt=\"[OUTLET] Table de soudage SMART 12 mm 1500x1480 mm - syst\u00e8me \u03c616, grille diagonale\" class=\"wp-image-37133\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-683x1024.jpg 683w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-200x300.jpg 200w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-768x1152.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-1024x1536.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-1365x2048.jpg 1365w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-8x12.jpg 8w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-600x900.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-64x96.jpg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322163-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Nous vous invitons \u00e0 le d\u00e9couvrir <a href=\"https:\/\/gpph-group.com\/pl\/p\/stoly-spawalnicze\/ekonomiczne-stoly-spawalnicze\/stol-spawalniczy-smart-12-1500-x-1480-mm\/\" target=\"_blank\" rel=\"noopener\">produit \u00e0 part enti\u00e8re<\/a>. L'offre actuelle concerne un exemplaire outlet,<strong> disponible en quantit\u00e9 limit\u00e9e et \u00e0 un prix exceptionnellement attractif.<\/strong> <strong>UWAGA! St\u00f3\u0142 posiada defekt:<\/strong><\/p>\n<ul>\n<li>Coin ab\u00eem\u00e9<\/li>\n<\/ul>","protected":false},"featured_media":37137,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168],"product_tag":[],"class_list":{"0":"post-37129","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outlet","7":"product_shipping_class-stol-spawalniczy-2000","8":"pa_nogi-na-kolach","9":"pa_nogi-na-stopach","10":"pa_seria-smart12","11":"pa_siatka-100x100mm","12":"pa_siatka-diagonalna","13":"pa_srednica-otworow-351","14":"pa_wymiar-stolu-1500x1480","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable","23":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product\/37129","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/comments?post=37129"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media\/37137"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media?parent=37129"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_brand?post=37129"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_cat?post=37129"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_tag?post=37129"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}