﻿{"id":33272,"date":"2026-02-26T16:53:00","date_gmt":"2026-02-26T14:53:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=33272"},"modified":"2026-06-15T08:46:19","modified_gmt":"2026-06-15T06:46:19","slug":"equerre-de-soudage-200x300x150-mm-%cf%8628-plus-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/fr\/p\/entrepot\/narzedzia-przestrzenne\/equerre-de-soudage-200x300x150-mm-%cf%8628-plus-m\/","title":{"rendered":"\u00c9querre de soudage 200x300x150 mm \u2013 \u03c628 \u2013 PLUS"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>\u00c9querre de soudage \u2013 positionnement et fixation pr\u00e9cis des pi\u00e8ces<\/strong><\/h2>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>\u00c9querre de soudage<\/strong> est un outil de positionnement solide et pr\u00e9cis, utilis\u00e9 pour l\u2019assemblage et la soudure de pi\u00e8ces en acier sur des tables de soudage.<\/p>\n\n\n\n<p>La conception \u00e0 deux bases parall\u00e8les reli\u00e9es par des supports verticaux permet un positionnement stable et pr\u00e9cis des pi\u00e8ces \u00e0 angle droit, ce qui est essentiel pour la cr\u00e9ation de structures spatiales.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS.png\" alt=\"\u00c9querre de soudage 200x300x150 mm PLUS\" class=\"wp-image-25166 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS.png 1000w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_009_PLUS-64x64.png 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construction et fonctionnalit\u00e9<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Le bras lat\u00e9ral de l\u2019\u00e9querre est \u00e9quip\u00e9 d\u2019un <strong>ensemble de trous de fixation<\/strong>, permettant un positionnement flexible et une connexion avec d\u2019autres outils.<\/p>\n\n\n\n<p class=\" translation-block\">La base inf\u00e9rieure comporte un <strong>trou de fixation allong\u00e9<\/strong> (oblong), permettant un r\u00e9glage fluide de la position et un ajustement rapide pendant le travail.<\/p>\n\n\n\n<p class=\" translation-block\">La base sup\u00e9rieure est \u00e9quip\u00e9e de <strong>trous ronds<\/strong>, con\u00e7us pour un montage stable et une utilisation avec d\u2019autres outils.<\/p>\n\n\n\n<p class=\" translation-block\">Gr\u00e2ce au <strong>support inclin\u00e9<\/strong>, la structure gagne en rigidit\u00e9 et en stabilit\u00e9, ce qui facilite le positionnement pr\u00e9cis des pi\u00e8ces.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Utilisation de l\u2019\u00e9querre de soudage<\/strong><\/h3>\n\n\n\n<p>L\u2019\u00e9querre de soudage est id\u00e9ale pour :<br>\u2013 positionnement et fixation de profils, de tuyaux et de structures en acier,<br>\u2013 assemblage et contr\u00f4le des connexions \u00e0 angle droit,<br>\u2013 fabrication de cadres et de structures n\u00e9cessitant une grande pr\u00e9cision,<br>\u2013 r\u00e9alisation de travaux de soudage, de montage et de serrurerie.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compatibilit\u00e9 avec les tables de soudage<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Chaque \u00e9querre de soudage est disponible avec un syst\u00e8me de trous de <strong>\u03c616 mm<\/strong> et <strong>\u03c628 mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Selon la s\u00e9rie d\u2019outils choisie, il s\u2019adapte au type correspondant de table de soudage :<br>\u2013 <strong>EXPERT<\/strong> \u2013 pour les tables de la s\u00e9rie <strong>EXPERT<\/strong> (plateau de 25 mm) et <strong>XWT<\/strong> avec plateau de type EXPERT,<br>\u2013 <strong>PRO<\/strong> \u2013 pour les tables des s\u00e9ries <strong>PRO<\/strong>, <strong>XWT<\/strong> et <strong>MWT<\/strong> avec plateau de 15 mm,<br>\u2013 <strong>PLUS<\/strong> \u2013 pour les tables des s\u00e9ries <strong>PLUS<\/strong>, <strong>ECO<\/strong>, <strong>DIY<\/strong>, <strong>BASIC<\/strong> et <strong>XWT<\/strong> avec plateau de 12 mm et 8 mm.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construction et mat\u00e9riaux<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">L\u2019\u00e9querre de soudage est fabriqu\u00e9e en <strong>acier de construction de haute qualit\u00e9 S355J2+N<\/strong>, caract\u00e9ris\u00e9 par une grande r\u00e9sistance \u00e0 la d\u00e9formation et aux charges prolong\u00e9es en atelier.<\/p>\n\n\n\n<p>Chaque surface de travail est soigneusement usin\u00e9e, garantissant un ajustement parfait et un positionnement r\u00e9p\u00e9table.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Qualit\u00e9 de fabrication<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Chaque \u00e9l\u00e9ment est soumis \u00e0 un <strong>contr\u00f4le de qualit\u00e9<\/strong>, garantissant le plus haut niveau de fabrication, la pr\u00e9cision dimensionnelle et la fiabilit\u00e9 lors d\u2019une utilisation quotidienne.<\/p>\n\n\n\n<p class=\" translation-block\">Le produit est fabriqu\u00e9 en <strong>Pologne<\/strong> \u00e0 partir de mat\u00e9riaux r\u00e9pondant aux normes de qualit\u00e9 pour les aciers de construction, constituant un outil durable et pr\u00e9cis pour des applications de soudage professionnelles.<\/p>","protected":false},"excerpt":{"rendered":"<p>\u00c9querre de soudage 200x300x150 mm<\/p>","protected":false},"featured_media":25166,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[441,438],"product_tag":[],"class_list":{"0":"post-33272","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-narzedzia-przestrzenne","7":"product_cat-magazyn","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-plus","11":"pa_srednica-otworow-28-lub-16","12":"pa_system-fi28","13":"pa_typ-narzedzia-przestrzenne","14":"pa_wymiar-narzedzia-200x300x150mm","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable","23":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product\/33272","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/comments?post=33272"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media\/25166"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media?parent=33272"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_brand?post=33272"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_cat?post=33272"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_tag?post=33272"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}