﻿{"id":14893,"date":"2023-01-10T13:26:00","date_gmt":"2023-01-10T11:26:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=lacznik-kostka-1500x200x200mm"},"modified":"2026-06-01T00:03:20","modified_gmt":"2026-05-31T22:03:20","slug":"connecteur-cube-1500x200x200mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/fr\/p\/augmentation-de-la-surface\/connecteur-cube-1500x200x200mm\/","title":{"rendered":"Poutre - raccordement interm\u00e9diaire 1500x200x200mm"},"content":{"rendered":"<p>La poutre - raccordement interm\u00e9diaire 1500x200x200 est un outil destin\u00e9 \u00e0 relier deux tables de soudage tout en conservant leur fonctionnalit\u00e9, car le plateau de la table est \u00e9quip\u00e9 d'une grille et d'orifices de montage. Il permet de cr\u00e9er un poste de soudage de forme non standard en reliant un nombre illimit\u00e9 de tables afin d'obtenir un poste de travail adapt\u00e9 au projet.<\/p>\n<p>La poutre - raccordement interm\u00e9diaire 1500x200x200 est disponible dans les syst\u00e8mes et maillages suivants :<\/p>\n<ul>\n<li>syst\u00e8me de trous \u03c616 mm, grille de trous 50 x 50 mm, \u00e9paisseur 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<li>syst\u00e8me de trous \u03c616 mm, grille de trous diagonale, \u00e9paisseur 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<li>syst\u00e8me de trous \u03c628 mm, grille de trous diagonale, \u00e9paisseur 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<\/ul>\n<p>La poutre - raccordement interm\u00e9diaire de la s\u00e9rie EXPERT peut \u00eatre utilis\u00e9e pour les tables de soudage de la s\u00e9rie EXPERT.<\/p>\n<p>La poutre - raccordement interm\u00e9diaire de la s\u00e9rie PRO peut \u00eatre utilis\u00e9e pour les tables de soudage de la s\u00e9rie PRO, XWT avec plateau de la s\u00e9rie PRO, ainsi que pour les tables de soudage modulaires.<\/p>\n<p>La poutre - raccordement interm\u00e9diaire de la s\u00e9rie PLUS peut \u00eatre utilis\u00e9e pour les tables de soudage des s\u00e9ries PLUS, ECO, BASIC, XWT avec plateau de la s\u00e9rie PLUS.<\/p>","protected":false},"excerpt":{"rendered":"<p>La poutre - raccordement interm\u00e9diaire 1500x200x200 en treillis est un outil destin\u00e9 \u00e0 relier deux tables de soudage tout en conservant leur fonctionnalit\u00e9, car le plateau de la table est \u00e9quip\u00e9 d'un treillis et d'orifices de montage. Il permet de cr\u00e9er un poste de soudage de forme non standard en reliant un nombre illimit\u00e9 de tables afin d'obtenir un poste de travail adapt\u00e9 au projet.<\/p>","protected":false},"featured_media":26745,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[171,105],"product_tag":[],"class_list":{"0":"post-14893","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zwiekszanie-powierzchni","7":"product_cat-kostki-i-przedluzenia","8":"product_shipping_class-narzedzia","9":"pa_dla-stolu-eco","10":"pa_dla-stolu-expert","11":"pa_dla-stolu-plus","12":"pa_dla-stolu-pro","13":"pa_grubosc-narzedzia-8mm-11mm-15mm-25mm","14":"pa_seria-eco","15":"pa_seria-expert","16":"pa_seria-plus","17":"pa_seria-pro","18":"pa_siatka-50x50mm","19":"pa_siatka-diagonalna","20":"pa_srednica-otworow-28-lub-16","21":"pa_system-fi16","22":"pa_system-fi28","23":"pa_typ-narzedzia-kostki-i-przedluzenia","24":"pa_wymiar-narzedzia-1500x200x200mm","26":"first","27":"instock","28":"sale","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-variable","33":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product\/14893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/comments?post=14893"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media\/26745"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media?parent=14893"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_brand?post=14893"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_cat?post=14893"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_tag?post=14893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}