﻿{"id":14748,"date":"2023-01-03T13:50:00","date_gmt":"2023-01-03T11:50:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=trzpien-mocujacy-pro"},"modified":"2026-08-17T16:24:00","modified_gmt":"2026-08-17T14:24:00","slug":"boulon-de-montage-pro","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/fr\/p\/outils\/goupilles-et-broches\/boulon-de-montage-pro\/","title":{"rendered":"Boulon de montage PRO"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Boulon de montage \u2013 connexion s\u00fbre et rapide des outils pour tables de soudage<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Boulon de montage<\/strong> est un outil pr\u00e9cis con\u00e7u pour <strong>la fixation stable et la connexion des outils \u00e0 la table de soudage ainsi qu\u2019entre eux<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Il constitue un \u00e9l\u00e9ment cl\u00e9 du syst\u00e8me de fixation, permettant <strong>une connexion rapide, fiable et s\u00fbre des outils<\/strong> lors des travaux de soudage, de montage et de m\u00e9tallerie.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.002UNI_00_000-Trzpien-mocujacy-UNI-gwint.742-1024x1024.png\" alt=\"Boulon de montage rapide \u00e0 billes UNI fi28\" class=\"wp-image-4504 size-full\"\/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construction et fonctionnalit\u00e9<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Le boulon est \u00e9quip\u00e9 d\u2019un <strong>m\u00e9canisme \u00e0 billes de haute pr\u00e9cision<\/strong>, garantissant un verrouillage s\u00fbr dans les <strong>orifices de montage<\/strong> de la table ou de l\u2019outil.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>La t\u00eate du boulon<\/strong> est con\u00e7ue pour offrir <strong>une manipulation confortable et une prise s\u00fbre<\/strong> \u2013 elle comporte un <strong>empreinte hexagonale (Allen)<\/strong> ainsi qu\u2019une <strong>surface molet\u00e9e<\/strong>, permettant un serrage ou desserrage rapide \u00e0 la main, sans outils suppl\u00e9mentaires.<\/p>\n\n\n\n<p class=\" translation-block\">Gr\u00e2ce \u00e0 sa conception compacte et \u00e0 sa g\u00e9om\u00e9trie perfectionn\u00e9e, le boulon garantit <strong>une stabilit\u00e9 maximale de la connexion<\/strong> ainsi qu\u2019un <strong>positionnement pr\u00e9cis des \u00e9l\u00e9ments pendant le travail<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Applications<\/strong><\/h3>\n\n\n\n<p>Le boulon de montage est parfaitement adapt\u00e9 pour :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>la fixation des outils \u00e0 la surface de la table de soudage,<\/li>\n\n\n\n<li>la connexion des outils de soudage entre eux,<\/li>\n\n\n\n<li>la stabilisation des assemblages lors du montage et du soudage,<\/li>\n\n\n\n<li>l\u2019ex\u00e9cution de t\u00e2ches n\u00e9cessitant r\u00e9p\u00e9tabilit\u00e9 et positionnement pr\u00e9cis,<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Syst\u00e8me et compatibilit\u00e9<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Les boulons de montage GPPH sont disponibles en versions <strong>EXPERT, PRO, PLUS, ECOPLUS (r\u00e9glable)<\/strong> et <strong>UNI (\u00e0 montage rapide)<\/strong>.<br><br>Le mod\u00e8le <strong>EXPERT<\/strong> est disponible pour le syst\u00e8me de trous <strong>\u03c628 mm<\/strong>, tandis que les mod\u00e8les <strong>PRO, PLUS<\/strong> et <strong>ECOPLUS<\/strong> sont propos\u00e9s dans les syst\u00e8mes <strong>\u03c616 mm<\/strong> et <strong>\u03c628 mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>Le boulon de montage rapide UNI<\/strong> est la solution la plus <strong>universelle<\/strong>, permettant de combiner des outils et des tables de soudage de diff\u00e9rentes gammes \u2013 par exemple, fixer des outils <strong>PLUS<\/strong> sur une table de la gamme <strong>PRO<\/strong>, ou inversement.<br><br>Les boulons <strong>UNI<\/strong> existent dans les syst\u00e8mes <strong>\u03c616 mm<\/strong> et <strong>\u03c628 mm<\/strong>, ce qui permet leur utilisation dans diverses configurations de travail.<br><br>Ils sont un choix id\u00e9al lorsque vous disposez de tables et d\u2019outils de <strong>diff\u00e9rentes \u00e9paisseurs<\/strong>, assurant une fixation fiable dans une <strong>plage de r\u00e9glage de 20mm \u00e0 62mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Cette solution offre <strong>une compatibilit\u00e9 totale avec le syst\u00e8me de tables et d\u2019outils GPPH<\/strong>, garantissant un serrage stable et pr\u00e9cis pendant le travail.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mat\u00e9riau et fabrication<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La goupille est fabriqu\u00e9e en <strong>acier au carbone de haute qualit\u00e9<\/strong>, reconnu pour sa tr\u00e8s bonne r\u00e9sistance m\u00e9canique ainsi que sa r\u00e9sistance \u00e0 l\u2019usure et \u00e0 la d\u00e9formation.<\/p>\n\n\n\n<p class=\" translation-block\">Chaque \u00e9l\u00e9ment est soumis \u00e0 un <strong>contr\u00f4le de qualit\u00e9 rigoureux<\/strong>, garantissant les normes de fabrication les plus \u00e9lev\u00e9es, la pr\u00e9cision dimensionnelle et la fiabilit\u00e9 au quotidien.<\/p>\n\n\n\n<p class=\" translation-block\">Le produit est <strong>enti\u00e8rement fabriqu\u00e9 en Pologne<\/strong> \u00e0 partir de mat\u00e9riaux conformes aux normes de qualit\u00e9 pour les aciers de construction.<\/p>","protected":false},"excerpt":{"rendered":"<p>Le boulon de montage rapide PRO est utilis\u00e9 pour fixer les outils PRO sur les tables de soudage de la gamme PRO ou sur la table de soudage modulaire.\u00a0<\/p>","protected":false},"featured_media":33359,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[106,69],"product_tag":[],"class_list":{"0":"post-14748","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-trzpienie-i-piny","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_srednica-otworow-28-lub-16","10":"pa_system-fi16","11":"pa_system-fi28","12":"pa_typ-narzedzia-trzpien","13":"pa_wymiar-narzedzia-74x45x45mm","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product\/14748","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/comments?post=14748"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media\/33359"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/media?parent=14748"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_brand?post=14748"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_cat?post=14748"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/fr\/wp-json\/wp\/v2\/product_tag?post=14748"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}