﻿{"id":23015,"date":"2025-08-08T12:02:00","date_gmt":"2025-08-08T10:02:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=23015"},"modified":"2026-06-15T08:52:04","modified_gmt":"2026-06-15T06:52:04","slug":"conector-bloque-1200x200x200mm-%cf%8628-pro-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_uy\/p\/deposito\/ampliacion-de-superficie\/conector-bloque-1200x200x200mm-%cf%8628-pro-m\/","title":{"rendered":"Conector, cubo 1200 x 200 x 200 mm, \u03c628 PRO"},"content":{"rendered":"<p class=\" translation-block\">El bloque de sujeci\u00f3n <span class=\"seriaText\"><\/span> 1200x200x200 es una herramienta dise\u00f1ada para unir dos mesas de soldadura, manteniendo su funcionalidad, ya que la superficie de la mesa tiene una rejilla y orificios de montaje. Se puede utilizar para crear una estaci\u00f3n de soldadura con una forma no est\u00e1ndar, uniendo cualquier n\u00famero de mesas para crear una estaci\u00f3n de trabajo adaptada al proyecto en cuesti\u00f3n.<\/p>\n<p>El bloque de sujeci\u00f3n 1200x200x200 est\u00e1 disponible en los siguientes sistemas y redes de orificios:<\/p>\n<ul>\n<li>sistema de orificios \u03c616 mm, malla de orificios 50 x 50 mm, grosor 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<li>sistema de orificios \u03c616 mm, malla de orificios diagonal, grosor 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<li>sistema de orificios \u03c628 mm, rejilla de orificios diagonal, grosor 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<\/ul>\n<p>El bloque de sujeci\u00f3n de la serie EXPERT se utiliza con las mesas de soldadura de la serie EXPERT.<\/p>\n<p>El bloque de sujeci\u00f3n de la serie PRO se puede utilizar con las mesas de soldadura de la serie PRO, XWT con tablero de la serie PRO, as\u00ed como con las mesas de soldadura modulares.<\/p>\n<p>El bloque de sujeci\u00f3n de la serie PLUS se puede utilizar con las mesas de soldadura de las series PLUS, ECO, BASIC y XWT con tablero de la serie PLUS.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\" translation-block\">El bloque de sujeci\u00f3n <span class=\"seriaText\"><\/span> 1200x200x200 en rejilla <span class=\"systemText\"><\/span> es una herramienta dise\u00f1ada para unir dos mesas de soldadura, conservando su funcionalidad, ya que la superficie de la mesa tiene una rejilla y orificios de montaje. Se puede utilizar para crear una estaci\u00f3n de soldadura con una forma no est\u00e1ndar, uniendo cualquier n\u00famero de mesas para crear una estaci\u00f3n de trabajo adaptada al proyecto en cuesti\u00f3n.<\/p>","protected":false},"featured_media":26736,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[445,438],"product_tag":[],"class_list":{"0":"post-23015","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zwiekszenie-powierzchni","7":"product_cat-magazyn","8":"product_shipping_class-narzedzia","9":"pa_dla-stolu-pro","10":"pa_grubosc-narzedzia-8mm-11mm-15mm-25mm","11":"pa_rozmiar-1200x200x200mm","12":"pa_seria-pro","13":"pa_siatka-diagonalna","14":"pa_srednica-otworow-28-lub-16","15":"pa_system-fi28","16":"pa_typ-narzedzia-kostki-i-przedluzenia","17":"pa_wymiar-narzedzia-1200x200x200mm","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable","26":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product\/23015","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/comments?post=23015"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/media\/26736"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/media?parent=23015"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product_brand?post=23015"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product_cat?post=23015"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product_tag?post=23015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}