﻿{"id":13370,"date":"2022-12-14T13:30:00","date_gmt":"2022-12-14T11:30:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=krazek-%cf%86100"},"modified":"2026-07-12T17:05:13","modified_gmt":"2026-07-12T15:05:13","slug":"disco-100","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_uy\/p\/herramientas\/plano\/disco-100\/","title":{"rendered":"Trinquete exc\u00e9ntrico \u03c6100"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Disco de soldadura \u03c6100 \u2013 posicionamiento preciso de piezas planas<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>El disco de soldadura \u03c6100<\/strong> es una herramienta auxiliar pr\u00e1ctica destinada al <strong>posicionamiento y apoyo de piezas planas soldadas<\/strong> sobre la superficie de la mesa de soldadura.<br><br>Resulta especialmente \u00fatil cuando el uso de topes cl\u00e1sicos es dif\u00edcil por falta de espacio o por la necesidad de situar la pieza muy cerca del borde.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/1\/8\/318.jpg\" alt=\"Disco \u03c6100, sistema - \u03a628, serie - PRO\" class=\"wp-image-13372 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/1\/8\/318.jpg 800w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/1\/8\/318-600x600.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/1\/8\/318-300x300.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/1\/8\/318-64x64.jpg 64w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construcci\u00f3n y funcionalidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">El disco cuenta con un <strong>orificio de montaje descentrado<\/strong>, por lo que, una vez colocado en el perno, se puede <strong>girar y cambiar el punto de apoyo o de tope de la pieza<\/strong> sin necesidad de mover la herramienta.<br><br>Esta soluci\u00f3n permite ajustar con precisi\u00f3n su posici\u00f3n seg\u00fan las necesidades actuales y utilizar el disco donde los topes tradicionales no tienen suficiente espacio.<\/p>\n\n\n\n<p>La forma compacta del disco facilita el trabajo con piezas planas y con elementos que requieren un posicionamiento r\u00e1pido y repetible.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sistema y compatibilidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">El disco est\u00e1 disponible en dos variantes de sistema: <strong>\u03c616 mm<\/strong> y <strong>\u03c628 mm<\/strong>, lo que permite adaptarlo a distintos tipos de mesas de soldadura y otras herramientas.<\/p>\n\n\n\n<p class=\" translation-block\">Seg\u00fan la serie de herramienta elegida, es compatible con las mesas:<br>\u2013 <strong>EXPERT<\/strong> \u2013 para mesas de la serie <strong>EXPERT<\/strong> (tablero de 25 mm) y <strong>XWT<\/strong> con tablero tipo EXPERT,<br>\u2013 <strong>PRO<\/strong> \u2013 para mesas de las series <strong>PRO<\/strong>, <strong>XWT<\/strong> y <strong>MWT<\/strong> con tablero de 15 mm de grosor,<br>\u2013 <strong>PLUS<\/strong> \u2013 para mesas de las series <strong>PLUS<\/strong>, <strong>ECO<\/strong>, <strong>BASIC<\/strong>, <strong>DIY<\/strong> y <strong>XWT<\/strong> con tablero de 12 mm y 8 mm de grosor.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Material y fabricaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">El disco est\u00e1 fabricado en <strong>acero de alta calidad<\/strong>, lo que garantiza durabilidad y un funcionamiento fiable en el trabajo diario.<br><br>Gracias al control de calidad realizado, cada disco cumple altos est\u00e1ndares de fabricaci\u00f3n y garantiza una larga vida \u00fatil.<\/p>\n\n\n\n<p class=\" translation-block\">El producto se <strong>fabrica \u00edntegramente en Polonia<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>El disco \u03c6100 es una herramienta del sistema destinada al posicionamiento de piezas planas soldadas en la mesa de soldadura.<\/p>","protected":false},"featured_media":13371,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[103,69],"product_tag":[],"class_list":{"0":"post-13370","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-plaskie","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-expert","11":"pa_seria-plus","12":"pa_seria-pro","13":"pa_srednica-otworow-28-lub-16","14":"pa_system-fi16","15":"pa_system-fi28","16":"pa_typ-narzedzia-plaskie","17":"pa_wymiar-narzedzia-233","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable","26":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product\/13370","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/comments?post=13370"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/media\/13371"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/media?parent=13370"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product_brand?post=13370"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product_cat?post=13370"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_uy\/wp-json\/wp\/v2\/product_tag?post=13370"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}