﻿{"id":37734,"date":"2026-06-17T12:51:21","date_gmt":"2026-06-17T10:51:21","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=37734"},"modified":"2026-06-22T08:00:34","modified_gmt":"2026-06-22T06:00:34","slug":"outlet-stol-spawalniczy-pro-2000x1000-mm-system-%cf%8628-siatka-100x100mm-w81","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_pr\/p\/outlet\/outlet-stol-spawalniczy-pro-2000x1000-mm-system-%cf%8628-siatka-100x100mm-w81\/","title":{"rendered":"[OUTLET] Mesa de soldadura PRO 2000\u00d71000 mm \u2013 sistema \u03c628, malla 100x100 mm"},"content":{"rendered":"<p>Las mesas de soldadura son la herramienta ideal all\u00e1 donde se requiera precisi\u00f3n y repetibilidad. La superficie de 15\u202fmm de espesor, con un nerviado denso, garantiza planitud y estabilidad incluso con estructuras m\u00e1s pesadas. El sistema de orificios fresados y biselados \u03c628 en la malla 100\u00d7100\u202fmm facilita el montaje de herramientas, acelerando y simplificando el trabajo.<\/p>\n\n\n\n<p><strong>Caracter\u00edsticas principales de la mesa:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La superficie de 15\u202fmm de grosor, con un nerviado denso, garantiza una superficie de trabajo perfectamente plana.<\/li>\n\n\n\n<li>Dimensiones: 2000\u00d71000 mm, 2 nervaduras longitudinales y 4 transversales que garantizan estabilidad durante el uso y resistencia a la deformaci\u00f3n.<\/li>\n\n\n\n<li>Malla 100\u00d7100 mm, sistema \u03c628<\/li>\n<\/ul>\n\n\n\n<p>La superficie de la mesa est\u00e1 adem\u00e1s equipada con una escala grabada en una rejilla de 100\u00d7100 mm, lo que facilita el posicionamiento preciso de las estructuras y el montaje de herramientas, garantizando una alta precisi\u00f3n en cada operaci\u00f3n.<\/p>\n\n\n\n<p><strong>Variantes de patas:&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Con pies fijos \u2013 proporcionan estabilidad y gran capacidad de carga.<\/li>\n\n\n\n<li>Con ruedas \u2013 ideal para trabajos donde se requiere movilidad de la mesa.<\/li>\n<\/ul>\n\n\n\n<p>Al comprar este producto, puedes elegir una versi\u00f3n con patas fijas o con ruedas.<\/p>\n\n\n\n<p>Las patas de la mesa, fabricadas con perfil de 100x100 mm, tienen una capacidad de carga de 1000 kg por pata, lo que proporciona una capacidad de carga total de 4000 kg con 4 patas. Gracias a ello, la mesa permanece estable incluso bajo cargas elevadas.<\/p>\n\n\n\n<p class=\" translation-block\">Al comprar una mesa outlet, declaras que <strong>te has informado sobre su estado real<\/strong> y que la <strong>aceptas sin derecho a presentar reclamaciones<\/strong>. De acuerdo con el art\u00edculo 557 \u00a7 1 del C\u00f3digo Civil polaco, el vendedor queda exento de responsabilidad por garant\u00eda si el comprador conoc\u00eda el defecto en el momento de celebrar el contrato.<\/p>\n\n\n\n<p>\u00bfQuiere saber m\u00e1s sobre las mesas de soldadura tradicionales de GPPH? Consulte la informaci\u00f3n en la p\u00e1gina dedicada <a href=\"https:\/\/gpph-group.com\/es_pr\/productos\/mesa-de-soldadura-tradicional\/\">mesas de soldadura tradicionales.<\/a><a href=\"https:\/\/gpph-group.com\/es_pr\/\" target=\"_blank\" rel=\"noreferrer noopener\">&nbsp;<\/a><\/p>\n\n\n\n<p id=\"defekty\"><strong>ATENCI\u00d3N: La mesa presenta defectos:&nbsp;<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Wystaj\u0105ca \u015bcianka boczna<\/li>\n\n\n\n<li>Revestido por la parte inferior<\/li>\n<\/ul>\n\n\n\n<p>Las fotos de los defectos se muestran a continuaci\u00f3n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-1024x683.jpg\" alt=\"[OUTLET] Mesa de soldadura PRO 2000x1000 mm \u2013 sistema \u03c628, malla 100x100 mm\" class=\"wp-image-37743\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322558-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-scaled.jpg\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-1024x683.jpg\" alt=\"[OUTLET] Mesa de soldadura PRO 2000x1000 mm \u2013 sistema \u03c628, malla 100x100 mm\" class=\"wp-image-37740\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322565-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Le invitamos a comprobarlo <a href=\"https:\/\/gpph-group.com\/p\/stoly-spawalnicze\/pro\/stol-spawalniczy-pro-2000-x-1000-mm\/\" target=\"_blank\" rel=\"noopener\">producto de pleno valor<\/a>. La oferta actual se refiere a una unidad outlet,<strong> disponible en cantidades limitadas y a un precio excepcionalmente atractivo.<\/strong> <strong>\u00a1ATENCI\u00d3N! La mesa presenta defectos:<\/strong><\/p>\n<ul>\n<li>\n<p id=\"defekty\">Wystaj\u0105ca \u015bcianka boczna<\/p>\n<\/li>\n<li>Revestido por la parte inferior<\/li>\n<\/ul>","protected":false},"featured_media":37738,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168],"product_tag":[],"class_list":{"0":"post-37734","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outlet","7":"product_shipping_class-stol-spawalniczy-2000","8":"pa_nogi-na-kolach","9":"pa_nogi-na-stopach","10":"pa_nosnosc-1000kg-noga","11":"pa_seria-pro","12":"pa_siatka-100x100mm","13":"pa_srednica-otworow-351","14":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","15":"pa_wymiar-stolu-2000x1000","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-variable","24":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product\/37734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/comments?post=37734"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/media\/37738"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/media?parent=37734"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product_brand?post=37734"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product_cat?post=37734"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product_tag?post=37734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}