﻿{"id":14943,"date":"2023-01-25T15:08:00","date_gmt":"2023-01-25T13:08:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=modulowy-stol-spawalniczy-pojedynczy-rozkladany-1770x1000-mm"},"modified":"2026-06-10T12:20:55","modified_gmt":"2026-06-10T10:20:55","slug":"mesa-de-soldadura-modular-plegable-individual-1770x1000-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_pr\/p\/mesas-de-soldadura\/mesa-de-soldadura-modular-plegable-individual-1770x1000-mm\/","title":{"rendered":"Mesa de soldadura modular individual desplegable 1770\u00d71000 mm"},"content":{"rendered":"<p>Esta subasta se refiere a una mesa de soldadura modular desmontable con tableros fabricados en material S355J2+N  con unas dimensiones de 1770\u00d71000.<\/p>\n<p>Las mesas modulares individuales se pueden desplegar gracias a las placas deslizantes y al uso de patas adicionales. Est\u00e1n disponibles en tres versiones dimensionales: 1770\u00d71000, 2170\u00d71200, 2670\u00d71600.<\/p>\n<p class=\" translation-block\">El tablero de las mesas modulares est\u00e1 compuesto por placas fresadas y desplazables de 15 mm de grosor, y gracias a la regulaci\u00f3n de su superficie se consigue una planitud perfecta. Est\u00e1n fabricadas con un sistema de orificios de 28 mm en una rejilla de 100\u00d7100 mm.\nCuentan con orificios fresados y biselados que facilitan el montaje de las herramientas. Las mesas modulares son compatibles con las herramientas de la serie PRO. Adem\u00e1s, el dise\u00f1o de nuestras mesas modulares permite aumentar el n\u00famero de puntos de fijaci\u00f3n de las herramientas en los huecos entre las placas de la superficie, lo que mejora la ergonom\u00eda del trabajo.<\/p>\n<p class=\" translation-block\">Las mesas modulares tienen ruedas con pie en las patas base, con una <strong>capacidad de carga de 250 kg por pata<\/strong>. Las versiones extensibles de las mesas modulares tienen <strong>soportes ajustables <\/strong>en las patas adicionales. La altura de las mesas puede ajustarse entre 850 mm y 1150 mm, P=50 mm.<\/p>\n<p class=\" translation-block\">Para obtener una mayor superficie de trabajo, las <strong>mesas pueden combinarse entre s\u00ed<\/strong>. Como opci\u00f3n, tambi\u00e9n se pueden adquirir placas laterales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ta aukcja dotyczy pojedynczego rozk\u0142adanego modu\u0142owego sto\u0142u spawalniczego z p\u0142ytami blatu wykonanymi z materia\u0142u: S355J2+N\u00a0 o wymiarze 1770&#215;1000. Pojedyncze rozk\u0142adane sto\u0142y modu\u0142owe mo\u017cna rozk\u0142ada\u0107 dzi\u0119ki przesuwnym p\u0142ytom oraz zastosowaniem dodatkowych n\u00f3g. Wyst\u0119puj\u0105 w trzech wersjach wymiarowych: 1770&#215;1000, 2170&#215;1200, 2670&#215;1600. Blat sto\u0142\u00f3w modu\u0142owych sk\u0142ada si\u0119 z frezowanych, przesuwnych p\u0142yt o grubo\u015bci 15 mm, a dzi\u0119ki regulacji [&hellip;]<\/p>","protected":false},"featured_media":14944,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[68,86,81],"product_tag":[],"class_list":{"0":"post-14943","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stoly-spawalnicze","7":"product_cat-modulowe","8":"product_cat-mwt","9":"product_shipping_class-stol-spawalniczy-2000","10":"pa_grubosc-blatu-15mm","11":"pa_nosnosc-250kg-noga","12":"pa_otwory-frezowane-i-fazowane","13":"pa_rozmiar-1770x1000mm","14":"pa_seria-mwt","15":"pa_siatka-100x100mm","16":"pa_system-fi28","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product\/14943","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/comments?post=14943"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/media\/14944"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/media?parent=14943"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product_brand?post=14943"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product_cat?post=14943"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pr\/wp-json\/wp\/v2\/product_tag?post=14943"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}