﻿{"id":36031,"date":"2026-06-01T00:00:00","date_gmt":"2026-05-31T22:00:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=36031"},"modified":"2026-07-06T10:27:05","modified_gmt":"2026-07-06T08:27:05","slug":"mesa-de-soldadura-smart-12-2400x1200-kit-de-herramientas-supreme","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_pe\/p\/conjuntos-promocionales\/mesa-de-soldadura-smart-12-2400x1200-kit-de-herramientas-supreme\/","title":{"rendered":"Mesa de soldadura SMART 12mm - 2400x1200mm + Kit de herramientas SUPREME"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Puesto de trabajo totalmente equipado para soldadura, montaje y fabricaci\u00f3n de estructuras de acero<\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>La mesa de soldadura SMART 12 mm 2400x1200 junto con el kit de herramientas SMART SUPREME<\/strong> constituye un puesto de trabajo ampliado destinado al posicionamiento, la fijaci\u00f3n y el ajuste de elementos durante trabajos de soldadura, montaje y metalister\u00eda. El conjunto ha sido preparado para talleres que esperan una amplia selecci\u00f3n de herramientas y una gran libertad a la hora de organizar el puesto de trabajo.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-1024x1024.png\" alt=\"St\u00f3\u0142 spawalniczy SMART 15 fi16 siatka 100x100 na ko\u0142ach z zestawem narz\u0119dzi SUPREME\" class=\"wp-image-36302 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-1024x1024.png 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-1536x1536.png 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100-64x64.png 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SUPREME_fi16-wozek-M-16_100x100_K_SMART_15_200x100.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>La combinaci\u00f3n de la mesa de soldadura SMART y el kit de herramientas SUPREME permite comenzar a trabajar de inmediato con un equipamiento completo, sin necesidad de seleccionar herramientas por separado. Esta soluci\u00f3n garantiza una organizaci\u00f3n c\u00f3moda del puesto de trabajo, una mayor flexibilidad al trabajar con estructuras de acero y la posibilidad de realizar proyectos de soldadura y montaje m\u00e1s complejos.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 incluye el conjunto?<\/h3>\n\n\n\n<p>El conjunto incluye:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mesa de soldadura SMART 12 mm 2400x1200 mm<\/li>\n\n\n\n<li>15x <span>Abrazadera de fijaci\u00f3n A<\/span><\/li>\n\n\n\n<li>6x <span>Disco SMART<\/span><\/li>\n\n\n\n<li>6x <span>Trinquete 150 SMART<\/span><\/li>\n\n\n\n<li>6x <span>Trinquete 225 SMART<\/span><\/li>\n\n\n\n<li>4x <span>Trinquete 260 SMART<\/span><\/li>\n\n\n\n<li>4x <span>Escuadra plana SMART 275x150<\/span><\/li>\n\n\n\n<li>4x <span>Escuadra plana SMART 320x150<\/span><\/li>\n\n\n\n<li>2x <span>Escuadra plana SMART 350x250<\/span><\/li>\n\n\n\n<li>2x <span>Escuadra angular SMART<\/span><\/li>\n\n\n\n<li>6x <span>Escuadra espacial<\/span> SMART 75&#215;185<\/li>\n\n\n\n<li>4x <span>Escuadra espacial<\/span> SMART 125&#215;185<\/li>\n\n\n\n<li>4x <span>Escuadra espacial<\/span> SMART 175&#215;185<\/li>\n\n\n\n<li>4x <span>Escuadra espacial<\/span> SMART 200&#215;200<\/li>\n\n\n\n<li>2x <span>Escuadra espacial<\/span> SMART 300&#215;190 <span>Derecho<\/span><\/li>\n\n\n\n<li>2x <span>Escuadra espacial<\/span> SMART 300&#215;190 <span>Izquierdo<\/span><\/li>\n\n\n\n<li>1x <span>Escuadra espacial<\/span> SMART 450&#215;250 <span>Derecho<\/span><\/li>\n\n\n\n<li>1x <span>Escuadra espacial<\/span> SMART 450&#215;250 <span>Izquierdo<\/span><\/li>\n\n\n\n<li>1x <span>Transportador 3D SMART<\/span> <span>Derecho<\/span><\/li>\n\n\n\n<li>1x <span>Medidor de \u00e1ngulo espacial<\/span> SMART <span>Izquierdo<\/span><\/li>\n\n\n\n<li>2x <span>Extensi\u00f3n SMART 1000x200<\/span><\/li>\n\n\n\n<li>30x <span>Perno de montaje r\u00e1pido SMART<\/span><\/li>\n\n\n\n<li>20x <span>Perno de posicionamiento<\/span><\/li>\n\n\n\n<li>2x <span>Estante m\u00f3vil para pernos M<\/span><\/li>\n\n\n\n<li>1x <span>Estante m\u00f3vil para pernos\u00a0S<\/span><\/li>\n\n\n\n<li>1x <span>Estante m\u00f3vil para torniquetes M<\/span><\/li>\n\n\n\n<li>1x <span>Carro de herramientas M\/L<\/span><\/li>\n<\/ul>\n\n\n\n<p class=\" translation-block\">En total, recibe un puesto de trabajo completo equipado con <strong>132 elementos<\/strong>, que permite realizar una amplia gama de trabajos de soldadura, montaje y fabricaci\u00f3n de estructuras.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Mesa de soldadura SMART 12 mm \u2013 puesto de trabajo funcional para soldadura y montaje<\/h3>\n\n\n\n<p class=\" translation-block\">La serie <strong>GPPH SMART<\/strong> fue creada para usuarios que buscan una mesa de soldadura s\u00f3lida y funcional a un precio atractivo. Es una soluci\u00f3n destinada a talleres, cerrajeros, empresas de producci\u00f3n y fabricantes de estructuras de acero que necesitan un puesto de trabajo fiable para las tareas diarias de soldadura y montaje.<\/p>\n\n\n\n<p class=\" translation-block\">La mesa est\u00e1 equipada con una superficie de trabajo de <strong>12 mm<\/strong> de espesor, disponible en los sistemas de orificios <strong>fi16<\/strong> y <strong>fi28<\/strong>, con una cuadr\u00edcula de orificios de <strong>100x100 mm<\/strong> o con disposici\u00f3n <strong>diagonal<\/strong>. Gracias a ello, la configuraci\u00f3n puede adaptarse f\u00e1cilmente al tipo de trabajo realizado y a las herramientas utilizadas.<\/p>\n\n\n\n<p class=\" translation-block\">En la superficie de trabajo se han aplicado <strong>orificios de montaje fresados y biselados<\/strong>, que facilitan el montaje y desmontaje de herramientas y mejoran la comodidad del trabajo diario. La superficie est\u00e1 equipada con una <strong>escala grabada<\/strong>, que facilita el posicionamiento de los elementos, el control de dimensiones y la realizaci\u00f3n de ajustes repetitivos durante los trabajos de soldadura y montaje de estructuras.<\/p>\n\n\n\n<p class=\" translation-block\">Uno de los par\u00e1metros m\u00e1s importantes de la mesa es la <strong>tolerancia de planitud \u2264 0,3 mm en toda la superficie de trabajo<\/strong>, lo que permite mantener una alta precisi\u00f3n durante el posicionamiento y la uni\u00f3n de elementos. La estructura de la mesa tambi\u00e9n garantiza una gran rigidez y una <strong>capacidad de carga de hasta 2000 kg<\/strong>, por lo que puede trabajar sin problemas con piezas m\u00e1s pesadas y estructuras de acero de gran tama\u00f1o.<\/p>\n\n\n\n<p>La mesa de soldadura SMART 12 mm constituye una excelente base para crear un puesto de trabajo funcional y es compatible con las herramientas del sistema SMART, permitiendo posicionar, fijar y ajustar elementos de forma c\u00f3moda durante las tareas diarias en el taller.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Kit de herramientas SMART SUPREME<\/h3>\n\n\n\n<p class=\" translation-block\"><strong>El kit de herramientas SMART SUPREME<\/strong> es la configuraci\u00f3n m\u00e1s completa dentro de la familia de conjuntos SMART. Ha sido desarrollado para talleres que necesitan una amplia selecci\u00f3n de herramientas y una gran flexibilidad en proyectos que requieren numerosos puntos de fijaci\u00f3n, posicionamiento preciso y control de la geometr\u00eda de las estructuras.<\/p>\n\n\n\n<p>El conjunto incluye herramientas que permiten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>posicionar elementos en distintos \u00e1ngulos,<\/li>\n\n\n\n<li>la construcci\u00f3n de estructuras tridimensionales,<\/li>\n\n\n\n<li>la fijaci\u00f3n r\u00e1pida de piezas,<\/li>\n\n\n\n<li>la ampliaci\u00f3n de la superficie de trabajo de la mesa,<\/li>\n\n\n\n<li>la realizaci\u00f3n de proyectos de construcci\u00f3n m\u00e1s complejos,<\/li>\n\n\n\n<li>la creaci\u00f3n de configuraciones de producci\u00f3n repetibles,<\/li>\n\n\n\n<li>una organizaci\u00f3n eficiente del puesto de trabajo<\/li>\n\n\n\n<li>el almacenamiento de herramientas en estanter\u00edas dedicadas y en un carro de taller.<\/li>\n<\/ul>\n\n\n\n<p>Gracias a la presencia de escuadras angulares tridimensionales, extensiones, un amplio conjunto de escuadras de soldadura, escuadras, trinquetes y pernos de montaje, el usuario dispone de un equipamiento vers\u00e1til que permite realizar una amplia gama de trabajos en la mesa de soldadura. De este modo se crea un sistema de trabajo integral que permite aprovechar al m\u00e1ximo el potencial de la mesa de soldadura SMART.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Sistema y compatibilidad<\/h3>\n\n\n\n<p class=\" translation-block\">La mesa y las herramientas SMART est\u00e1n disponibles en los sistemas de orificios <strong>fi16<\/strong> y <strong>fi28<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">La serie <strong>SMART12<\/strong> est\u00e1 dise\u00f1ada para mesas con una superficie de trabajo de 12 mm de espesor y tambi\u00e9n es compatible con las herramientas y accesorios de la serie <strong>PLUS<\/strong>.<\/p>\n\n\n\n<p>Gracias a ello, el usuario puede ampliar en el futuro su puesto de trabajo con herramientas adicionales del sistema y equipamiento complementario para el taller.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Caracter\u00edsticas principales del conjunto<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mesa de soldadura SMART 12 mm 2400x1200 mm<\/li>\n\n\n\n<li>capacidad de carga de la mesa de hasta 2000 kg,<\/li>\n\n\n\n<li>tolerancia de planitud de la superficie de trabajo \u2264 0,3 mm,<\/li>\n\n\n\n<li>orificios de montaje fresados y biselados,<\/li>\n\n\n\n<li>escala grabada en la superficie de trabajo,<\/li>\n\n\n\n<li>conjunto de 132 herramientas y accesorios,<\/li>\n\n\n\n<li>escuadras angulares tridimensionales, extensiones y carro de herramientas incluidos,<\/li>\n\n\n\n<li>compatibilidad con sistemas fi16 y fi28<\/li>\n\n\n\n<li>amplias posibilidades de posicionamiento y fijaci\u00f3n de componentes,<\/li>\n\n\n\n<li class=\" translation-block\">producto fabricado <strong>en Polonia<\/strong>.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfNecesita mayores posibilidades?<\/h3>\n\n\n\n<p class=\" translation-block\">La serie <strong>SMART<\/strong> fue creada para usuarios que buscan soluciones funcionales y econ\u00f3micas para el trabajo diario en el taller. A medida que el taller se desarrolla, el puesto de trabajo puede ampliarse f\u00e1cilmente con equipamiento adicional y nuevas herramientas del sistema.<\/p>\n\n\n\n<p>Descubra tambi\u00e9n nuestros <strong><a href=\"https:\/\/gpph-group.com\/es_pe\/c\/herramientas\/\" data-type=\"link\" data-id=\"https:\/\/gpph-group.com\/pl\/c\/narzedzia\/\">herramientas de soldadura<\/a> de las series PLUS, PRO y EXPERT<\/strong>, dedicadas a las mesas de soldadura tradicionales de GPPH. El amplio sistema de accesorios permite adaptar a\u00fan mejor el puesto de trabajo a las necesidades individuales y a proyectos m\u00e1s exigentes relacionados con la soldadura, el montaje y la fabricaci\u00f3n de estructuras de acero.<\/p>","protected":false},"excerpt":{"rendered":"<p>La mesa de soldadura SMART 12 mm 2400x1200 junto con el kit de herramientas SUPREME constituye un puesto de trabajo completo destinado a tareas de soldadura, montaje y trabajos metal\u00fargicos. El conjunto incluye una mesa de soldadura y 132 herramientas y accesorios para posicionar, fijar y ajustar elementos durante la realizaci\u00f3n de exigentes proyectos estructurales.<\/p>","protected":false},"featured_media":36302,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-36031","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2400","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_nogi-na-kolach","12":"pa_nogi-na-stopach","13":"pa_nosnosc-max-2000kg","14":"pa_otwory-frezowane-i-fazowane","15":"pa_rozmiar-2400x1200mm","16":"pa_seria-smart12","17":"pa_siatka-100x100mm","18":"pa_siatka-diagonalna","19":"pa_system-fi16","20":"pa_system-fi28","21":"pa_tolerancja-plaskosci-03-mm","22":"pa_tolerancja-wykonania-otworow-005-mm","23":"pa_wozek-wozek-narzedziowy-l","24":"pa_wozek-wozek-narzedziowy-m","25":"pa_wzmocnienie-zebrami-tak","27":"first","28":"instock","29":"sale","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable","34":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product\/36031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/comments?post=36031"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media\/36302"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media?parent=36031"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_brand?post=36031"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_cat?post=36031"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_tag?post=36031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}