﻿{"id":36025,"date":"2026-06-01T00:00:00","date_gmt":"2026-05-31T22:00:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=36025"},"modified":"2026-07-06T10:27:13","modified_gmt":"2026-07-06T08:27:13","slug":"mesa-de-soldadura-smart-12-2400x1200-kit-de-herramientas-select","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_pe\/p\/conjuntos-promocionales\/mesa-de-soldadura-smart-12-2400x1200-kit-de-herramientas-select\/","title":{"rendered":"Mesa de soldadura SMART 12mm \u2013 2400x1200mm + Kit de herramientas SELECT"},"content":{"rendered":"<h2 class=\"wp-block-heading\">Puesto de trabajo completamente equipado para soldadura y montaje<\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>La mesa de soldadura SMART 12 mm 2400x1200 junto con el kit de herramientas SELECT<\/strong> constituye un puesto de trabajo listo para usar destinado al posicionamiento, la fijaci\u00f3n y el ajuste de elementos durante tareas de soldadura, montaje y trabajos metal\u00fargicos. El conjunto ha sido dise\u00f1ado para talleres que necesitan mayores posibilidades de trabajo y un equipamiento m\u00e1s amplio que el ofrecido por las configuraciones b\u00e1sicas de herramientas.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-1024x1024.png\" alt=\"St\u00f3\u0142 spawalniczy SMART 15 fi28 siatka 100x100 na ko\u0142ach z zestawem narz\u0119dzi SELECT\" class=\"wp-image-36307 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-1024x1024.png 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-1536x1536.png 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100-64x64.png 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/05\/SMART15_SELECT_fi16-16_100x100_K_SMART_15_200x100.png 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p>La combinaci\u00f3n de la mesa de soldadura SMART y el kit de herramientas SELECT permite comenzar a trabajar de inmediato con un equipamiento completo, sin necesidad de seleccionar las herramientas por separado. Esta soluci\u00f3n proporciona una organizaci\u00f3n c\u00f3moda del puesto de trabajo y una mayor flexibilidad en la realizaci\u00f3n de estructuras de acero, trabajos de montaje y proyectos de taller.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 incluye el conjunto?<\/h3>\n\n\n\n<p>El conjunto incluye:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mesa de soldadura SMART 12 mm 2400x1200 mm<\/li>\n\n\n\n<li>8x <span>Abrazadera de fijaci\u00f3n A<\/span><\/li>\n\n\n\n<li>4x <span>Disco SMART<\/span><\/li>\n\n\n\n<li>4x <span>Tope SMART 150<\/span><\/li>\n\n\n\n<li>2x <span>Tope SMART 225<\/span><\/li>\n\n\n\n<li>4x <span>Escuadra plana SMART 275x150<\/span><\/li>\n\n\n\n<li>2x <span>Escuadra plana SMART 320x150<\/span><\/li>\n\n\n\n<li>2x <span>Escuadra angular SMART<\/span><\/li>\n\n\n\n<li>2x <span>Escuadra espacial<\/span> SMART 75&#215;185<\/li>\n\n\n\n<li>2x <span>Escuadra espacial<\/span> SMART 175&#215;185<\/li>\n\n\n\n<li>15x <span>Perno de montaje r\u00e1pido SMART<\/span><\/li>\n\n\n\n<li>5x <span>Perno de posicionamiento<\/span><\/li>\n\n\n\n<li>1x <span>Estante m\u00f3vil para pernos M<\/span><\/li>\n<\/ul>\n\n\n\n<p class=\" translation-block\">En total, recibe un puesto de trabajo completo equipado con <strong>51 elementos<\/strong>, que permite realizar una amplia gama de trabajos de soldadura y montaje.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Mesa de soldadura SMART 12 mm \u2013 puesto de trabajo funcional para soldadura y montaje<\/h3>\n\n\n\n<p class=\" translation-block\">La serie <strong>GPPH SMART<\/strong> fue creada para usuarios que buscan una mesa de soldadura s\u00f3lida y funcional a un precio atractivo. Es una soluci\u00f3n destinada a talleres, cerrajeros, empresas de producci\u00f3n y fabricantes de estructuras de acero que necesitan un puesto de trabajo fiable para las tareas diarias de soldadura y montaje.<\/p>\n\n\n\n<p class=\" translation-block\">La mesa est\u00e1 equipada con una superficie de trabajo de <strong>12 mm<\/strong> de espesor, disponible en los sistemas de orificios <strong>fi16<\/strong> y <strong>fi28<\/strong>, con una cuadr\u00edcula de orificios de <strong>100x100 mm<\/strong> o con disposici\u00f3n <strong>diagonal<\/strong>. Gracias a ello, la configuraci\u00f3n puede adaptarse f\u00e1cilmente al tipo de trabajo realizado y a las herramientas utilizadas.<\/p>\n\n\n\n<p class=\" translation-block\">En la superficie de trabajo se han aplicado <strong>orificios de montaje fresados y biselados<\/strong>, que facilitan el montaje y desmontaje de herramientas y mejoran la comodidad del trabajo diario. La superficie est\u00e1 equipada con una <strong>escala grabada<\/strong>, que facilita el posicionamiento de los elementos, el control de dimensiones y la realizaci\u00f3n de ajustes repetitivos durante los trabajos de soldadura y montaje de estructuras.<\/p>\n\n\n\n<p class=\" translation-block\">Uno de los par\u00e1metros m\u00e1s importantes de la mesa es la <strong>tolerancia de planitud \u2264 0,3 mm en toda la superficie de trabajo<\/strong>, lo que permite mantener una alta precisi\u00f3n durante el posicionamiento y la uni\u00f3n de elementos. La estructura de la mesa tambi\u00e9n garantiza una gran rigidez y una <strong>capacidad de carga de hasta 2000 kg<\/strong>, por lo que puede trabajar sin problemas con piezas m\u00e1s pesadas y estructuras de acero de gran tama\u00f1o.<\/p>\n\n\n\n<p>La mesa de soldadura SMART 12 mm constituye una excelente base para crear un puesto de trabajo funcional y es compatible con las herramientas del sistema SMART, permitiendo posicionar, fijar y ajustar elementos de forma c\u00f3moda durante las tareas diarias en el taller.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Kit de herramientas SMART SELECT<\/h3>\n\n\n\n<p class=\" translation-block\"><strong>El kit de herramientas SMART SELECT<\/strong> es una configuraci\u00f3n ampliada de herramientas dise\u00f1ada para el trabajo regular en una mesa de soldadura. En comparaci\u00f3n con los conjuntos b\u00e1sicos, ofrece una mayor cantidad de herramientas, m\u00e1s puntos de fijaci\u00f3n y mayores posibilidades de posicionamiento de los elementos.<\/p>\n\n\n\n<p>El conjunto incluye herramientas que permiten:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>posicionamiento de elementos estructurales<\/li>\n\n\n\n<li>la colocaci\u00f3n de elementos en \u00e1ngulo recto,<\/li>\n\n\n\n<li>control de \u00e1ngulos durante el montaje<\/li>\n\n\n\n<li>fijaci\u00f3n r\u00e1pida de elementos,<\/li>\n\n\n\n<li>creaci\u00f3n de repetibles configuraciones de trabajo<\/li>\n\n\n\n<li>organizaci\u00f3n del puesto de trabajo<\/li>\n\n\n\n<li>la realizaci\u00f3n de proyectos de taller m\u00e1s avanzados.<\/li>\n<\/ul>\n\n\n\n<p>Todas las herramientas han sido seleccionadas para complementarse entre s\u00ed y garantizar un trabajo c\u00f3modo, sin necesidad de configurar el equipamiento por cuenta propia, desde el primer d\u00eda de uso.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Sistema y compatibilidad<\/h3>\n\n\n\n<p class=\" translation-block\">La mesa y las herramientas SMART est\u00e1n disponibles en los sistemas de orificios <strong>fi16<\/strong> y <strong>fi28<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">La serie <strong>SMART12<\/strong> est\u00e1 dise\u00f1ada para mesas con una superficie de trabajo de 12 mm de espesor y tambi\u00e9n es compatible con las herramientas y accesorios de la serie <strong>PLUS<\/strong>.<\/p>\n\n\n\n<p>Gracias a ello, el usuario puede ampliar en el futuro su puesto de trabajo con herramientas adicionales del sistema y equipamiento complementario para el taller.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Caracter\u00edsticas principales del conjunto<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mesa de soldadura SMART 12 mm 2400x1200 mm<\/li>\n\n\n\n<li>capacidad de carga de la mesa de hasta 2000 kg,<\/li>\n\n\n\n<li>tolerancia de planitud de la superficie de trabajo \u2264 0,3 mm,<\/li>\n\n\n\n<li>orificios de montaje fresados y biselados,<\/li>\n\n\n\n<li>escala grabada en la superficie de trabajo,<\/li>\n\n\n\n<li>conjunto de 51 herramientas y accesorios,<\/li>\n\n\n\n<li>compatibilidad con sistemas fi16 y fi28<\/li>\n\n\n\n<li>la posibilidad de posicionar y fijar elementos de forma r\u00e1pida,<\/li>\n\n\n\n<li class=\" translation-block\">producto fabricado <strong>en Polonia<\/strong>.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfNecesita mayores posibilidades?<\/h3>\n\n\n\n<p class=\" translation-block\">La serie <strong>SMART<\/strong> fue creada para usuarios que buscan soluciones funcionales y econ\u00f3micas para el trabajo diario en el taller. A medida que el taller se desarrolla, el puesto de trabajo puede ampliarse f\u00e1cilmente con equipamiento adicional y nuevas herramientas del sistema.<\/p>\n\n\n\n<p>Descubra tambi\u00e9n nuestros <strong><a href=\"https:\/\/gpph-group.com\/es_pe\/c\/herramientas\/\" data-type=\"link\" data-id=\"https:\/\/gpph-group.com\/pl\/c\/narzedzia\/\">herramientas de soldadura<\/a> de las series PLUS, PRO y EXPERT<\/strong>, dedicadas a las mesas de soldadura tradicionales de GPPH. El amplio sistema de accesorios permite adaptar a\u00fan mejor el puesto de trabajo a las necesidades individuales y a proyectos m\u00e1s exigentes relacionados con la soldadura, el montaje y la fabricaci\u00f3n de estructuras de acero.<\/p>","protected":false},"excerpt":{"rendered":"<p>La mesa de soldadura SMART 12 mm 2400x1200 junto con el kit de herramientas SMART SELECT constituye un puesto de trabajo completo destinado a las tareas diarias de soldadura, montaje y trabajos metal\u00fargicos. El conjunto incluye una mesa de soldadura y una selecci\u00f3n ampliada de herramientas para posicionar, fijar y ajustar elementos durante la fabricaci\u00f3n de estructuras de acero.<\/p>","protected":false},"featured_media":36307,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-36025","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2400","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_nogi-na-kolach","12":"pa_nogi-na-stopach","13":"pa_nosnosc-max-2000kg","14":"pa_otwory-frezowane-i-fazowane","15":"pa_rozmiar-2400x1200mm","16":"pa_seria-plus","17":"pa_siatka-100x100mm","18":"pa_siatka-diagonalna","19":"pa_system-fi16","20":"pa_system-fi28","21":"pa_tolerancja-plaskosci-03-mm","22":"pa_tolerancja-wykonania-otworow-005-mm","23":"pa_wzmocnienie-zebrami-tak","25":"first","26":"instock","27":"sale","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-variable","32":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product\/36025","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/comments?post=36025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media\/36307"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media?parent=36025"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_brand?post=36025"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_cat?post=36025"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_tag?post=36025"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}