﻿{"id":32733,"date":"2026-02-24T09:15:00","date_gmt":"2026-02-24T07:15:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=32733"},"modified":"2026-06-15T08:49:53","modified_gmt":"2026-06-15T06:49:53","slug":"escuadra-de-soldadura-plana-275x150mm-%cf%8628-pro-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_pe\/p\/deposito\/escuadra-de-soldadura-plana-275x150mm-%cf%8628-pro-m\/","title":{"rendered":"Escuadra de soldadura plana 275x150mm \u2013 \u03c628 \u2013 PRO"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Escuadra plana \u2013 posicionamiento preciso de piezas a 90\u00b0<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Escuadra plana<\/strong> es una herramienta auxiliar pr\u00e1ctica destinada al <strong>posicionamiento y sujeci\u00f3n de piezas de acero<\/strong> sobre la superficie de la mesa de soldadura utilizando un \u00e1ngulo recto.<br><br>Facilita un ajuste r\u00e1pido y repetible de los elementos, lo que acelera la preparaci\u00f3n de la estructura para soldadura o montaje.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/2\/1\/4\/214.jpg\" alt=\"Escuadra plana 350x250mm, Sistema - \u03a628, Serie - PLUS\" class=\"wp-image-13349 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/2\/1\/4\/214.jpg 800w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/2\/1\/4\/214-600x600.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/2\/1\/4\/214-300x300.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/2\/1\/4\/214-64x64.jpg 64w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construcci\u00f3n y funcionalidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La escuadra tiene forma de \u201cL\u201d y est\u00e1 fabricada con alta precisi\u00f3n, por lo que mantiene de forma segura el <strong>\u00e1ngulo de 90\u00b0<\/strong> durante el trabajo.<br><br>Las superficies de trabajo garantizan un apoyo estable de la pieza y facilitan su ajuste preciso.<\/p>\n\n\n\n<p class=\" translation-block\">En el cuerpo hay <strong>orificios de montaje redondos y alargados<\/strong> que permiten fijar r\u00e1pidamente la escuadra y colocarla en el lugar adecuado sobre la mesa.<br><br>Esta soluci\u00f3n facilita el trabajo con piezas de diferentes formas y ayuda a mantenerlas exactamente en la posici\u00f3n establecida durante la soldadura.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sistema y compatibilidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La escuadra est\u00e1 disponible en versiones adecuadas para diferentes sistemas de agujeros.<br><br>La variante <strong>EXPERT<\/strong> est\u00e1 disponible \u00fanicamente en el sistema <strong>\u03c628 mm<\/strong>, mientras que las series <strong>PRO, PLUS y ECO<\/strong> se ofrecen en los sistemas <strong>\u03c616 mm<\/strong> y <strong>\u03c628 mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Seg\u00fan la serie de herramienta elegida, es compatible con las mesas:<br>\u2013 <strong>EXPERT<\/strong> \u2013 para mesas de la serie <strong>EXPERT<\/strong> (tablero de 25 mm) y <strong>XWT<\/strong> con tablero tipo EXPERT,<br>\u2013 <strong>PRO<\/strong> \u2013 para mesas de las series <strong>PRO<\/strong>, <strong>XWT<\/strong> y <strong>MWT<\/strong> con tablero de 15 mm de grosor,<br>\u2013 <strong>PLUS<\/strong> \u2013 para mesas de las series <strong>PLUS<\/strong>, <strong>ECO<\/strong>, <strong>BASIC<\/strong>, <strong>DIY<\/strong> y <strong>XWT<\/strong> con tablero de 12 mm y 8 mm de grosor.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Material y fabricaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La escuadra est\u00e1 fabricada con <strong>acero al carbono de alta calidad<\/strong>, lo que garantiza durabilidad y un funcionamiento fiable en el trabajo diario.<br><br>Gracias al control de calidad realizado, cada escuadra cumple altos est\u00e1ndares de fabricaci\u00f3n y garantiza una larga vida \u00fatil.<\/p>\n\n\n\n<p class=\" translation-block\">El producto se <strong>fabrica \u00edntegramente en Polonia<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>Escuadra plana 275x150 es una herramienta destinada al posicionamiento de elementos planos que se sueldan sobre la mesa de soldadura utilizando un \u00e1ngulo de 90\u00b0.<\/p>","protected":false},"featured_media":13307,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[438,439],"product_tag":[],"class_list":{"0":"post-32733","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magazyn","7":"product_cat-narzedzia-plaskie","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-pro","11":"pa_srednica-otworow-28-lub-16","12":"pa_system-fi28","13":"pa_typ-narzedzia-plaskie","14":"pa_wymiar-narzedzia-275x150mm","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable","23":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product\/32733","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/comments?post=32733"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media\/13307"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media?parent=32733"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_brand?post=32733"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_cat?post=32733"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_tag?post=32733"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}