﻿{"id":24773,"date":"2025-08-30T05:52:00","date_gmt":"2025-08-30T03:52:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=24773"},"modified":"2026-07-15T10:58:06","modified_gmt":"2026-07-15T08:58:06","slug":"mesa-de-soldadura-plus-12-mm-2400-x-1200-mm-juego-de-herramientas-s","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_pe\/p\/conjuntos-promocionales\/mesa-de-soldadura-plus-12-mm-2400-x-1200-mm-juego-de-herramientas-s\/","title":{"rendered":"Mesa de soldadura PLUS 12 mm \u2013 2400 x 1200 mm + juego de herramientas S"},"content":{"rendered":"<p class=\" translation-block\"><b>Mesa de soldadura PLUS 2400x1200mm<\/b> es la soluci\u00f3n ideal para la soldadura manual y robotizada, all\u00ed donde la precisi\u00f3n, la repetibilidad y la comodidad de trabajo son fundamentales. Gracias al tablero mecanizado de 12 mm de espesor y al denso sistema de refuerzos (2 refuerzos transversales y 5 longitudinales), la mesa garantiza una superficie de trabajo perfectamente plana con una tolerancia de planitud de \u00b10,15 mm.<\/p>\n<p>Los orificios fresados y biselados (con una tolerancia de \u00b10,05 mm) garantizan un montaje preciso de las herramientas y un menor desgaste de las mismas. La escala grabada facilita el posicionamiento de los elementos y las mediciones.<\/p>\n<p>La estabilidad y resistencia de la mesa est\u00e1n garantizadas por una s\u00f3lida estructura base y patas fabricadas con perfil de 80x80 mm, disponibles con pies niveladores o con ruedas, seg\u00fan las necesidades. Cada pata tiene una capacidad de carga de 750 kg, lo que garantiza seguridad y comodidad de trabajo incluso con cargas elevadas.<\/p>\n<p>Juego compacto pero completo para talleres peque\u00f1os y trabajos de servicio y montaje. Contiene las herramientas necesarias para la fijaci\u00f3n y el posicionamiento b\u00e1sicos, como abrazaderas, escuadras de sujeci\u00f3n y topes. El juego tambi\u00e9n incluye estantes m\u00f3viles para pernos y un soporte para soplete, lo que facilita la organizaci\u00f3n del trabajo y aumenta la ergonom\u00eda del puesto de trabajo.<\/p>\n<table class=\"aligncenter\" border=\"0\" width=\"470\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"291\" \/>\n<col width=\"179\" \/><\/colgroup>\n<tbody>\n<tr>\n<td class=\"xl65\" width=\"291\" height=\"31\"><strong>SET S<\/strong><\/td>\n<td class=\"xl67\" width=\"179\"><strong>Total: 45<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Torniquetes sujetadores<\/td>\n<td class=\"xl66\" align=\"right\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete 150<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete 225<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete 260<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete exc\u00e9ntrico \u00d8 100<\/td>\n<td class=\"xl66\" align=\"right\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo plano 275\u00d7150<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 75\u00d775<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 75\u00d7185<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Escuadra de sujeci\u00f3n 200x300x150<\/td>\n<td class=\"xl66\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Perno de sujeci\u00f3n de montaje r\u00e1pido<\/td>\n<td class=\"xl66\" align=\"right\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Posicionamiento pin<\/td>\n<td class=\"xl66\" align=\"right\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Soporte para pistolas y antorchas de soldadura<\/td>\n<td class=\"xl66\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Estante m\u00f3vil para pernos S<\/td>\n<td class=\"xl66\" align=\"right\">2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p style=\"text-align: center;\">","protected":false},"excerpt":{"rendered":"<p>Mesa de soldadura PLUS 12mm \u2013 2400x1200mm + juego de herramientas s<\/p>","protected":false},"featured_media":24876,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-24773","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2400","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_nogi-na-stopach","12":"pa_nogi-na-kolach","13":"pa_nosnosc-500kg-noga","14":"pa_otwory-frezowane-i-fazowane","15":"pa_profil-nog-80x80x4-mm","16":"pa_rozmiar-2400x1200mm","17":"pa_seria-plus","18":"pa_siatka-100x100mm","19":"pa_siatka-50x50mm","20":"pa_siatka-diagonalna","21":"pa_system-fi28","22":"pa_system-fi16","23":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","24":"pa_tolerancja-wykonania-otworow-005-mm","25":"pa_wzmocnienie-zebrami-tak","27":"first","28":"instock","29":"sale","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable","34":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product\/24773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/comments?post=24773"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media\/24876"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/media?parent=24773"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_brand?post=24773"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_cat?post=24773"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_pe\/wp-json\/wp\/v2\/product_tag?post=24773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}