﻿{"id":37548,"date":"2026-06-16T06:55:21","date_gmt":"2026-06-16T04:55:21","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=37548"},"modified":"2026-06-16T08:18:46","modified_gmt":"2026-06-16T06:18:46","slug":"outlet-stol-spawalniczy-plus-2000x1000-mm-system-%cf%8616-siatka-100x100mm-w91","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_mx\/p\/outlet\/outlet-stol-spawalniczy-plus-2000x1000-mm-system-%cf%8616-siatka-100x100mm-w91\/","title":{"rendered":"[OUTLET] Mesa de soldadura PLUS 2000\u00d71000 mm \u2013 sistema \u03c616, rejilla 100x100 mm"},"content":{"rendered":"<p>Las mesas de soldadura son la herramienta ideal donde se requiere precisi\u00f3n y repetibilidad. La encimera de 12 mm de grosor con un nervado denso garantiza planitud y estabilidad, incluso con estructuras pesadas. El sistema de orificios \u03c616 fresados y avellanados en una rejilla de 100\u00d7100 mm facilita el montaje de herramientas, acelerando y simplificando el trabajo.<\/p>\n<p><strong>Caracter\u00edsticas principales de la mesa:<\/strong><\/p>\n<ul>\n<li>Tablero de 12 mm de grosor con un nervado denso que garantiza una superficie de trabajo perfectamente plana.<\/li>\n<li>Dimensiones: 2000\u00d71000 mm, 2 nervaduras longitudinales y 4 transversales que garantizan estabilidad durante el uso y resistencia a la deformaci\u00f3n.<\/li>\n<li>Malla de 100 \u00d7 100 mm, sistema \u03c616<\/li>\n<\/ul>\n<p>La superficie de la mesa est\u00e1 adem\u00e1s equipada con una escala grabada en una rejilla de 100\u00d7100 mm, lo que facilita el posicionamiento preciso de las estructuras y el montaje de herramientas, garantizando una alta precisi\u00f3n en cada operaci\u00f3n.<\/p>\n<p><strong>Variantes de patas:\u00a0<\/strong><\/p>\n<ul>\n<li>Con pies fijos \u2013 proporcionan estabilidad y gran capacidad de carga.<\/li>\n<li>Con ruedas \u2013 ideal para trabajos donde se requiere movilidad de la mesa.<\/li>\n<\/ul>\n<p>Al comprar este producto, puedes elegir una versi\u00f3n con patas fijas o con ruedas.<\/p>\n<p>Nogi sto\u0142u, wykonane z profilu 80&#215;80 mm, maj\u0105 no\u015bno\u015b\u0107 750 kg na ka\u017cd\u0105 nog\u0119, co przy 4 nogach daje no\u015bno\u015b\u0107 ca\u0142kowit\u0105 na poziomie 3000 kg. Dzi\u0119ki temu st\u00f3\u0142 jest stabilny nawet przy du\u017cych obci\u0105\u017ceniach.<\/p>\n<p class=\" translation-block\">Al comprar una mesa outlet, declaras que <strong>te has informado sobre su estado real<\/strong> y que la <strong>aceptas sin derecho a presentar reclamaciones<\/strong>. De acuerdo con el art\u00edculo 557 \u00a7 1 del C\u00f3digo Civil polaco, el vendedor queda exento de responsabilidad por garant\u00eda si el comprador conoc\u00eda el defecto en el momento de celebrar el contrato.<\/p>\n<p>\u00bfQuiere saber m\u00e1s sobre las mesas de soldadura tradicionales de GPPH? Consulte la informaci\u00f3n en la p\u00e1gina dedicada <a href=\"https:\/\/gpph-group.com\/es_mx\/productos\/mesa-de-soldadura-tradicional\/\">mesas de soldadura tradicionales.<\/a><a href=\"https:\/\/gpph-group.com\/es_mx\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0<\/a><\/p>\n<p id=\"defekty\"><strong>ATENCI\u00d3N: La mesa presenta un defecto:\u00a0<\/strong><\/p>\n<ul>\n<li>Obity blat<\/li>\n<\/ul>\n<p>Las fotos de los defectos se muestran a continuaci\u00f3n.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-1024x683.jpg\" alt=\"[OUTLET] Mesa de soldadura PLUS 2000x1000 mm \u2013 sistema \u03c616, rejilla 100x100 mm\" class=\"wp-image-37551\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322576-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-scaled.jpg\"><img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-683x1024.jpg\" alt=\"[OUTLET] Mesa de soldadura PLUS 2000x1000 mm \u2013 sistema \u03c616, rejilla 100x100 mm\" class=\"wp-image-37552\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-683x1024.jpg 683w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-200x300.jpg 200w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-768x1152.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-1024x1536.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-1365x2048.jpg 1365w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-8x12.jpg 8w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-600x900.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-64x96.jpg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/06\/P1322577-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p class=\" translation-block\">Le recomendamos consultar el <a href=\"https:\/\/gpph-group.com\/en_us\/p\/welding-tables\/eco\/welding-table-eco-1500-x-1000-mm\/?attribute_pa_system=f28&amp;attribute_pa_siatka=100x100mm&amp;attribute_pa_nogi=na-stopach\" target=\"_blank\" rel=\"noopener\">producto de valor completo<\/a>. La oferta actual corresponde a una unidad outlet, disponible en cantidad limitada y a un precio extremadamente atractivo.<\/p>\n<p><strong>\u00a1ATENCI\u00d3N! La mesa presenta defectos:<\/strong><\/p>\n<ul>\n<li>Obity blat<\/li>\n<\/ul>","protected":false},"featured_media":37557,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168],"product_tag":[],"class_list":{"0":"post-37548","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outlet","7":"product_shipping_class-stol-spawalniczy-2000","8":"pa_nogi-na-stopach","9":"pa_nogi-na-kolach","10":"pa_nosnosc-750kg-noga","11":"pa_seria-plus","12":"pa_siatka-100x100mm","13":"pa_srednica-otworow-364","14":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","15":"pa_wymiar-stolu-2400x1200","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-variable","24":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product\/37548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/comments?post=37548"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/media\/37557"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/media?parent=37548"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product_brand?post=37548"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product_cat?post=37548"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product_tag?post=37548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}