﻿{"id":33124,"date":"2026-02-24T14:23:00","date_gmt":"2026-02-24T12:23:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=33124"},"modified":"2026-06-15T08:47:34","modified_gmt":"2026-06-15T06:47:34","slug":"perno-de-montaje-magnetico-regulable-ecoplus-fi28-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_mx\/p\/deposito\/pernos-y-pasadores-almacen\/perno-de-montaje-magnetico-regulable-ecoplus-fi28-m\/","title":{"rendered":"Perno de montaje magn\u00e9tico regulable ECOPLUS - \u03c628"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Perno de montaje \u2013 conexi\u00f3n segura y r\u00e1pida de herramientas para mesas de soldadura<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Perno de montaje<\/strong> es una herramienta precisa dise\u00f1ada para <strong>la fijaci\u00f3n estable y la conexi\u00f3n de herramientas a la mesa de soldadura y entre s\u00ed<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Constituye un elemento clave del sistema de fijaci\u00f3n, que permite <strong>la uni\u00f3n r\u00e1pida, segura y confiable de herramientas<\/strong> durante trabajos de soldadura, montaje y herrer\u00eda.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/8\/9\/1\/891.jpg\" alt=\"Perno de montaje ajustable ECOPLUS sistema 28\" class=\"wp-image-14793 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/8\/9\/1\/891.jpg 800w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/8\/9\/1\/891-600x600.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/8\/9\/1\/891-300x300.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/8\/9\/1\/891-64x64.jpg 64w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construcci\u00f3n y funcionalidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">El perno est\u00e1 equipado con un <strong>mecanismo de bolas de alta precisi\u00f3n<\/strong>, que garantiza un bloqueo seguro en los <strong>orificios de montaje<\/strong> de la mesa o herramienta.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>La cabeza del perno<\/strong> est\u00e1 dise\u00f1ada para ofrecer <strong>un manejo c\u00f3modo y un agarre seguro<\/strong> \u2013 cuenta con un <strong>orificio hexagonal (tipo Allen)<\/strong> y una <strong>superficie moleteada<\/strong>, que permite un apriete o aflojado r\u00e1pido a mano, sin herramientas adicionales.<\/p>\n\n\n\n<p class=\" translation-block\">Gracias a su dise\u00f1o compacto y geometr\u00eda refinada, el perno garantiza <strong>la m\u00e1xima estabilidad de la uni\u00f3n<\/strong> y <strong>el posicionamiento preciso de los elementos durante el trabajo<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aplicaciones<\/strong><\/h3>\n\n\n\n<p>El perno de montaje es ideal para:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>fijaci\u00f3n de herramientas a la superficie de la mesa de soldadura,<\/li>\n\n\n\n<li>conexi\u00f3n de herramientas de soldadura entre s\u00ed,<\/li>\n\n\n\n<li>estabilizaci\u00f3n de uniones durante el montaje y la soldadura,<\/li>\n\n\n\n<li>realizaci\u00f3n de tareas que requieren repetibilidad y posicionamiento preciso,<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Sistema y compatibilidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Los pernos de montaje GPPH est\u00e1n disponibles en las versiones <strong>EXPERT, PRO, PLUS, ECOPLUS (ajustable)<\/strong> y <strong>UNI (de montaje r\u00e1pido)<\/strong>.<br><br>El modelo <strong>EXPERT<\/strong> est\u00e1 disponible para el sistema de orificios <strong>\u03c628 mm<\/strong>, mientras que los pernos <strong>PRO, PLUS<\/strong> y <strong>ECOPLUS<\/strong> se ofrecen en sistemas de <strong>\u03c616 mm<\/strong> y <strong>\u03c628 mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\"><strong>El perno de montaje r\u00e1pido UNI<\/strong> es la soluci\u00f3n m\u00e1s <strong>universal<\/strong>, que permite combinar herramientas y mesas de soldadura de diferentes series \u2013 por ejemplo, fijar herramientas <strong>PLUS<\/strong> en una mesa de la serie <strong>PRO<\/strong>, o al rev\u00e9s.<br><br>Los pernos <strong>UNI<\/strong> est\u00e1n disponibles en los sistemas <strong>\u03c616 mm<\/strong> y <strong>\u03c628 mm<\/strong>, lo que permite su uso en diversas configuraciones de trabajo.<br><br>Son una opci\u00f3n ideal cuando se dispone de mesas y herramientas de <strong>diferentes espesores<\/strong>, proporcionando una fijaci\u00f3n segura en un <strong>rango de ajuste de 20mm a 62mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Esta soluci\u00f3n garantiza <strong>una compatibilidad total con el sistema de mesas y herramientas GPPH<\/strong>, ofreciendo una fijaci\u00f3n estable y precisa durante el trabajo.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Material y fabricaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">El perno est\u00e1 fabricado en <strong>acero al carbono de alta calidad<\/strong>, caracterizado por su excelente resistencia mec\u00e1nica y su durabilidad frente al desgaste y la deformaci\u00f3n.<\/p>\n\n\n\n<p class=\" translation-block\">Cada elemento se somete a un <strong>riguroso control de calidad<\/strong>, lo que garantiza el m\u00e1ximo est\u00e1ndar de fabricaci\u00f3n, precisi\u00f3n dimensional y fiabilidad en el uso diario.<\/p>\n\n\n\n<p class=\" translation-block\">El producto se <strong>fabrica \u00edntegramente en Polonia<\/strong> con materiales que cumplen las normas de calidad para aceros estructurales.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\" translation-block\">El perno de montaje r\u00e1pido 19-22 es una herramienta utilizada para fijar herramientas PLUS en mesas de soldadura de las series ECO y DIY. Conecta un tablero <strong>de 8mm de grosor<\/strong> con herramientas <strong>de 11mm<\/strong> y ofrece <strong>3mm<\/strong> de ajuste.<\/p>","protected":false},"featured_media":14793,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[581,438],"product_tag":[],"class_list":{"0":"post-33124","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-trzpienie-i-piny-magazyn","7":"product_cat-magazyn","8":"product_shipping_class-narzedzia","9":"pa_srednica-otworow-28-lub-16","10":"pa_system-fi28","11":"pa_typ-narzedzia-trzpien","12":"pa_wymiar-narzedzia-64x40x40mm","14":"first","15":"instock","16":"sale","17":"taxable","18":"shipping-taxable","19":"purchasable","20":"product-type-variable","21":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product\/33124","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/comments?post=33124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/media\/14793"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/media?parent=33124"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product_brand?post=33124"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product_cat?post=33124"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_mx\/wp-json\/wp\/v2\/product_tag?post=33124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}