﻿{"id":23594,"date":"2025-08-19T08:13:00","date_gmt":"2025-08-19T06:13:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=23594"},"modified":"2026-06-15T12:49:13","modified_gmt":"2026-06-15T10:49:13","slug":"iq-aero-clean-wall-1-0","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_ec\/p\/dispositivos-de-ventilacion\/extractores-de-humos-de-soldadura\/iq-aero-clean-wall-1-0\/","title":{"rendered":"IQ Aero Clean Wall 1.0"},"content":{"rendered":"<p class=\" translation-block\"><span data-contrast=\"auto\">El extractor de humos de soldadura <strong>IQ Aero Clean Wall 1.0<\/strong> es un dispositivo de filtraci\u00f3n y ventilaci\u00f3n destinado a montaje en pared.<\/span><span> <\/span><\/p>\n<p><span data-contrast=\"none\">W odci\u0105gach spawalniczych zastosowali\u015bmy filtr przeciwiskrowy i filtr patronowy o powierzchni 20m\u00b2, a poziom filtracji to<strong> 99,5%<\/strong> dla cz\u0105steczek o wielko\u015bci 0,3 \u03bcm.\u202fWydajno\u015b\u0107 przep\u0142ywu powietrza to <strong>3000m<\/strong><\/span><strong>3<\/strong><span data-contrast=\"none\"><strong>\/h<\/strong>, natomiast poziom ha\u0142asu to 60 dB przy 40% mocy urz\u0105dzenia, oraz 80 dB przy 100% mocy \u2013 poziom ha\u0142asu zosta\u0142 zmierzony w bliskiej odleg\u0142o\u015bci od obudowy urz\u0105dzenia. Moc silnika to 2,2 kW, a zasilanie \u2013 400 V.\u202f<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El sistema de filtraci\u00f3n aplicado purifica el aire eliminando las part\u00edculas nocivas. El extractor de humos de soldadura GPPH est\u00e1 equipado con un sistema antipolvo con rejilla en los cajones, lo que evita la resuspensi\u00f3n secundaria de contaminantes durante el funcionamiento.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Adem\u00e1s, cuenta con un sistema de limpieza \u201cpulse-jet\u201d, que utiliza impulsos cortos e intensos de aire comprimido que invierten el flujo de aire en el filtro, eliminando eficazmente el polvo acumulado de la superficie de los cartuchos filtrantes. Dispone de la posibilidad de programar la frecuencia de funcionamiento del sistema.\u00a0<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El extractor puede estar equipado con uno o dos brazos de aspiraci\u00f3n de diferentes longitudes.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">El extractor de humos de soldadura IQ Aero Clean Wall se fabrica en Polonia.<\/span><span data-ccp-props=\"{&quot;134233117&quot;:true,&quot;134233118&quot;:true,&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>IQ Aero Clean Wall 1.0 es un sistema de filtraci\u00f3n de aire que elimina eficazmente el humo, el polvo y otros contaminantes. Mejora la calidad del aire en el lugar de trabajo, apoyando la salud y el confort de los empleados \u2013 ideal para talleres, naves de producci\u00f3n y otros entornos exigentes.<\/p>","protected":false},"featured_media":23596,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[178,126],"product_tag":[],"class_list":{"0":"post-23594","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-odciagi-spawalnicze","7":"product_cat-urzadzenia-wentylacyjne","8":"product_shipping_class-stol-spawalniczy-2000","9":"pa_material-wykonania-stal-malowana-proszkowo","10":"pa_moc-silnika-kw-322","11":"pa_napiecie-400-v","12":"pa_poziom-halasu-40-60-db-100-80-db","13":"pa_system-iq-flow-control-adaptacyjna-regulacja-przeplywu-powietrza","14":"pa_typ-filtracji-filtr-przeciwiskrowy-filtr-patronowy-o-powierzchni-20m2","15":"pa_wydajnosc-przeplywu-powietrza-3000-m3-h","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product\/23594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/comments?post=23594"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/media\/23596"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/media?parent=23594"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product_brand?post=23594"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product_cat?post=23594"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product_tag?post=23594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}