﻿{"id":23337,"date":"2025-08-12T11:08:00","date_gmt":"2025-08-12T09:08:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=23337"},"modified":"2026-06-15T09:00:18","modified_gmt":"2026-06-15T07:00:18","slug":"mesa-de-soldadura-profesional-2000-x-1000-mm-con-sistema-de-elevacion-hidraulico","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_ec\/p\/mesas-de-soldadura\/mesa-de-soldadura-profesional-2000-x-1000-mm-con-sistema-de-elevacion-hidraulico\/","title":{"rendered":"Mesa de soldadura EXPERT 2000\u00d71000 mm con sistema de elevaci\u00f3n hidr\u00e1ulico"},"content":{"rendered":"<p class=\" translation-block\">Las mesas de soldadura GPPH con sistema de elevaci\u00f3n hidr\u00e1ulico son mesas especializadas con regulaci\u00f3n autom\u00e1tica de la altura de la superficie de trabajo.<br>Gracias a ello, podr\u00e1 alcanzar r\u00e1pida y f\u00e1cilmente la altura de trabajo ideal de la superficie de la mesa, lo que garantiza un alto confort de trabajo.<\/p>\n<p>Las mesas de soldadura con sistema de elevaci\u00f3n hidr\u00e1ulico cuentan con:<\/p>\n<ul>\n<li>v\u00e1lvula de sobrecarga que impide levantar cargas demasiado pesadas;<\/li>\n<li>v\u00e1lvula de seguridad que detiene el descenso en caso de rotura de los conductos hidr\u00e1ulicos;<\/li>\n<li>Interruptores de l\u00edmite que protegen contra aplastamiento o lesiones corporales del usuario.<\/li>\n<\/ul>\n<p>Las mesas con sistema de elevaci\u00f3n hidr\u00e1ulica est\u00e1n disponibles en cinco series de tableros para mesas de soldadura GPPH: PRO, PRO INOX, PLUS, PLUS INOX y ECO, y cada serie en 4 versiones dimensionales.<\/p>\n<p>Cada tablero de mesa est\u00e1 disponible con orificios de 28 mm en rejillas de 100\u00d7100 mm y diagonales.<\/p>\n<p class=\" translation-block\"><strong>\u00a1La mesa de soldadura debe ser plana!<\/strong> Las encimeras de las mesas PRO con un espesor de 15 mm cuentan con <strong>un denso nervado<\/strong>, lo que garantiza una superficie de trabajo perfectamente plana. <strong>La base maciza y r\u00edgida de la encimera<\/strong> asegura la m\u00e1xima estabilidad durante el uso y protecci\u00f3n contra deformaciones. La tolerancia de planitud en toda la superficie de la mesa es de <strong>\u22640,15 mm <\/strong>(menor o igual a 0,15 mm).<\/p>\n<p class=\" translation-block\">Los <strong>orificios fresados y achaflanados<\/strong> en la encimera de la mesa de soldadura facilitan el montaje y desmontaje de las herramientas durante tu trabajo, gracias al ajuste preciso entre los orificios y los \u00fatiles. Esto tambi\u00e9n contribuye a un menor desgaste de los mismos: no necesitas aplicar una gran fuerza para montarlos y desmontarlos. Esta ejecuci\u00f3n es la mejor de las soluciones disponibles en el mercado de mesas de soldadura. La tolerancia de fabricaci\u00f3n de los orificios de la mesa de soldadura <span class=\"ui-provider gp b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\" dir=\"ltr\">es de <strong>\u2264<\/strong><\/span><strong>0,05 mm <\/strong>(menor o igual que 0,05 mm).<\/p>\n<p>Par\u00e1metros t\u00e9cnicos de la base con sistema hidr\u00e1ulico de elevaci\u00f3n:<\/p>\n<ul>\n<li>tensi\u00f3n de alimentaci\u00f3n: 400 V<\/li>\n<li>velocidad: 1400 rpm<\/li>\n<li>clase de protecci\u00f3n: IP54<\/li>\n<li>clase de aislamiento: F<\/li>\n<\/ul>\n<h4>Par\u00e1metros t\u00e9cnicos<\/h4>\n<ul>\n<li>Capacidad de carga m\u00e1xima [kg]: 3200<\/li>\n<li>Tiempo de elevaci\u00f3n con carga [s]: 30-40<\/li>\n<li>Altura m\u00e1xima de la mesa [mm]: 1200<\/li>\n<li>Altura m\u00ednima de la mesa [mm]: 470<\/li>\n<li>Dimensiones de la base del elevador [mm]: 1863\u00d7890<\/li>\n<li>Potencia del motor [kW]: 2,2<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Sto\u0142y Spawalnicze GPPH z hydraulicznym systemem podnoszenia to specjalistyczne sto\u0142y z automatyczn\u0105 regulacj\u0105 wysoko\u015bci blatu. Dzi\u0119ki niemu szybko i \u0142atwo osi\u0105gniesz idealn\u0105 wysoko\u015b\u0107 robocz\u0105 blatu sto\u0142u, zapewniaj\u0105c wysoki komfort pracy. Sto\u0142y spawalnicze z hydraulicznym systemem podnoszenia posiadaj\u0105: zaw\u00f3r przeci\u0105\u017ceniowy uniemo\u017cliwiaj\u0105cy podnoszenie zbyt ci\u0119\u017ckich \u0142adunk\u00f3w; zaw\u00f3r bezpiecze\u0144stwa zatrzymuj\u0105cy opuszczanie w momencie p\u0119kni\u0119cia przewod\u00f3w hydraulicznych; wy\u0142\u0105czniki kra\u0144cowe [&hellip;]<\/p>","protected":false},"featured_media":15045,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[68,88,111,82],"product_tag":[],"class_list":{"0":"post-23337","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stoly-spawalnicze","7":"product_cat-podnoszone","8":"product_cat-2000x1000-mm","9":"product_cat-xwt","10":"product_shipping_class-stol-spawalniczy-2000","11":"pa_blat-expert","12":"pa_max-wysokosc-stolu-mm-319","13":"pa_min-wysokosc-stolu-mm-320","14":"pa_moc-silnika-kw-322","15":"pa_nosnosc-max-kg-317","16":"pa_rozmiar-2000x1000mm","17":"pa_seria-xwt","18":"pa_siatka-100x100mm","19":"pa_siatka-diagonalna","20":"pa_system-fi28","21":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","22":"pa_tolerancja-wykonania-otworow-005-mm","23":"pa_wymiary-podstawy-podnosnika-m-1863x890","25":"first","26":"instock","27":"sale","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-variable","32":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product\/23337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/comments?post=23337"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/media\/15045"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/media?parent=23337"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product_brand?post=23337"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product_cat?post=23337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/product_tag?post=23337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}