﻿{"id":7289,"date":"2024-06-05T04:00:00","date_gmt":"2024-06-05T04:00:00","guid":{"rendered":"https:\/\/gpph-group.com\/?p=7289"},"modified":"2025-02-21T06:49:25","modified_gmt":"2025-02-21T06:49:25","slug":"encuentro-de-aficionados-a-la-soldadura-tercera-edicion-de-integration-forumgpphpl","status":"publish","type":"post","link":"https:\/\/gpph-group.com\/es_ec\/noticias\/encuentro-de-aficionados-a-la-soldadura-tercera-edicion-de-integration-forumgpphpl\/","title":{"rendered":"Encuentro de aficionados a la soldadura - Tercera edici\u00f3n de Integration Forum.GPPH.pl"},"content":{"rendered":"<p><strong>Encuentro de aficionados a la soldadura - Tercera edici\u00f3n de Integration Forum.GPPH.pl<\/strong>&nbsp;<\/p>\n\n\n\n<p class=\" translation-block\">El evento anual de integraci\u00f3n organizado por GPPH, dedicado a los usuarios de Forum.GPPH.pl, ya es historia. El <strong>evento se celebr\u00f3 por tercera vez y reuni\u00f3 a un n\u00famero r\u00e9cord de personas relacionadas con la industria de la soldadura<\/strong>. El evento, que despierta un gran inter\u00e9s cada a\u00f1o, fue una oportunidad para hacer valiosos contactos y compartir experiencias que pueden abrir las puertas a nuevas oportunidades de cooperaci\u00f3n y desarrollo. <strong>Krzysztof Rze\u017anik, copropietario de GPPH, resumi\u00f3 as\u00ed el prop\u00f3sito del evento<\/strong>: \"Creamos <em>nuestra red social para reunir a personas de la industria metal\u00fargica. Quer\u00edamos que tuvieran un lugar propio y dedicado, distinto de los que ten\u00edan hasta ahora. Los usuarios de nuestro foro se hacen amigos en el mundo virtual. Tambi\u00e9n sabemos que estas personas se comunican entre s\u00ed por tel\u00e9fono. Aqu\u00ed pueden conocerse en persona, pasar tiempo juntos. Estos lazos que forjan entre s\u00ed pueden influir mejor en su trabajo diario y en las amistades que sabemos que se forman aqu\u00ed y contin\u00faan hasta ahora.\"<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-1024x683.jpeg\" alt=\"Participantes en la tercera edici\u00f3n del Foro Integraci\u00f3n en 2024\u00a0\" class=\"wp-image-7298\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-1024x683.jpeg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-600x400.jpeg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-64x43.jpeg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-300x200.jpeg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-768x512.jpeg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10-18x12.jpeg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-10.jpeg 1386w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Participantes en la tercera edici\u00f3n del Foro Integraci\u00f3n en 2024<\/em>\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\" translation-block\">Al igual que en ediciones anteriores, el <strong>Foro Integraci\u00f3n de <\/strong>este a\u00f1o se <strong>dividi\u00f3 en una parte oficial, <\/strong>celebrada en la sala de exposiciones de GPPH, <strong>y una parte de entretenimiento<\/strong>, que tuvo lugar en el restaurante. El inicio del evento fue inaugurado por los propietarios de la empresa:<\/p>\n\n\n\n<p class=\" translation-block\"><strong>Wieslaw Piechota<\/strong>: \"Nos <em>gustar\u00eda daros la bienvenida a todos a una reuni\u00f3n tan numerosa para la tercera edici\u00f3n de la reuni\u00f3n del foro GPPH. Espero que hag\u00e1is muchas nuevas y fruct\u00edferas amistades y que pas\u00e9is el tiempo lo mejor posible.\"<\/em><\/p>\n\n\n\n<p class=\" translation-block\"><strong>Krzysztof Rzeznik<\/strong>: <em>\"Nuestro objetivo hoy es conocer a\u00fan mejor a la gente que no hemos visto en persona y conocer a aquellos con los que s\u00f3lo tenemos contacto por internet\".<\/em><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-1024x576.jpeg\" alt=\"Participantes en el Foro Intagration durante la presentaci\u00f3n de los productos GPPH\u00a0\" class=\"wp-image-7297\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-1024x576.jpeg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-600x337.jpeg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-64x36.jpeg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-300x169.jpeg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-768x432.jpeg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11-18x10.jpeg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-11.jpeg 1387w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Participantes en el Foro Intagration durante la presentaci\u00f3n de los productos GPPH<\/em>\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\" translation-block\">Result\u00f3 que los usuarios de la comunidad en l\u00ednea de la empresa hicieron muchos contactos valiosos entre s\u00ed. A la pregunta: \"<strong>\u00bfHas hecho nuevos amigos gracias a nuestro foro?\"<\/strong>, respondieron: \"En la medida de lo posible, sobre todo he conocido a gente cara a cara, no s\u00f3lo por escribir y hacer clic, sino f\u00edsicamente\", \"Gracias al foro s\u00ed, en la medida de lo posible. Hay gente excepcional del sector de la soldadura que puede intercambiar experiencias entre s\u00ed.\"<\/p>\n\n\n\n<p>En la primera parte de la reuni\u00f3n, el departamento comercial de GPPH present\u00f3 todos los productos que figuran en la oferta de la empresa y, en primicia, las novedades. Adem\u00e1s, se present\u00f3 una pel\u00edcula sobre la historia de la empresa y, mientras tanto, todos los participantes del evento tuvieron la oportunidad de practicar la construcci\u00f3n de competici\u00f3n, que aparecer\u00e1 en la feria STOM de Kielce del 19 al 22 de marzo de 2024. Tras la parte oficial, todos se dirigieron al restaurante, donde, adem\u00e1s de una cena de celebraci\u00f3n y una fiesta hasta el amanecer, esperaba a los participantes un invitado especial: el cantante de mon\u00f3logos Arkadiusz \"Jaksa\" Jakszewicz. Por la ma\u00f1ana, antes de volver a casa, todos se reunieron para desayunar juntos.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-1024x683.jpeg\" alt=\"Ensayos de los participantes antes del concurso &quot;Monta una estructura lo m\u00e1s r\u00e1pido posible y gana una mesa de soldar&quot;\u00a0\" class=\"wp-image-7299\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-1024x683.jpeg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-600x400.jpeg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-64x43.jpeg 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-300x200.jpeg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-768x512.jpeg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12-18x12.jpeg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2024\/05\/image-12.jpeg 1385w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><figcaption class=\"wp-element-caption\"><em>Ensayos de los participantes antes del concurso \"Monta una estructura lo m\u00e1s r\u00e1pido posible y gana una mesa de soldar\"<\/em>\u00a0<\/figcaption><\/figure>\n\n\n\n<p class=\" translation-block\">La tercera <strong>integraci\u00f3n del Foro fue un r\u00e9cord de asistencia<\/strong>: <em>\"Estamos muy satisfechos de la participaci\u00f3n que hemos tenido en la tercera edici\u00f3n del encuentro de foreros del GPPH. Hemos podido comprobar que ha venido mucha gente de todo el pa\u00eds. Tenemos indicios de que han venido desde la parte m\u00e1s lejana del pa\u00eds, es decir, desde m\u00e1s all\u00e1 del mar. Es una distancia enorme para venir a ver nuestros productos y conocer a los foreros. Estamos muy, muy orgullosos de ello. Nos vienen clientes, simpatizantes, los que han comprado nuestros productos y tambi\u00e9n gente que va a comprarlos. As\u00ed que es el lugar perfecto para conocer nuestros productos y a la gente que los fabrica\". - <\/em>Wieslaw Piechota, copropietario de GPPH, concluye.<\/p>\n\n\n\n<p>Vea la cobertura en v\u00eddeo de Integration: <a href=\"https:\/\/www.youtube.com\/watch?v=LeqlImoBkBE&#038;t\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">https:\/\/www.youtube.com\/watch?v=LeqlImoBkBE&amp;t<\/a>&nbsp;&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>El evento anual de integraci\u00f3n organizado por GPPH, dedicado a los usuarios de Forum.GPPH.pl, ya es historia. El evento se celebr\u00f3 por tercera vez y reuni\u00f3 a un n\u00famero r\u00e9cord de personas relacionadas con la industria de la soldadura. El evento, que despierta un gran inter\u00e9s cada a\u00f1o, fue una oportunidad para hacer valiosos contactos y compartir experiencias que pueden abrir las puertas a nuevas oportunidades de cooperaci\u00f3n y desarrollo. <\/p>","protected":false},"author":4,"featured_media":7298,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[26],"tags":[],"class_list":["post-7289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktualnosci"],"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/posts\/7289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/comments?post=7289"}],"version-history":[{"count":0,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/posts\/7289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/media\/7298"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/media?parent=7289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/categories?post=7289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ec\/wp-json\/wp\/v2\/tags?post=7289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}