﻿{"id":16228,"date":"2023-06-22T12:12:00","date_gmt":"2023-06-22T10:12:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=protector-5l"},"modified":"2026-07-14T05:44:41","modified_gmt":"2026-07-14T03:44:41","slug":"protector-5l","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_do\/p\/gpph-chem\/protector-5l\/","title":{"rendered":"PROTECTOR 5L"},"content":{"rendered":"<p>Agente antirrebote hidrosoluble, altamente concentrado y eficaz para mesas de soldadura, enriquecido con inhibidores de corrosi\u00f3n. Es un producto b\u00e1sico para proteger el puesto de soldadura, ya que deja una capa protectora especial y duradera. Gracias a \u00e9l, las mesas de soldadura permanecen sin salpicaduras, lo que se traduce en un trabajo m\u00e1s preciso, c\u00f3modo y ordenado. El uso del preparado PROTECTOR protege en gran medida el equipo contra los efectos del uso. El l\u00edquido es inodoro y no emite sustancias vol\u00e1tiles peligrosas para la salud durante la soldadura. No contiene compuestos oleosos, por lo que no hay contraindicaciones para su uso en materiales que se someten a etapas posteriores de pintura o galvanizaci\u00f3n. Para distribuir el producto de manera uniforme, recomendamos su aplicaci\u00f3n con el pulverizador GPPH CHEM, disponible aqu\u00ed.<\/p>\n<p><strong>MODO DE EMPLEO:<\/strong><\/p>\n<p>Aplicar con un pulverizador sobre toda la superficie de la mesa antes de comenzar a trabajar. Proporci\u00f3n 1:1 (1 l de producto:1 l de agua). Una vez finalizada la soldadura, limpiar el l\u00edquido con un pa\u00f1o suave.<\/p>\n<p><strong>CAPACIDAD:<\/strong><\/p>\n<p>5 L.<\/p>\n<p><strong>FECHA DE CADUCIDAD:<\/strong><\/p>\n<p>18 meses a partir de la fecha de fabricaci\u00f3n.<\/p>\n<p><strong>FICHA T\u00c9CNICA:<\/strong><\/p>\n<p>disponible bajo petici\u00f3n<\/p>\n<p><small><span style=\"color: #9b9b9b;\">PELIGRO:<\/span><br \/>\n<span style=\"color: #9b9b9b;\">H318 Riesgo de lesiones oculares graves. P264 Lavarse las manos minuciosamente despu\u00e9s de la manipulaci\u00f3n. P280 Utilizar guantes\/ropa protectora\/protecci\u00f3n ocular\/protecci\u00f3n facial. P270 No comer, beber ni fumar durante la manipulaci\u00f3n.  P301+P312 EN CASO DE INGESTI\u00d3N: Si se encuentra mal, acuda a un CENTRO DE INFORMACI\u00d3N TOXICOL\u00d3GICA\/a un m\u00e9dico. P330 Enjuagarse la boca. P305+P351+P338 EN CASO DE CONTACTO CON LOS OJOS: Aclarar cuidadosamente con agua durante varios minutos. Quitar las lentes de contacto si lleva y si es f\u00e1cil de hacer. Seguir enjuagando. P501 Eliminar el contenido\/recipiente en un punto de recogida de residuos peligrosos o especiales.<\/span><\/small><\/p>\n<p>Contiene: Alcoholes, C13, ramificados, etoxilados, pol\u00edmero.<\/p>\n<p>Contiene: 5-15 % de tensioactivos no i\u00f3nicos.<\/p>","protected":false},"excerpt":{"rendered":"<p>Concentrado antichispas para proteger mesas de soldadura, enriquecido con inhibidores de corrosi\u00f3n.<br \/>\n<strong>PARA USO PROFESIONAL<\/strong><\/p>\n<p>Es un producto b\u00e1sico para proteger el puesto de soldadura, ya que deja una capa protectora especial y duradera. Gracias a \u00e9l, las mesas de soldadura no se astillan, lo que se traduce en un trabajo m\u00e1s preciso, c\u00f3modo y ordenado.<\/p>","protected":false},"featured_media":16229,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[102,69],"product_tag":[],"class_list":{"0":"post-16228","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-chemia-spawalnicza","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_pojemnosc-5-l","10":"pa_termin-przydatnosci-18-miesiecy-od-daty-produkcji","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product\/16228","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/comments?post=16228"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/media\/16229"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/media?parent=16228"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product_brand?post=16228"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product_cat?post=16228"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product_tag?post=16228"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}