﻿{"id":14881,"date":"2023-01-10T12:50:00","date_gmt":"2023-01-10T10:50:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=modulowy-stol-spawalniczy-pojedynczy-1600x1500-mm"},"modified":"2026-07-07T08:59:41","modified_gmt":"2026-07-07T06:59:41","slug":"mesa-de-soldadura-modular-individual-1600x1500-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_do\/p\/mesas-de-soldadura\/modulares\/mesa-de-soldadura-modular-individual-1600x1500-mm\/","title":{"rendered":"Mesa de soldadura modular individual 1600\u00d71500 mm"},"content":{"rendered":"<p>Esta subasta se refiere a una mesa de soldadura modular individual con placas de superficie fabricadas en material S355J2+N con unas dimensiones de 1600\u00d71500.<\/p>\n<p>Las mesas modulares individuales son ideales para la producci\u00f3n de piezas de peque\u00f1o tama\u00f1o o como base para ampliar sin l\u00edmites la superficie de la estaci\u00f3n de soldadura. Est\u00e1n disponibles en tres tama\u00f1os: 1000\u00d71000, 1200\u00d71200 y 1600\u00d71500.<\/p>\n<p class=\" translation-block\">El tablero de las mesas modulares est\u00e1 compuesto por placas fresadas y desplazables de 15 mm de grosor, y gracias a la regulaci\u00f3n de su superficie se consigue una planitud perfecta. Est\u00e1n fabricadas con un sistema de orificios de 28 mm en una rejilla de 100\u00d7100 mm.\nCuentan con orificios fresados y biselados que facilitan el montaje de las herramientas. Las mesas modulares son compatibles con las herramientas de la serie PRO. Adem\u00e1s, el dise\u00f1o de nuestras mesas modulares permite aumentar el n\u00famero de puntos de fijaci\u00f3n de las herramientas en los huecos entre las placas de la superficie, lo que mejora la ergonom\u00eda del trabajo.<\/p>\n<p class=\" translation-block\">Las mesas modulares tienen ruedas con pie en las patas base, con una <strong>capacidad de carga de 250 kg por pata<\/strong>. Las versiones extensibles de las mesas modulares tienen <strong>soportes ajustables <\/strong>en las patas adicionales. La altura de las mesas puede ajustarse entre 850 mm y 1150 mm, P=50 mm.<\/p>\n<p class=\" translation-block\">Para obtener una mayor superficie de trabajo, las <strong>mesas pueden combinarse entre s\u00ed<\/strong>. Como opci\u00f3n, tambi\u00e9n se pueden adquirir placas laterales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ta aukcja dotyczy pojedynczego modu\u0142owego sto\u0142u spawalniczego z p\u0142ytami blatu wykonanymi z materia\u0142u: S355J2+N o wymiarze 1600&#215;1500. Pojedyncze sto\u0142y modu\u0142owe s\u0105 idealne do produkcji ma\u0142o gabarytowych lub s\u0142u\u017c\u0105 jako podstawa do nieograniczonej rozbudowy powierzchni stanowiska spawalniczego. Wyst\u0119puj\u0105 w trzech wersjach wymiarowych: 1000&#215;1000, 1200&#215;1200, 1600&#215;1500. Blat sto\u0142\u00f3w modu\u0142owych sk\u0142ada si\u0119 z frezowanych, przesuwnych p\u0142yt o grubo\u015bci [&hellip;]<\/p>","protected":false},"featured_media":14882,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[86,81,68],"product_tag":[],"class_list":{"0":"post-14881","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-modulowe","7":"product_cat-mwt","8":"product_cat-stoly-spawalnicze","9":"product_shipping_class-stol-spawalniczy-2000","10":"pa_grubosc-blatu-15mm","11":"pa_nosnosc-250kg-noga","12":"pa_otwory-frezowane-i-fazowane","13":"pa_rozmiar-1600x1500mm","14":"pa_seria-mwt","15":"pa_siatka-100x100mm","16":"pa_system-fi28","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product\/14881","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/comments?post=14881"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/media\/14882"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/media?parent=14881"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product_brand?post=14881"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product_cat?post=14881"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_do\/wp-json\/wp\/v2\/product_tag?post=14881"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}