﻿{"id":32708,"date":"2026-02-24T08:34:00","date_gmt":"2026-02-24T06:34:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=32708"},"modified":"2026-06-15T08:49:53","modified_gmt":"2026-06-15T06:49:53","slug":"escuadra-de-soldadura-75x75-mm-fi28-expert-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_cr\/p\/deposito\/escuadra-de-soldadura-75x75-mm-fi28-expert-m\/","title":{"rendered":"Escuadra de soldadura 75x75 mm - \u03c628 - EXPERT"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Escuadra de soldadura \u2013 posicionamiento preciso de elementos en \u00e1ngulo recto<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:auto 28%\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Escuadra de soldadura<\/strong> es un elemento de posicionamiento preciso utilizado durante la soldadura, el montaje y los trabajos met\u00e1licos en mesas de soldadura.<\/p>\n\n\n\n<p><br>Permite un ajuste preciso y un mantenimiento estable de las piezas en \u00e1ngulo recto, lo cual es fundamental al adaptar y unir perfiles, tubos o estructuras de acero.<\/p>\n\n\n\n<p><br>La escuadra tiene forma de letra \u201cL\u201d y se fabrica con una alta precisi\u00f3n dimensional, lo que garantiza que mantenga el \u00e1ngulo correcto y permita una colocaci\u00f3n repetible de las piezas.<\/p>\n\n\n\n<p><br>Los orificios de montaje permiten una fijaci\u00f3n r\u00e1pida y un ajuste f\u00e1cil seg\u00fan las necesidades del trabajo.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO.png\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO.png\" alt=\"Escuadra de soldadura 75x75 mm PRO\" class=\"wp-image-25158 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO.png 1000w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_006_PRO-64x64.png 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/a><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compatibilidad con mesas de soldadura<\/strong><\/h3>\n\n\n\n<p>Las escuadras de soldadura est\u00e1n disponibles en tres series, adaptadas a los diferentes tipos de mesas de soldadura:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\" translation-block\"><strong>EXPERT \u2013<\/strong> dise\u00f1ada para mesas de soldadura con tablero de 25 mm de grosor.<\/li>\n\n\n\n<li class=\" translation-block\"><strong>PRO \u2013<\/strong> dise\u00f1ada para mesas de soldadura con tablero de 15 mm de grosor.<\/li>\n\n\n\n<li class=\" translation-block\"><strong>PLUS \u2013<\/strong> dise\u00f1ada para mesas de soldadura con tableros de 12 mm y 8 mm de grosor.<\/li>\n<\/ul>\n\n\n\n<p>Cada serie mantiene total compatibilidad con su tipo de mesa de soldadura, garantizando un ajuste adecuado y una colocaci\u00f3n estable de las piezas.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construcci\u00f3n y acabado<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Der Schwei\u00dfwinkel besteht aus Baustahl <strong>S355J2+N<\/strong>, der gegen Verformungen und intensive Nutzung unter Werkstattbedingungen best\u00e4ndig ist.<br>Jede Arbeitsfl\u00e4che ist pr\u00e4zise bearbeitet, was eine stabile Auflage und sichere Positionierung der Werkst\u00fccke gew\u00e4hrleistet.<br>Die robuste Konstruktion bew\u00e4hrt sich sowohl im t\u00e4glichen Einsatz als auch bei Projekten, die hohe Pr\u00e4zision und Wiederholgenauigkeit erfordern.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Ventajas de utilizar una escuadra de soldadura<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>posicionamiento preciso de los elementos en \u00e1ngulo recto,<\/li>\n\n\n\n<li>soporte estable y sujeci\u00f3n segura de las piezas,<\/li>\n\n\n\n<li>preparaci\u00f3n r\u00e1pida de las estructuras para la soldadura,<\/li>\n\n\n\n<li>estructura de acero duradera y resistente,<\/li>\n\n\n\n<li>uso universal en trabajos de soldadura, montaje y cerrajer\u00eda.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aplicaciones<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>posicionamiento de perfiles, tubos y elementos estructurales,<\/li>\n\n\n\n<li>montaje y control de uniones en \u00e1ngulo recto,<\/li>\n\n\n\n<li>trabajos de taller que requieren una alineaci\u00f3n precisa y una sujeci\u00f3n estable.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Informaci\u00f3n adicional<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La escuadra se fabrica en <strong>Polonia<\/strong> con materiales que cumplen las normas de calidad para aceros estructurales.<\/p>\n\n\n\n<p>Cada componente se somete a un control de calidad que garantiza el m\u00e1s alto nivel de fabricaci\u00f3n.<\/p>","protected":false},"excerpt":{"rendered":"<p>Escuadra de soldadura 75x75 mm<\/p>","protected":false},"featured_media":25157,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[438,441],"product_tag":[],"class_list":{"0":"post-32708","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magazyn","7":"product_cat-narzedzia-przestrzenne","8":"product_shipping_class-narzedzia","9":"pa_seria-expert","10":"pa_srednica-otworow-28-lub-16","11":"pa_system-fi28","12":"pa_typ-narzedzia-przestrzenne","13":"pa_wymiar-narzedzia-75x75mm","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product\/32708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/comments?post=32708"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/media\/25157"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/media?parent=32708"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product_brand?post=32708"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product_cat?post=32708"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product_tag?post=32708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}