﻿{"id":15828,"date":"2023-04-28T21:43:00","date_gmt":"2023-04-28T19:43:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stol-spawalniczy-plus-inox-1200-x-1000-mm"},"modified":"2026-06-10T12:20:52","modified_gmt":"2026-06-10T10:20:52","slug":"mesa-de-soldadura-plus-inox-1200-x-1000-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_cr\/p\/mesas-de-soldadura\/plus-inox\/mesa-de-soldadura-plus-inox-1200-x-1000-mm\/","title":{"rendered":"Mesa de soldadura PLUS INOX 12 mm \u2013 1200 x 1000 mm"},"content":{"rendered":"<p class=\" translation-block\">Las mesas de soldadura las utilizar\u00e1s dondequiera que se requiera <strong>precisi\u00f3n durante la soldadura<\/strong>. Las usar\u00e1s para soldadura manual o robotizada. <strong>Tus construcciones se realizar\u00e1n finalmente con exactitud, sin correcciones innecesarias!<\/strong><\/p>\n<p>Tambi\u00e9n proporciona un trabajo ergon\u00f3mico y r\u00e1pido, manteniendo la precisi\u00f3n y la repetibilidad de las construcciones realizadas.<\/p>\n<p><strong><a href=\"https:\/\/gpph-group.com\/es_cr\/\">St\u00f3\u0142 Spawalniczy<\/a> musi by\u0107 p\u0142aski!<\/strong> Blaty Sto\u0142\u00f3w PLUS, maj\u0105ce grubo\u015b\u0107 12mm, posiadaj\u0105 g\u0119ste o\u017cebrowanie, co wp\u0142ywa na idealnie p\u0142ask\u0105 powierzchni\u0119 robocz\u0105. St\u00f3\u0142 o wymiarze 1200&#215;1000 mm ma 2 \u017cebra wzd\u0142u\u017cne i 2 \u017cebra pod\u0142u\u017cne. Masywna i sztywna podbudowa blatu sto\u0142u gwarantuje najwy\u017csz\u0105 stabilno\u015b\u0107 podczas u\u017cytkowania oraz zabezpieczenie przed odkszta\u0142ceniem. Tolerancja p\u0142asko\u015bci sto\u0142u na ca\u0142ym blacie wynosi \u2264<strong>0,3<\/strong><strong>\u00a0mm<\/strong>*.<\/p>\n<table class=\"description_table--thickness_and_ribbing\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/BLAT_PLUS.jpg\" alt=\"Tablero de mesa de soldadura\" width=\"500\" height=\"500\" \/><\/td>\n<td><img decoding=\"async\" class=\"mh-500\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/stoly\/ozebrowanie\/ozebrowanie_twt_inox_1200x1000.png\" alt=\"Refuerzo de nervaduras de la mesa 1200x1000\u202fmm\" width=\"500\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\" translation-block\"><strong>Las mesas de soldadura inoxidables<\/strong>  de la serie INOX est\u00e1n fabricadas en acero inoxidable de grado 1.4301, que se caracteriza por una mejor conductividad el\u00e9ctrica que el acero normal: resistencia el\u00e9ctrica a 20 \u00b0C = 0,73 (\u03a9 mm\u00b2)\/m.  Se pueden utilizar en todos los lugares donde se requiere una soldadura precisa del acero inoxidable.<\/p>\n<p>Las mesas de soldadura inoxidables se caracterizan por su alta calidad de fabricaci\u00f3n y resistencia al desgaste. Est\u00e1n fabricadas en acero inoxidable con alto contenido en cromo, lo que les garantiza durabilidad y resistencia a la corrosi\u00f3n. Gracias a las mesas de soldadura GPPH INOX, al soldar estructuras de acero inoxidable no hay que temer que el hierro se precipite y aparezcan focos de corrosi\u00f3n.<\/p>\n<p><strong>\u00a1T\u00fa decides! <\/strong><\/p>\n<table class=\"descriptionSystemsTable\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/INOX_28_100.png\" alt=\"Malla 100\u00d7100\u202fmm, sistema fi28\" width=\"500\" \/><\/td>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/INOX_16_100.png\" alt=\"Malla 100 x 100 mm, sistema fi16\" width=\"500\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/INOX_28_DIAG.png\" alt=\"Malla diagonal, sistema fi28\" width=\"500\" \/><\/td>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/INOX_16_DIAG.png\" alt=\"Malla diagonal, sistema fi28\" width=\"500\" \/><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/INOX_16_50.png\" alt=\"Malla de 50 x 50 mm, sistema fi16\" width=\"500\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\" translation-block\">Los orificios <strong>fresados y biselados<\/strong> en la superficie de la mesa facilitan el montaje y desmontaje de las herramientas durante el trabajo, gracias al ajuste perfecto de los orificios a las herramientas. Esto tambi\u00e9n contribuye a reducir su desgaste, ya que no es necesario aplicar mucha fuerza para montarlas y desmontarlas. \u00a1Este dise\u00f1o es la mejor soluci\u00f3n disponible en el mercado de mesas de soldadura! La tolerancia de fabricaci\u00f3n de los orificios de la mesa de soldadura es de <strong>\u00b10,05 mm<\/strong>.<\/p>\n<p class=\" translation-block\">La\u202f<strong>graduaci\u00f3n grabada<\/strong> de la superficie de la mesa consiste en l\u00edneas verticales y horizontales en la malla de 100\u00d7100\u202fmm. Sirve como punto de referencia al colocar la construcci\u00f3n y durante el montaje de herramientas. Con instrumentos de medici\u00f3n, puedes ajustar correctamente tu construcci\u00f3n para obtener la dimensi\u00f3n necesaria.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/grawerowana_podzialka.jpg\" alt=\"Escala grabada\" width=\"1000\" height=\"500\" \/><\/p>\n<p>Las patas de las mesas de soldadura PLUS INOX, fabricadas con perfil de 80x80 mm, tienen una capacidad de carga de 750 kg\/pata. En el caso de la dimensi\u00f3n 3000x1480 mm, que tiene 8 patas, se obtiene una capacidad m\u00e1xima de carga de 6 000 kg.<\/p>\n<p>Tienes la elecci\u00f3n: pata con pie o con rueda\u202f\u2013 comprueba cu\u00e1l ser\u00e1 mejor para ti.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/nosnosc_nogi_PLUS.jpg\" alt=\"Capacidad de carga de la pata de la mesa de soldadura PLUS\" width=\"500\" height=\"500\" \/><\/p>\n<p>Para trabajar con las mesas de soldadura de la serie PLUS INOX, utilice las herramientas fresadas PLUS. Con ellas, podr\u00e1 realizar con precisi\u00f3n cualquier construcci\u00f3n plana en 2D y espacial en 3D. \u00a1Y todo ello en mucho menos tiempo!<\/p>\n<p>*siempre que la mesa est\u00e9 correctamente nivelada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sto\u0142y Spawalnicze wykorzystasz wsz\u0119dzie tam, gdzie potrzebna jest precyzja podczas spawania. U\u017cyjesz go do spawania manualnego lub zrobotyzowanego. Twoje konstrukcje nareszcie b\u0119d\u0105 wykonane dok\u0142adnie, bez zb\u0119dnego poprawiania! Zapewnia on tak\u017ce ergonomiczn\u0105 i szybk\u0105 prac\u0119 przy zachowaniu precyzji oraz powtarzalno\u015b\u0107 wykonywanych konstrukcji. St\u00f3\u0142 Spawalniczy musi by\u0107 p\u0142aski! Blaty Sto\u0142\u00f3w PLUS, maj\u0105ce grubo\u015b\u0107 12mm, posiadaj\u0105 g\u0119ste o\u017cebrowanie, [&hellip;]<\/p>","protected":false},"featured_media":15829,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[139,68,115,141,85],"product_tag":[],"class_list":{"0":"post-15828","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-plus-inox","7":"product_cat-stoly-spawalnicze","8":"product_cat-1200x1000-mm","9":"product_cat-stoly-spawalnicze-ze-stali-nierdzewnej","10":"product_cat-tradycyjne","11":"product_shipping_class-stol-spawalniczy-2000","12":"pa_blat-plus-inox","13":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","14":"pa_grubosc-blatu-12-mm","15":"pa_nogi-na-kolach","16":"pa_nogi-na-stopach","17":"pa_nosnosc-750kg-noga","18":"pa_otwory-frezowane-i-fazowane","19":"pa_profil-nog-80x80x4-mm","20":"pa_rozmiar-1200x1000mm","21":"pa_seria-plus-inox","22":"pa_siatka-100x100mm","23":"pa_siatka-50x50mm","24":"pa_siatka-diagonalna","25":"pa_system-fi16","26":"pa_system-fi28","27":"pa_tolerancja-plaskosci-03-mm","28":"pa_tolerancja-wykonania-otworow-005-mm","29":"pa_wzmocnienie-zebrami-tak","31":"first","32":"instock","33":"sale","34":"taxable","35":"shipping-taxable","36":"purchasable","37":"product-type-variable","38":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product\/15828","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/comments?post=15828"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/media\/15829"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/media?parent=15828"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product_brand?post=15828"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product_cat?post=15828"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cr\/wp-json\/wp\/v2\/product_tag?post=15828"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}