﻿{"id":24691,"date":"2025-08-29T13:38:00","date_gmt":"2025-08-29T11:38:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=24691"},"modified":"2026-07-06T10:28:12","modified_gmt":"2026-07-06T08:28:12","slug":"mesa-de-soldadura-plus-12-mm-2000-x-1000-mm-juego-de-herramientas-xs","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_co\/p\/conjuntos-promocionales\/mesa-de-soldadura-plus-12-mm-2000-x-1000-mm-juego-de-herramientas-xs\/","title":{"rendered":"Mesa de soldadura PLUS 12 mm \u2013 2000 x 1000 mm + juego de herramientas XS"},"content":{"rendered":"<p class=\" translation-block\"><b>La mesa de soldadura GPPH PLUS con unas dimensiones de 2000\u00d71000 mm <\/b> es una soluci\u00f3n profesional para usuarios exigentes. La superficie de trabajo de 12 mm de grosor con nervaduras densas garantiza una superficie de trabajo perfectamente plana, lo que garantiza la precisi\u00f3n y la repetibilidad de las construcciones realizadas. Los orificios fresados y biselados de 28 mm de di\u00e1metro, dispuestos en una rejilla de 100\u00d7100 mm con escala grabada, permiten montar f\u00e1cilmente accesorios como abrazaderas de sujeci\u00f3n o \u00e1ngulos. La mesa est\u00e1 equipada con cuatro patas de perfil 80\u00d780 mm, cada una con una capacidad de carga de 500 kg, lo que garantiza la estabilidad y resistencia de la estructura. El ajuste de altura en el rango de 880-930 mm permite adaptar la mesa a las necesidades individuales del usuario.<\/p>\n<p>El juego m\u00e1s compacto de la gama: solo contiene las herramientas m\u00e1s importantes para la fijaci\u00f3n y el posicionamiento b\u00e1sicos. Se utiliza cuando el espacio y la movilidad son fundamentales, por ejemplo, en trabajos de mantenimiento, montaje o en puestos de trabajo con espacio reducido. A pesar de su reducido tama\u00f1o, ofrece un apoyo s\u00f3lido para trabajos de soldadura ligeros.<\/p>\n<table class=\"aligncenter\" border=\"0\" width=\"424\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"276\" \/>\n<col width=\"148\" \/><\/colgroup>\n<tbody>\n<tr>\n<td class=\"xl66\" width=\"276\" height=\"31\"><strong>SET XS<\/strong><\/td>\n<td class=\"xl68\" width=\"148\"><strong>Total: 36<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Torniquetes sujetadores<\/td>\n<td class=\"xl67\" align=\"right\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Trinquete 150<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Trinquete 225<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Trinquete exc\u00e9ntrico \u00d8 100<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">\u00c1ngulo plano 275\u00d7150<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Perno de sujeci\u00f3n de montaje r\u00e1pido<\/td>\n<td class=\"xl67\" align=\"right\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Posicionamiento pin<\/td>\n<td class=\"xl67\" align=\"right\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Soporte para pistolas y antorchas de soldadura<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Estante m\u00f3vil para pernos S<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Mesa de soldadura PLUS 12 mm \u2013 2000 x 1000 mm + juego de herramientas XS<\/p>","protected":false},"featured_media":24834,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-24691","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2000","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_nogi-na-stopach","12":"pa_nogi-na-kolach","13":"pa_nosnosc-500kg-noga","14":"pa_otwory-frezowane-i-fazowane","15":"pa_profil-nog-80x80x4-mm","16":"pa_rozmiar-2000x1000mm","17":"pa_seria-plus","18":"pa_siatka-100x100mm","19":"pa_siatka-50x50mm","20":"pa_siatka-diagonalna","21":"pa_system-fi28","22":"pa_system-fi16","23":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","24":"pa_tolerancja-wykonania-otworow-005-mm","25":"pa_wzmocnienie-zebrami-tak","27":"first","28":"instock","29":"sale","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable","34":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product\/24691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/comments?post=24691"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/media\/24834"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/media?parent=24691"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_brand?post=24691"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_cat?post=24691"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_tag?post=24691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}