﻿{"id":24610,"date":"2025-08-29T11:37:14","date_gmt":"2025-08-29T09:37:14","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=24610"},"modified":"2026-06-13T12:06:05","modified_gmt":"2026-06-13T10:06:05","slug":"mesa-de-soldadura-smart-12-mm-2000-x-1000-mm-juego-de-herramientas-3xl","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_co\/p\/conjuntos-promocionales\/mesa-de-soldadura-smart-12-mm-2000-x-1000-mm-juego-de-herramientas-3xl\/","title":{"rendered":"Mesa de soldadura SMART 12 mm \u2013 2000 x 1000 mm + juego de herramientas 3XL"},"content":{"rendered":"<p style=\"text-align: left;\" class=\" translation-block\"><b>La mesa de soldadura GPPH SMART 12 con unas dimensiones de 2000\u00d71000 mm<\/b> es una soluci\u00f3n econ\u00f3mica dise\u00f1ada para aficionados y talleres peque\u00f1os y medianos. La superficie de trabajo, con un grosor de 12 mm, garantiza estabilidad y seguridad durante el trabajo. El sistema de orificios de 28 mm de di\u00e1metro, distribuidos en una cuadr\u00edcula de 100\u00d7100 mm, permite fijar f\u00e1cilmente accesorios y elementos de construcci\u00f3n. La escala grabada en la superficie facilita el posicionamiento preciso de las piezas que se est\u00e1n trabajando. La mesa se caracteriza por tener menos nervaduras en comparaci\u00f3n con los modelos profesionales, lo que la hace m\u00e1s ligera y m\u00f3vil, manteniendo al mismo tiempo la resistencia adecuada.<\/p>\n<p>El juego m\u00e1s grande y completo de nuestra oferta, dise\u00f1ado para profesionales. Incluye una amplia selecci\u00f3n de herramientas de fijaci\u00f3n, posicionamiento y ayuda para el ajuste preciso de los elementos en la mesa. El juego incluye dos carros de herramientas con cajones que garantizan el orden y un f\u00e1cil acceso a todos los componentes. Una elecci\u00f3n perfecta para la producci\u00f3n en serie y las grandes plantas de soldadura.<\/p>\n<table class=\"aligncenter\" border=\"0\" width=\"547\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"358\" \/>\n<col width=\"189\" \/><\/colgroup>\n<tbody>\n<tr>\n<td class=\"xl65\" width=\"358\" height=\"31\"><strong>SET 3XL<\/strong><\/td>\n<td class=\"xl68\" width=\"189\"><strong>Total: 252<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Torniquetes sujetadores<\/td>\n<td class=\"xl69\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Tornillo de apriete ajustable con palanca de acci\u00f3n r\u00e1pida<\/td>\n<td class=\"xl69\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Tornillo de apriete con palanca de acci\u00f3n r\u00e1pida<\/td>\n<td class=\"xl69\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Mango de abrazadera de tubo<\/td>\n<td class=\"xl69\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Abrazadera angular para tubos H=330 L=245, 45\u00b0<\/td>\n<td class=\"xl69\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Abrazadera recta H=330 L=175, 90\u00b0<\/td>\n<td class=\"xl69\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Abrazadera recta para tubos H=330 L=245, 180\u00b0<\/td>\n<td class=\"xl69\">20<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Placa de presi\u00f3n perfilada<\/td>\n<td class=\"xl69\">3<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">List\u00f3n de presi\u00f3n 175<\/td>\n<td class=\"xl69\">3<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Trinquete 150<\/td>\n<td class=\"xl69\">12<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Trinquete 225<\/td>\n<td class=\"xl69\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Trinquete 260<\/td>\n<td class=\"xl69\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Trinquete 500<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra angular<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Trinquete exc\u00e9ntrico \u00d8 100<\/td>\n<td class=\"xl69\">8<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Placa adaptadora 150\u00d7150<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Placa adaptadora 200\u00d7150<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo plano 275\u00d7150<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo plano 320\u00d7150<\/td>\n<td class=\"xl69\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra plana 350\u00d7250<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 75\u00d775<\/td>\n<td class=\"xl69\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 75\u00d7185<\/td>\n<td class=\"xl69\">8<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 125\u00d7185<\/td>\n<td class=\"xl69\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 185\u00d7175<\/td>\n<td class=\"xl69\">8<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 200\u00d7200<\/td>\n<td class=\"xl69\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 300\u00d7190 (derecho)<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 300\u00d7190 (izquierdo)<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 450\u00d7250 (derecho)<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">\u00c1ngulo 450\u00d7250 (izquierdo)<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra de sujeci\u00f3n 275x500x175x100 (derecha)<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra de sujeci\u00f3n 275x500x175x100 (izquierda)<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra de sujeci\u00f3n 200x300x150<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra de sujeci\u00f3n 275x400x200<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra de sujeci\u00f3n 350x500x250<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra angular espacial 180x260x225 (derecha)<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Escuadra angular espacial 180x260x225 (izquierda)<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Perno de sujeci\u00f3n de montaje r\u00e1pido<\/td>\n<td class=\"xl69\">40<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Posicionamiento pin<\/td>\n<td class=\"xl69\">20<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Soporte para pistolas y antorchas de soldadura<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Extensi\u00f3n 1000\u00d7100<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Extensi\u00f3n 1000\u00d7200<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Bloque multiusos<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Estante m\u00f3vil para pernos M<\/td>\n<td class=\"xl69\">3<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Estante m\u00f3vil para sargentos M<\/td>\n<td class=\"xl69\">3<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Estante m\u00f3vil plana M<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Estante m\u00f3vil MIX<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Estante m\u00f3vil para documentos<\/td>\n<td class=\"xl69\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"29\">Carro de herramientas L con cajones<\/td>\n<td class=\"xl69\">2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Mesa de soldadura SMART 12 mm \u2013 2000 x 1000 mm + juego de herramientas 3XL<\/p>","protected":false},"featured_media":24966,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-24610","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2000","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_grubosc-blatu-12mm","12":"pa_nogi-na-kolach","13":"pa_nogi-na-stopach","14":"pa_rozmiar-1000mm","15":"pa_rozmiar-1000x1000mm","16":"pa_rozmiar-1000x100mm","17":"pa_rozmiar-1000x100x100mm","18":"pa_rozmiar-1000x200mm","19":"pa_rozmiar-1000x200x200mm","20":"pa_rozmiar-1000x400x200mm","21":"pa_rozmiar-1000x600mm","22":"pa_rozmiar-1200mm","23":"pa_rozmiar-1200x1000mm","24":"pa_rozmiar-1200x100x100mm","25":"pa_rozmiar-1200x1200mm","26":"pa_rozmiar-1200x200x200mm","27":"pa_rozmiar-1200x400x200mm","28":"pa_rozmiar-1200x800mm","29":"pa_rozmiar-1300x800","30":"pa_rozmiar-1300x800mm","31":"pa_rozmiar-1400x1400mm","32":"pa_rozmiar-1500mm","33":"pa_rozmiar-1500x1000mm","34":"pa_rozmiar-1500x100x100mm","35":"pa_rozmiar-1500x1480mm","36":"pa_rozmiar-1500x200x200mm","37":"pa_rozmiar-1500x400x200mm","38":"pa_rozmiar-1600x1500mm","39":"pa_rozmiar-1770x1000mm","40":"pa_rozmiar-2000mm","41":"pa_rozmiar-2000x1000mm","42":"pa_rozmiar-2000x100x100mm","43":"pa_rozmiar-2000x200x200mm","44":"pa_rozmiar-2000x400x200mm","45":"pa_rozmiar-2170x1200mm","46":"pa_rozmiar-2400x100x100mm","47":"pa_rozmiar-2400x1200mm","48":"pa_rozmiar-2400x200x200mm","49":"pa_rozmiar-2400x400x200mm","50":"pa_rozmiar-2630x1770mm","51":"pa_rozmiar-2670x1600mm","52":"pa_rozmiar-3000x100x100mm","53":"pa_rozmiar-3000x1480mm","54":"pa_rozmiar-3000x200x200mm","55":"pa_rozmiar-3000x400x200mm","56":"pa_rozmiar-3030x2170mm","57":"pa_rozmiar-3200x1500mm","58":"pa_rozmiar-4000x2670mm","59":"pa_rozmiar-600x100x100mm","60":"pa_rozmiar-600x200x200mm","61":"pa_rozmiar-600x400x200mm","62":"pa_rozmiar-600x600mm","63":"pa_rozmiar-800x100x100mm","64":"pa_rozmiar-800x200x200mm","65":"pa_rozmiar-800x400x200mm","66":"pa_rozmiar-800x800mm","67":"pa_seria-smart12","68":"pa_siatka-100x100mm","69":"pa_siatka-diagonalna","70":"pa_system-fi16","71":"pa_system-fi28","72":"pa_tolerancja-plaskosci-03-mm","73":"pa_wozek-2x-wozek-narzedziowy-l-z-szufladami","74":"pa_wymiar-stolu-2000x1000","76":"first","77":"instock","78":"sale","79":"taxable","80":"shipping-taxable","81":"purchasable","82":"product-type-variable","83":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product\/24610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/comments?post=24610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/media\/24966"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/media?parent=24610"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_brand?post=24610"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_cat?post=24610"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_tag?post=24610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}