﻿{"id":24598,"date":"2025-08-29T10:58:27","date_gmt":"2025-08-29T08:58:27","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=24598"},"modified":"2026-06-30T14:47:38","modified_gmt":"2026-06-30T12:47:38","slug":"mesa-de-soldadura-smart-12-mm-2000-x-1000-mm-juego-de-herramientas-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_co\/p\/conjuntos-promocionales\/mesa-de-soldadura-smart-12-mm-2000-x-1000-mm-juego-de-herramientas-m\/","title":{"rendered":"Mesa de soldadura SMART 12 mm \u2013 2000 x 1000 mm + juego de herramientas M"},"content":{"rendered":"<p style=\"text-align: left;\" class=\" translation-block\"><b>La mesa de soldadura GPPH SMART 12 con unas dimensiones de 2000\u00d71000 mm<\/b> es una soluci\u00f3n econ\u00f3mica dise\u00f1ada para aficionados y talleres peque\u00f1os y medianos. La superficie de trabajo, con un grosor de 12 mm, garantiza estabilidad y seguridad durante el trabajo. El sistema de orificios de 28 mm de di\u00e1metro, distribuidos en una cuadr\u00edcula de 100\u00d7100 mm, permite fijar f\u00e1cilmente accesorios y elementos de construcci\u00f3n. La escala grabada en la superficie facilita el posicionamiento preciso de las piezas que se est\u00e1n trabajando. La mesa se caracteriza por tener menos nervaduras en comparaci\u00f3n con los modelos profesionales, lo que la hace m\u00e1s ligera y m\u00f3vil, manteniendo al mismo tiempo la resistencia adecuada.<\/p>\n<p style=\"text-align: left;\">Juego de herramientas de tama\u00f1o mediano, ideal para proyectos de soldadura m\u00e1s complejos. Contiene un juego cuidadosamente seleccionado de pinzas, escuadras de sujeci\u00f3n, trinquetes y elementos de posicionamiento, que permiten una fijaci\u00f3n precisa y estable de las piezas. Gracias a las bandejas m\u00f3viles y al soporte para soplete, el trabajo resulta m\u00e1s ergon\u00f3mico y ordenado. La elecci\u00f3n ideal para talleres que necesitan herramientas s\u00f3lidas y vers\u00e1tiles en un formato compacto.<\/p>\n<table class=\"aligncenter\" border=\"0\" width=\"462\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"304\" \/>\n<col width=\"158\" \/><\/colgroup>\n<tbody>\n<tr>\n<td class=\"xl69\" width=\"304\" height=\"31\"><strong>SET M<\/strong><\/td>\n<td class=\"xl68\" width=\"158\"><strong>Total: 64<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Torniquetes sujetadores<\/td>\n<td class=\"xl67\">8<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Tornillo de apriete con palanca de acci\u00f3n r\u00e1pida<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete 150<\/td>\n<td class=\"xl67\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete 225<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete 260<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Trinquete exc\u00e9ntrico \u00d8 100<\/td>\n<td class=\"xl67\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo plano 275\u00d7150<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo plano 320\u00d7150<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Escuadra plana 350\u00d7250<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 75\u00d775<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 75\u00d7185<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 125\u00d7185<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 185\u00d7175<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 200\u00d7200<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 300\u00d7190 (derecho)<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">\u00c1ngulo 300\u00d7190 (izquierdo)<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Escuadra de sujeci\u00f3n 200x300x150<\/td>\n<td class=\"xl67\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Perno de sujeci\u00f3n de montaje r\u00e1pido<\/td>\n<td class=\"xl67\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Posicionamiento pin<\/td>\n<td class=\"xl67\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Soporte para pistolas y antorchas de soldadura<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Estante m\u00f3vil para pernos M<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Estante m\u00f3vil para sargentos M<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl66\" height=\"31\">Estante m\u00f3vil plana M<\/td>\n<td class=\"xl67\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>","protected":false},"excerpt":{"rendered":"<p>Mesa de soldadura SMART 12 mm \u2013 2000 x 1000 mm + juego de herramientas M<\/p>","protected":false},"featured_media":24653,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-24598","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2000","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_grubosc-blatu-12mm","12":"pa_nogi-na-kolach","13":"pa_nogi-na-stopach","14":"pa_rozmiar-2000x1000mm","15":"pa_seria-smart12","16":"pa_siatka-100x100mm","17":"pa_siatka-diagonalna","18":"pa_system-fi16","19":"pa_system-fi28","20":"pa_tolerancja-plaskosci-03-mm","21":"pa_wymiar-stolu-2000x1000","23":"first","24":"instock","25":"sale","26":"taxable","27":"shipping-taxable","28":"purchasable","29":"product-type-variable","30":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product\/24598","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/comments?post=24598"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/media\/24653"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/media?parent=24598"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_brand?post=24598"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_cat?post=24598"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_co\/wp-json\/wp\/v2\/product_tag?post=24598"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}