﻿{"id":33107,"date":"2026-02-24T14:03:00","date_gmt":"2026-02-24T12:03:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=33107"},"modified":"2026-06-15T08:47:55","modified_gmt":"2026-06-15T06:47:55","slug":"escuadra-de-soldadura-275x400x200-mm-fi16-plus","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_cl\/p\/deposito\/escuadra-de-soldadura-275x400x200-mm-fi16-plus\/","title":{"rendered":"Escuadra de soldadura 275x400x200 mm - \u03c616 - PLUS"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Escuadra de soldadura \u2013 posicionamiento y sujeci\u00f3n precisa de piezas<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Escuadra de soldadura<\/strong> es una herramienta de posicionamiento s\u00f3lida y precisa utilizada en el montaje y la soldadura de piezas de acero sobre mesas de soldadura.<\/p>\n\n\n\n<p>La estructura con dos bases paralelas unidas por soportes verticales permite un posicionamiento estable y preciso de las piezas en \u00e1ngulo recto, lo cual es fundamental al crear estructuras tridimensionales.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS.png\" alt=\"Escuadra de soldadura 275x400x200 mm PLUS\" class=\"wp-image-25169 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS.png 1000w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/09\/S_010_PLUS-64x64.png 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construcci\u00f3n y funcionalidad<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">El brazo lateral de la escuadra est\u00e1 equipado con un <strong>conjunto de orificios de montaje<\/strong> que permite un posicionamiento flexible y la conexi\u00f3n con otras herramientas.<\/p>\n\n\n\n<p class=\" translation-block\">La base inferior cuenta con un <strong>orificio de montaje alargado<\/strong> (ranura) que permite un ajuste suave de la posici\u00f3n y una adaptaci\u00f3n r\u00e1pida durante el trabajo.<\/p>\n\n\n\n<p class=\" translation-block\">La base superior est\u00e1 equipada con <strong>orificios redondos<\/strong>, destinados a una fijaci\u00f3n estable y al trabajo conjunto con otras herramientas.<\/p>\n\n\n\n<p class=\" translation-block\">Gracias al <strong>soporte inclinado<\/strong>, la estructura obtiene mayor rigidez y estabilidad, lo que facilita el posicionamiento preciso de las piezas.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Aplicaci\u00f3n de la escuadra de soldadura<\/strong><\/h3>\n\n\n\n<p>La escuadra de soldadura es ideal para:<br>\u2013 posicionamiento y fijaci\u00f3n de perfiles, tubos y estructuras de acero,<br>\u2013 montaje y control de uniones en \u00e1ngulo recto,<br>\u2013 construcci\u00f3n de marcos y estructuras que requieren alta precisi\u00f3n,<br>\u2013 realizaci\u00f3n de trabajos de soldadura, montaje y cerrajer\u00eda.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compatibilidad con mesas de soldadura<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Cada escuadra de soldadura est\u00e1 disponible en sistemas de orificios de <strong>\u03c616 mm<\/strong> y <strong>\u03c628 mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Seg\u00fan la serie de herramienta seleccionada, se adapta al tipo correspondiente de mesa de soldadura:<br>\u2013 <strong>EXPERT<\/strong> \u2013 para mesas de la serie <strong>EXPERT<\/strong> (tablero de 25 mm) y <strong>XWT<\/strong> con tablero tipo EXPERT,<br>\u2013 <strong>PRO<\/strong> \u2013 para mesas de las series <strong>PRO<\/strong>, <strong>XWT<\/strong> y <strong>MWT<\/strong> con tablero de 15 mm,<br>\u2013 <strong>PLUS<\/strong> \u2013 para mesas de las series <strong>PLUS<\/strong>, <strong>ECO<\/strong>, <strong>DIY<\/strong>, <strong>BASIC<\/strong> y <strong>XWT<\/strong> con tablero de 12 mm y 8 mm.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construcci\u00f3n y materiales<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La escuadra de soldadura est\u00e1 fabricada en <strong>acero estructural de alta calidad S355J2+N<\/strong>, caracterizado por su gran resistencia a la deformaci\u00f3n y a las cargas prolongadas en el taller.<\/p>\n\n\n\n<p>Cada superficie de trabajo est\u00e1 cuidadosamente mecanizada, lo que garantiza un ajuste perfecto y una colocaci\u00f3n repetible.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Calidad de fabricaci\u00f3n<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Cada componente se somete a un <strong>control de calidad<\/strong> que garantiza el m\u00e1s alto nivel de fabricaci\u00f3n, precisi\u00f3n dimensional y fiabilidad en el uso diario.<\/p>\n\n\n\n<p class=\" translation-block\">El producto se fabrica en <strong>Polonia<\/strong> con materiales que cumplen las normas de calidad para aceros estructurales, constituyendo una herramienta duradera y precisa para aplicaciones de soldadura profesional.<\/p>","protected":false},"excerpt":{"rendered":"<p>Escuadra de soldadura 275x400x200 mm<\/p>","protected":false},"featured_media":25169,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[438,441],"product_tag":[],"class_list":{"0":"post-33107","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-magazyn","7":"product_cat-narzedzia-przestrzenne","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-plus","11":"pa_srednica-otworow-28-lub-16","12":"pa_system-fi16","13":"pa_typ-narzedzia-przestrzenne","14":"pa_wymiar-narzedzia-275x400x200mm","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable","23":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product\/33107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/comments?post=33107"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/media\/25169"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/media?parent=33107"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_brand?post=33107"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_cat?post=33107"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_tag?post=33107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}