﻿{"id":24607,"date":"2025-08-29T11:32:18","date_gmt":"2025-08-29T09:32:18","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=24607"},"modified":"2026-06-13T12:05:40","modified_gmt":"2026-06-13T10:05:40","slug":"mesa-de-soldadura-smart-12-mm-2000-x-1000-mm-juego-de-herramientas-2xl","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_cl\/p\/conjuntos-promocionales\/mesa-de-soldadura-smart-12-mm-2000-x-1000-mm-juego-de-herramientas-2xl\/","title":{"rendered":"Mesa de soldadura SMART 12 mm \u2013 2000 x 1000 mm + juego de herramientas 2XL"},"content":{"rendered":"<p class=\" translation-block\"><b>La mesa de soldadura GPPH SMART 12 con unas dimensiones de 2000\u00d71000 mm<\/b> es una soluci\u00f3n econ\u00f3mica dise\u00f1ada para aficionados y talleres peque\u00f1os y medianos. La superficie de trabajo, con un grosor de 12 mm, garantiza estabilidad y seguridad durante el trabajo. El sistema de orificios de 28 mm de di\u00e1metro, distribuidos en una cuadr\u00edcula de 100\u00d7100 mm, permite fijar f\u00e1cilmente accesorios y elementos de construcci\u00f3n. La escala grabada en la superficie facilita el posicionamiento preciso de las piezas que se est\u00e1n trabajando. La mesa se caracteriza por tener menos nervaduras en comparaci\u00f3n con los modelos profesionales, lo que la hace m\u00e1s ligera y m\u00f3vil, manteniendo al mismo tiempo la resistencia adecuada.<\/p>\n<p style=\"text-align: left;\">Juego completo de herramientas para los trabajos de soldadura m\u00e1s exigentes. Incluye una amplia gama de pinzas, escuadras de sujeci\u00f3n, trinquetes, adaptadores y extensiones, as\u00ed como estantes m\u00f3viles y un carro de herramientas en tama\u00f1o L o M. Gracias a la variedad de herramientas, permite un control total del proceso de fijaci\u00f3n y posicionamiento de las piezas en la mesa de soldadura. Ideal para puestos de producci\u00f3n avanzados y talleres con gran volumen de trabajo.<\/p>\n<table class=\"aligncenter\" border=\"0\" width=\"588\" cellspacing=\"0\" cellpadding=\"0\">\n<colgroup>\n<col width=\"452\" \/>\n<col width=\"136\" \/><\/colgroup>\n<tbody>\n<tr>\n<td class=\"xl65\" width=\"452\" height=\"31\"><strong>SET 2XL<\/strong><\/td>\n<td class=\"xl66\" width=\"136\"><strong>Total: 190<\/strong><\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Torniquetes sujetadores<\/td>\n<td class=\"xl67\" align=\"right\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Tornillo de apriete con palanca de acci\u00f3n r\u00e1pida<\/td>\n<td class=\"xl67\" align=\"right\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Tornillo de apriete ajustable<\/td>\n<td class=\"xl67\" align=\"right\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"31\">Tornillo de apriete ajustable con palanca de acci\u00f3n r\u00e1pida<\/td>\n<td class=\"xl67\" align=\"right\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Tornillo de apriete con palanca de acci\u00f3n r\u00e1pida<\/td>\n<td class=\"xl67\" align=\"right\">5<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Mango de abrazadera de tubo<\/td>\n<td class=\"xl67\" align=\"right\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Abrazadera angular para tubos H=330 L=245, 45\u00b0<\/td>\n<td class=\"xl67\" align=\"right\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Abrazadera angular para tubos H=330 L=245, 45\u00b0<\/td>\n<td class=\"xl67\" align=\"right\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Abrazadera tubular H=330 L=245, 180\u00b0<\/td>\n<td class=\"xl67\" align=\"right\">14<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Trinquete 150<\/td>\n<td class=\"xl67\" align=\"right\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Trinquete 225<\/td>\n<td class=\"xl67\" align=\"right\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Trinquete 260<\/td>\n<td class=\"xl67\" align=\"right\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Trinquete 500<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra angular<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Trinquete exc\u00e9ntrico \u00d8 100<\/td>\n<td class=\"xl67\" align=\"right\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Placa adaptadora 150\u00d7150<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Placa adaptadora 200\u00d7150<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo plano 275\u00d7150<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo plano 320\u00d7150<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra plana 350\u00d7250<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 75\u00d775<\/td>\n<td class=\"xl67\" align=\"right\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 75\u00d7185<\/td>\n<td class=\"xl67\" align=\"right\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 125\u00d7185<\/td>\n<td class=\"xl67\" align=\"right\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 185\u00d7175<\/td>\n<td class=\"xl67\" align=\"right\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 200\u00d7200<\/td>\n<td class=\"xl67\" align=\"right\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 300\u00d7190 (derecho)<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 300\u00d7190 (izquierdo)<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 450\u00d7250 (derecho)<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">\u00c1ngulo 450\u00d7250 (izquierdo)<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra de sujeci\u00f3n 275x500x175x100 (derecha)<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra de sujeci\u00f3n 275x500x175x100 (izquierda)<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra de sujeci\u00f3n 200x300x150<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra de sujeci\u00f3n 275x400x200<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra de sujeci\u00f3n 350x500x250<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra angular espacial 180x260x225 (derecha)<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Escuadra angular espacial 180x260x225 (izquierda)<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Perno de sujeci\u00f3n de montaje r\u00e1pido<\/td>\n<td class=\"xl67\" align=\"right\">20<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Posicionamiento pin<\/td>\n<td class=\"xl67\" align=\"right\">20<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Soporte para pistolas y antorchas de soldadura<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Extensi\u00f3n 1000\u00d7100<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Extensi\u00f3n 1000\u00d7200<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Bloque multiusos<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Estante m\u00f3vil para pernos M<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Estante m\u00f3vil para sargentos M<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Estante m\u00f3vil plana M<\/td>\n<td class=\"xl67\" align=\"right\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Estante m\u00f3vil MIX<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Estante m\u00f3vil para documentos<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"xl67\" height=\"29\">Carro de herramientas L o M<\/td>\n<td class=\"xl67\" align=\"right\">1<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">","protected":false},"excerpt":{"rendered":"<p>Mesa de soldadura SMART 12 mm \u2013 2000 x 1000 mm + juego de herramientas 2XL<\/p>","protected":false},"featured_media":24815,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[460,616],"product_tag":[],"class_list":{"0":"post-24607","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zestawy-promocyjne","7":"product_cat-super-promocje","8":"product_shipping_class-stol-spawalniczy-2000","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-12-mm","11":"pa_grubosc-blatu-12mm","12":"pa_nogi-na-kolach","13":"pa_nogi-na-stopach","14":"pa_rozmiar-2000x1000mm","15":"pa_seria-smart12","16":"pa_siatka-100x100mm","17":"pa_siatka-diagonalna","18":"pa_system-fi16","19":"pa_system-fi28","20":"pa_tolerancja-plaskosci-03-mm","21":"pa_wozek-wozek-narzedziowy-l","22":"pa_wozek-wozek-narzedziowy-m","23":"pa_wymiar-stolu-2000x1000","25":"first","26":"instock","27":"sale","28":"taxable","29":"shipping-taxable","30":"purchasable","31":"product-type-variable","32":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product\/24607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/comments?post=24607"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/media\/24815"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/media?parent=24607"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_brand?post=24607"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_cat?post=24607"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_tag?post=24607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}