﻿{"id":14254,"date":"2022-12-20T17:52:00","date_gmt":"2022-12-20T15:52:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stol-spawalniczy-pro-2400-x-1200-mm"},"modified":"2026-06-15T09:04:34","modified_gmt":"2026-06-15T07:04:34","slug":"mesa-de-soldadura-pro-2400-x-1200-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_cl\/p\/mesas-de-soldadura\/pro\/mesa-de-soldadura-pro-2400-x-1200-mm\/","title":{"rendered":"Mesa de soldadura PRO 15 mm \u2013 2400x1200 mm"},"content":{"rendered":"<p class=\" translation-block\">Las mesas de soldadura las utilizar\u00e1s dondequiera que se requiera <strong>precisi\u00f3n durante la soldadura<\/strong>. Las usar\u00e1s para soldadura manual o robotizada. <strong>Tus construcciones se realizar\u00e1n finalmente con exactitud, sin correcciones innecesarias!<\/strong><\/p>\n<p>Tambi\u00e9n proporciona un trabajo ergon\u00f3mico y r\u00e1pido, manteniendo la precisi\u00f3n y la repetibilidad de las construcciones realizadas.<\/p>\n<p class=\" translation-block\"><strong>\u00a1La mesa de soldadura debe ser plana!<\/strong> Los tableros de las mesas PRO, con un espesor de 15 mm, cuentan con <strong>un denso nervado<\/strong>, lo que garantiza una superficie de trabajo perfectamente plana. Una mesa de dimensiones 2400x1200 mm tiene 2 nervaduras longitudinales y 5 nervaduras transversales. La <strong>estructura maciza y r\u00edgida del tablero<\/strong> garantiza la m\u00e1xima estabilidad durante el uso y protecci\u00f3n contra deformaciones. La tolerancia de planitud de toda la superficie de la mesa es \u2264<strong>0,15<\/strong><strong> mm*<\/strong>.<\/p>\n<table class=\"description_table--thickness_and_ribbing\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/BLAT_PRO.jpg\" alt=\"Tablero de mesa de soldadura\" width=\"500\" height=\"500\" \/><\/td>\n<td><img decoding=\"async\" class=\"mh-500\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/stoly\/ozebrowanie\/ozebrowanie_2400x1200.jpg\" alt=\"Reforcements de mesa 2400x1200mm\" width=\"500\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a1T\u00fa decides! <\/strong><\/p>\n<table class=\"descriptionSystemsTable\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/100x100_fi28.jpg\" alt=\"Malla 100\u00d7100\u202fmm, sistema fi28\" width=\"500\" height=\"188\" \/><\/td>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/100x100_fi16.jpg\" alt=\"Malla 100 x 100 mm, sistema fi16\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/diagonal_fi28.jpg\" alt=\"Malla diagonal, sistema fi28\" width=\"500\" height=\"188\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/diagonal_fi16.jpg\" alt=\"Malla diagonal, sistema fi28\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/50x50_fi16.jpg\" alt=\"Malla de 50 x 50 mm, sistema fi16\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\" translation-block\">Los orificios <strong>fresados y biselados<\/strong> en la superficie de la mesa facilitan el montaje y desmontaje de las herramientas durante el trabajo, gracias al ajuste perfecto de los orificios a las herramientas. Esto tambi\u00e9n contribuye a reducir su desgaste, ya que no es necesario aplicar mucha fuerza para montarlas y desmontarlas. \u00a1Este dise\u00f1o es la mejor soluci\u00f3n disponible en el mercado de mesas de soldadura! La tolerancia de fabricaci\u00f3n de los orificios de la mesa de soldadura es de <strong>\u00b10,05 mm<\/strong>.<\/p>\n<p class=\" translation-block\">La\u202f<strong>graduaci\u00f3n grabada<\/strong> de la superficie de la mesa consiste en l\u00edneas verticales y horizontales en la malla de 100\u00d7100\u202fmm. Sirve como punto de referencia al colocar la construcci\u00f3n y durante el montaje de herramientas. Con instrumentos de medici\u00f3n, puedes ajustar correctamente tu construcci\u00f3n para obtener la dimensi\u00f3n necesaria.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/grawerowana_podzialka.jpg\" alt=\"Escala grabada en la mesa PRO\" width=\"1000\" height=\"500\" \/><\/p>\n<p>Las patas de las mesas de soldadura PRO, fabricadas con perfil de 100x100 mm, tienen una capacidad de carga de 1000 kg\/pata. En el caso de la dimensi\u00f3n 3000x1480 mm, que tiene 8 patas, se obtiene una capacidad m\u00e1xima de carga de 8 000 kg.<\/p>\n<p>Tienes la elecci\u00f3n: pata con pie o con rueda\u202f\u2013 comprueba cu\u00e1l ser\u00e1 mejor para ti.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/nosnosc_nogi_PRO.jpg\" alt=\"Capacidad de carga de las patas de la mesa PRO\" width=\"500\" height=\"500\" \/><\/p>\n<p>Para trabajar con las mesas de soldadura de la serie PRO, utilice las herramientas fresadas PRO. Con ellas, podr\u00e1 realizar con precisi\u00f3n cualquier estructura plana en 2D y espacial en 3D. \u00a1Y todo ello en mucho menos tiempo!<\/p>\n<p>*siempre que la mesa est\u00e9 correctamente nivelada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sto\u0142y Spawalnicze wykorzystasz wsz\u0119dzie tam, gdzie potrzebna jest precyzja podczas spawania. U\u017cyjesz go do spawania manualnego lub zrobotyzowanego. Twoje konstrukcje nareszcie b\u0119d\u0105 wykonane dok\u0142adnie, bez zb\u0119dnego poprawiania! Zapewnia on tak\u017ce ergonomiczn\u0105 i szybk\u0105 prac\u0119 przy zachowaniu precyzji oraz powtarzalno\u015b\u0107 wykonywanych konstrukcji. St\u00f3\u0142 Spawalniczy musi by\u0107 p\u0142aski! Blaty Sto\u0142\u00f3w PRO, maj\u0105ce grubo\u015b\u0107 15mm, posiadaj\u0105 g\u0119ste o\u017cebrowanie, [&hellip;]<\/p>","protected":false},"featured_media":27898,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[425,68,110,85],"product_tag":[],"class_list":{"0":"post-14254","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pro","7":"product_cat-stoly-spawalnicze","8":"product_cat-2400x1200-mm","9":"product_cat-tradycyjne","10":"product_shipping_class-stol-spawalniczy-2400","11":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","12":"pa_grubosc-blatu-15mm","13":"pa_nogi-na-kolach","14":"pa_nogi-na-stopach","15":"pa_nosnosc-1000kg-noga","16":"pa_otwory-frezowane-i-fazowane","17":"pa_profil-nog-100x100x4-mm","18":"pa_rozmiar-2400x1200mm","19":"pa_seria-pro","20":"pa_siatka-100x100mm","21":"pa_siatka-50x50mm","22":"pa_siatka-diagonalna","23":"pa_system-fi16","24":"pa_system-fi28","25":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","26":"pa_tolerancja-wykonania-otworow-005-mm","27":"pa_wzmocnienie-zebrami-tak","29":"first","30":"instock","31":"sale","32":"taxable","33":"shipping-taxable","34":"purchasable","35":"product-type-variable","36":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product\/14254","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/comments?post=14254"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/media\/27898"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/media?parent=14254"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_brand?post=14254"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_cat?post=14254"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_cl\/wp-json\/wp\/v2\/product_tag?post=14254"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}