﻿{"id":32908,"date":"2026-02-24T12:13:00","date_gmt":"2026-02-24T10:13:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=32908"},"modified":"2026-06-15T08:48:37","modified_gmt":"2026-06-15T06:48:37","slug":"extension-1000x100mm-fi16-pro-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_ar\/p\/deposito\/ampliacion-de-superficie\/extension-1000x100mm-fi16-pro-m\/","title":{"rendered":"Extensi\u00f3n 1000x100 mm - \u03c616 - PRO"},"content":{"rendered":"<p>Extensi\u00f3n de 1000 x 100 mm: herramienta destinada a la extensi\u00f3n de la superficie de trabajo de la mesa de soldadura, manteniendo su funcionalidad, ya que, al igual que la superficie de la mesa, cuenta con una rejilla y orificios de montaje.<\/p>\n<p>La extensi\u00f3n de 1000 x 100 mm est\u00e1 disponible en las siguientes variantes:<\/p>\n<ul>\n<li>sistema de orificios \u03c628 mm, rejilla de orificios 100x100 mm, grosor 25 mm \u2013 serie EXPERT<\/li>\n<li>sistema de orificios \u03c616 mm, malla de orificios 100x100 mm, grosor 15 mm \u2013 serie PRO<\/li>\n<li>sistema de orificios \u03c628 mm, malla de orificios 100x100 mm, grosor 15 mm \u2013 serie PRO<\/li>\n<li>sistema de orificios \u03c616 mm, malla de orificios 100x100 mm, grosor 11 mm \u2013 serie PLUS<\/li>\n<li>sistema de orificios \u03c628 mm, malla de orificios 100x100 mm, grosor 11 mm \u2013 serie PLUS<\/li>\n<li>sistema de orificios \u03c616 mm, malla de orificios 100x100 mm, grosor 8 mm \u2013 serie ECO<\/li>\n<li>sistema de orificios \u03c628 mm, malla de orificios 100x100 mm, grosor 8 mm \u2013 serie ECO<\/li>\n<\/ul>\n<p>Las extensiones se pueden utilizar tanto en posici\u00f3n vertical, como base para fijar herramientas en la soldadura de estructuras espaciales, como en posici\u00f3n horizontal, para aumentar la superficie de trabajo de la mesa de soldadura.<\/p>\n<p>La extensi\u00f3n 1000\u00d7100 de la serie EXPERT se puede utilizar con las mesas de soldadura de la serie EXPERT.<\/p>\n<p>La extensi\u00f3n 1000\u00d7100 de la serie de herramientas PRO se puede utilizar para las mesas de soldadura de la serie PRO, XWT con tablero PRO y tambi\u00e9n para las mesas de soldadura modulares.<\/p>\n<p>La extensi\u00f3n 1000\u00d7100 de la serie de herramientas PLUS se puede utilizar con las mesas de soldadura de las series PLUS, ECO, BASIC y XWT con tablero PLUS.<\/p>","protected":false},"excerpt":{"rendered":"<p>La extensi\u00f3n de 1000 x 100 mm es una herramienta dise\u00f1ada para ampliar la superficie de trabajo de la mesa de soldadura, manteniendo su funcionalidad, ya que, al igual que la superficie de la mesa, cuenta con una rejilla y orificios de montaje.<\/p>","protected":false},"featured_media":13832,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[445,438],"product_tag":[],"class_list":{"0":"post-32908","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zwiekszenie-powierzchni","7":"product_cat-magazyn","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-8mm-11mm-15mm-25mm","10":"pa_rozmiar-1000x100mm","11":"pa_seria-pro","12":"pa_siatka-100x100mm","13":"pa_srednica-otworow-28-lub-16","14":"pa_system-fi16","15":"pa_typ-narzedzia-kostki-i-przedluzenia","16":"pa_wymiar-narzedzia-1000x100mm","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product\/32908","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/comments?post=32908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/media\/13832"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/media?parent=32908"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product_brand?post=32908"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product_cat?post=32908"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product_tag?post=32908"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}