﻿{"id":16473,"date":"2024-04-11T14:49:00","date_gmt":"2024-04-11T12:49:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stol-spawalniczy-expert-1500-x-1000-mm"},"modified":"2026-06-15T08:56:36","modified_gmt":"2026-06-15T06:56:36","slug":"mesa-de-soldadura-expert-1500-x-1000-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/es_ar\/p\/mesas-de-soldadura\/expert\/mesa-de-soldadura-expert-1500-x-1000-mm\/","title":{"rendered":"Mesa de soldadura EXPERT 25mm \u2013 1500x1000mm"},"content":{"rendered":"<p class=\" translation-block\">Las mesas de soldadura las utilizar\u00e1s dondequiera que se requiera <strong>precisi\u00f3n durante la soldadura<\/strong>. Las usar\u00e1s para soldadura manual o robotizada. <strong>Tus construcciones se realizar\u00e1n finalmente con exactitud, sin correcciones innecesarias!<\/strong><\/p>\n<p>Tambi\u00e9n proporciona un trabajo ergon\u00f3mico y r\u00e1pido, manteniendo la precisi\u00f3n y la repetibilidad de las construcciones realizadas.<\/p>\n<p class=\" translation-block\"><strong>\u00a1La mesa de soldadura debe ser plana!<\/strong> Los tableros de las mesas EXPERT, con un espesor de 25 mm, cuentan con <strong>un denso nervado<\/strong>, lo que garantiza una superficie de trabajo perfectamente plana. Una mesa de dimensiones 1500x1000 mm tiene 2 nervaduras longitudinales y 3 nervaduras transversales. La <strong>estructura maciza y r\u00edgida del tablero<\/strong> garantiza la m\u00e1xima estabilidad durante el uso y protecci\u00f3n contra deformaciones. La tolerancia de planitud de toda la superficie de la mesa es \u2264<strong>0,15<\/strong><strong> mm*<\/strong>.<\/p>\n<table class=\"description_table--thickness_and_ribbing\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/BLAT_EXPERT.jpg\" alt=\"Superficie de la mesa de soldadura\u202fEXPERT\" width=\"500\" height=\"500\" \/><\/td>\n<td><img decoding=\"async\" class=\"mh-500\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/stoly\/ozebrowanie\/ozebrowanie_1500x1000.jpg\" alt=\"Nerviado de la mesa\u202f1200\u00d71200\u202fmm\" width=\"500\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a1T\u00fa decides! <\/strong><\/p>\n<table class=\"descriptionSystemsTable\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/100x100_fi28.jpg\" alt=\"Malla 100\u00d7100\u202fmm, sistema fi28\" width=\"500\" height=\"188\" \/><\/td>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/diagonal_fi28.jpg\" alt=\"Malla diagonal, sistema fi28\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\" translation-block\">Los orificios <strong>fresados y biselados<\/strong> en la superficie de la mesa facilitan el montaje y desmontaje de las herramientas durante el trabajo, gracias al ajuste perfecto de los orificios a las herramientas. Esto tambi\u00e9n contribuye a reducir su desgaste, ya que no es necesario aplicar mucha fuerza para montarlas y desmontarlas. \u00a1Este dise\u00f1o es la mejor soluci\u00f3n disponible en el mercado de mesas de soldadura! La tolerancia de fabricaci\u00f3n de los orificios de la mesa de soldadura es de <strong>\u00b10,05 mm<\/strong>.<\/p>\n<p class=\" translation-block\">La\u202f<strong>graduaci\u00f3n grabada<\/strong> de la superficie de la mesa consiste en l\u00edneas verticales y horizontales en la malla de 100\u00d7100\u202fmm. Sirve como punto de referencia al colocar la construcci\u00f3n y durante el montaje de herramientas. Con instrumentos de medici\u00f3n, puedes ajustar correctamente tu construcci\u00f3n para obtener la dimensi\u00f3n necesaria.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/grawerowana_podzialka.jpg\" alt=\"graduaci\u00f3n grabada de la mesa\u202fEXPERT\" width=\"1000\" height=\"500\" \/><\/p>\n<p>Las patas de las mesas de soldadura EXPERT, fabricadas con perfil de 120x120 mm, tienen una capacidad de carga de 1250 kg por pata. En el caso de la dimensi\u00f3n 3000x1480 mm, que cuenta con 8 patas, se obtiene una capacidad m\u00e1xima de carga de 10 000 kg.<\/p>\n<p>Tienes la elecci\u00f3n: pata con pie o con rueda\u202f\u2013 comprueba cu\u00e1l ser\u00e1 mejor para ti.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/nosnosc_nogi_EXPERT.jpg\" alt=\"Capacidad de carga de las patas de la mesa\u202fEXPERT\" width=\"500\" height=\"500\" \/><\/p>\n<p>Para el trabajo en mesas de soldadura de la serie EXPERT utilizar\u00e1s herramientas fresadas EXPERT. Gracias a ellas ejecutar\u00e1s con precisi\u00f3n cada construcci\u00f3n plana en 2D y espacial en 3D. \u00a1Y todo esto en mucho menos tiempo!<\/p>\n<p>*siempre que la mesa est\u00e9 correctamente nivelada.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sto\u0142y Spawalnicze wykorzystasz wsz\u0119dzie tam, gdzie potrzebna jest precyzja podczas spawania. U\u017cyjesz go do spawania manualnego lub zrobotyzowanego. Twoje konstrukcje nareszcie b\u0119d\u0105 wykonane dok\u0142adnie, bez zb\u0119dnego poprawiania! Zapewnia on tak\u017ce ergonomiczn\u0105 i szybk\u0105 prac\u0119 przy zachowaniu precyzji oraz powtarzalno\u015b\u0107 wykonywanych konstrukcji. St\u00f3\u0142 Spawalniczy musi by\u0107 p\u0142aski! Blaty Sto\u0142\u00f3w EXPERT, maj\u0105ce grubo\u015b\u0107 25mm, posiadaj\u0105 g\u0119ste o\u017cebrowanie, [&hellip;]<\/p>","protected":false},"featured_media":27717,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[424,68,113,85],"product_tag":[],"class_list":{"0":"post-16473","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-expert","7":"product_cat-stoly-spawalnicze","8":"product_cat-1500x1000-mm","9":"product_cat-tradycyjne","10":"product_shipping_class-stol-spawalniczy-2000","11":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","12":"pa_grubosc-blatu-25-mm","13":"pa_nogi-na-kolach","14":"pa_nogi-na-stopach","15":"pa_nosnosc-1250kg-noga","16":"pa_otwory-frezowane-i-fazowane","17":"pa_profil-nog-120x120x4-mm","18":"pa_rozmiar-1500x1000mm","19":"pa_seria-expert","20":"pa_siatka-100x100mm","21":"pa_siatka-diagonalna","22":"pa_system-fi28","23":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","24":"pa_tolerancja-wykonania-otworow-005-mm","25":"pa_wzmocnienie-zebrami-tak","27":"first","28":"instock","29":"sale","30":"taxable","31":"shipping-taxable","32":"purchasable","33":"product-type-variable","34":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product\/16473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/comments?post=16473"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/media\/27717"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/media?parent=16473"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product_brand?post=16473"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product_cat?post=16473"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/es_ar\/wp-json\/wp\/v2\/product_tag?post=16473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}