﻿{"id":38583,"date":"2026-07-14T09:45:53","date_gmt":"2026-07-14T07:45:53","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=38583"},"modified":"2026-07-14T10:33:44","modified_gmt":"2026-07-14T08:33:44","slug":"outlet-table-de-soudage-smart-15mm-2400x1200mm-systeme-%cf%8628-grille-100x100mm-w67","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/dz\/p\/magasin-dusine\/outlet-table-de-soudage-smart-15mm-2400x1200mm-systeme-%cf%8628-grille-100x100mm-w67\/","title":{"rendered":"[OUTLET] Table de soudage SMART 15 mm 2400x1200 mm \u2013 syst\u00e8me \u03c628, grille 100x100 mm"},"content":{"rendered":"<p>Les tables de soudage sont l\u2019outil id\u00e9al partout o\u00f9 pr\u00e9cision et r\u00e9p\u00e9tabilit\u00e9 sont requises. Le plateau de 15\u202fmm d\u2019\u00e9paisseur, dot\u00e9 d\u2019un nervurage dense, assure plan\u00e9it\u00e9 et stabilit\u00e9 m\u00eame avec des structures lourdes. Le syst\u00e8me de trous frais\u00e9s et chanfrein\u00e9s \u03c628 dans une grille de 100\u00d7100\u202fmm facilite le montage des outils, acc\u00e9l\u00e9rant et simplifiant le travail.<\/p>\n<p><strong>Caract\u00e9ristiques principales de la table :<\/strong><\/p>\n<ul>\n<li>Le plateau de 15\u202fmm d\u2019\u00e9paisseur, dot\u00e9 d\u2019un nervurage dense, garantit une surface de travail parfaitement plane.<\/li>\n<li>Dimensions : 2400\u00d71200 mm, 1 nervure longitudinale et 3 nervures longitudinales assurant la stabilit\u00e9 lors de l\u2019utilisation et la r\u00e9sistance aux d\u00e9formations.<\/li>\n<li>Maille 100 \u00d7 100 mm, syst\u00e8me \u03c628<\/li>\n<\/ul>\n<p>Le plateau est en outre \u00e9quip\u00e9 d\u2019un marquage grav\u00e9 en grille de 100\u00d7100 mm, facilitant le positionnement pr\u00e9cis des structures et le montage des outils, garantissant une grande pr\u00e9cision \u00e0 chaque op\u00e9ration.<\/p>\n<p><strong>Options de pieds :\u00a0<\/strong><\/p>\n<ul>\n<li>Sur pieds fixes \u2013 assurent une grande stabilit\u00e9 et une capacit\u00e9 de charge \u00e9lev\u00e9e.<\/li>\n<li>Sur roulettes \u2013 id\u00e9al pour les travaux n\u00e9cessitant la mobilit\u00e9 de la table.<\/li>\n<\/ul>\n<p>En achetant ce produit, vous pouvez choisir une version avec pieds fixes ou sur roulettes.<\/p>\n<p>Les pieds de la table, fabriqu\u00e9s \u00e0 partir de profils de 60\u00d760 mm, offrent une capacit\u00e9 de charge maximale de 2500 kg. La table reste ainsi stable m\u00eame sous de fortes charges.<\/p>\n<p class=\" translation-block\">En achetant une table outlet, vous d\u00e9clarez avoir <strong>pris connaissance de son \u00e9tat r\u00e9el<\/strong> et <strong>l\u2019accepter sans droit \u00e0 r\u00e9clamation<\/strong>. Conform\u00e9ment \u00e0 l\u2019article 557 \u00a7 1 du Code civil polonais, le vendeur est exon\u00e9r\u00e9 de responsabilit\u00e9 pour vices cach\u00e9s si l\u2019acheteur avait connaissance du d\u00e9faut au moment de la conclusion du contrat.<\/p>\n<p>Vous souhaitez en savoir plus sur les tables de soudage traditionnelles GPPH ? Consultez les informations sur la page d\u00e9di\u00e9e <a href=\"https:\/\/gpph-group.com\/dz\/produits\/table-de-soudage-traditionnelle\/\">tables de soudage traditionnelles.<\/a><a href=\"https:\/\/gpph-group.com\/dz\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0<\/a><\/p>\n<p id=\"defekty\"><strong>ATTENTION : La table pr\u00e9sente un d\u00e9faut :\u00a0<\/strong><\/p>\n<ul>\n<li>Rayures sur le plateau<\/li>\n<li>Chanfreins in\u00e9gaux<\/li>\n<\/ul>\n<p>Les photos des d\u00e9fauts sont pr\u00e9sent\u00e9es ci-dessous.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-1024x683.jpg\" alt=\"[OUTLET] Table de soudage SMART 15 mm 2400x1200 mm \u2013 syst\u00e8me \u03c628, grille 100x100 mm\" class=\"wp-image-38595\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-scaled.jpg\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-1024x683.jpg\" alt=\"[OUTLET] Table de soudage SMART 15 mm 2400x1200 mm \u2013 syst\u00e8me \u03c628, grille 100x100 mm\" class=\"wp-image-38589\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Nous vous invitons \u00e0 le d\u00e9couvrir <a href=\"https:\/\/gpph-group.com\/pl\/p\/stoly-spawalnicze\/2400x1200-mm\/stol-spawalniczy-smart-15-2400-x-1200-mm\/\" target=\"_blank\" rel=\"noopener\">produit \u00e0 part enti\u00e8re<\/a>. L'offre actuelle concerne un exemplaire outlet,<strong> disponible en quantit\u00e9 limit\u00e9e et \u00e0 un prix exceptionnellement attractif.<\/strong> <strong>UWAGA! St\u00f3\u0142 posiada defekt:<\/strong><\/p>\n<ul>\n<li>Rayures sur le plateau<\/li>\n<li>Chanfreins in\u00e9gaux<\/li>\n<\/ul>","protected":false},"featured_media":38586,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168],"product_tag":[],"class_list":{"0":"post-38583","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outlet","7":"product_shipping_class-stol-spawalniczy-2000","8":"pa_nogi-na-kolach","9":"pa_nogi-na-stopach","10":"pa_seria-smart15","11":"pa_siatka-100x100mm","12":"pa_srednica-otworow-364","13":"pa_wymiar-stolu-2400x1200","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product\/38583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/comments?post=38583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/media\/38586"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/media?parent=38583"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_brand?post=38583"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_cat?post=38583"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_tag?post=38583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}