﻿{"id":14979,"date":"2023-01-25T17:19:00","date_gmt":"2023-01-25T15:19:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=modulowy-zestaw-o-duzej-powierzchni-2630x1770-mm"},"modified":"2026-06-10T12:20:55","modified_gmt":"2026-06-10T10:20:55","slug":"ensemble-modulaire-a-grande-surface-2630x1770-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/dz\/p\/tables-de-soudage\/ensemble-modulaire-a-grande-surface-2630x1770-mm\/","title":{"rendered":"Ensemble modulaire de grande surface 2630\u00d71770 mm"},"content":{"rendered":"<p>Ta aukcja dotyczy modu\u0142owego zestawu o du\u017cej powierzchni z p\u0142ytami blatu wykonanymi z materia\u0142u: S355J2+N o wymiarze 2630&#215;1770.<\/p>\n<p>Les ensembles de grande surface sont compos\u00e9s de deux tables modulaires assembl\u00e9es \u00e0 l'aide de raccords. C'est la solution id\u00e9ale pour les constructions spacieuses. Ils sont disponibles en trois dimensions : 2630\u00d71770, 3030\u00d72170, 4000\u00d72670.<\/p>\n<p class=\" translation-block\">Le plateau des tables modulaires est compos\u00e9 de panneaux frais\u00e9s et coulissants d'une \u00e9paisseur de 15 mm. Gr\u00e2ce \u00e0 leur surface r\u00e9glable, vous obtiendrez une plan\u00e9it\u00e9 parfaite. Ils sont r\u00e9alis\u00e9s avec un syst\u00e8me de trous de 28 mm de diam\u00e8tre dispos\u00e9s en grille de 100\u00d7100 mm.\nIls sont dot\u00e9s de trous frais\u00e9s et chanfrein\u00e9s facilitant le montage des outils. Les tables modulaires sont compatibles avec les outils de la s\u00e9rie PRO. De plus, la conception de nos tables modulaires permet d'augmenter le nombre de points de fixation des outils dans les interstices entre les panneaux du plateau, ce qui am\u00e9liore l'ergonomie du travail.<\/p>\n<p class=\" translation-block\">Les tables modulaires sont \u00e9quip\u00e9es de roues avec un pied dans les pieds de la base, avec une <strong>capacit\u00e9 de charge de 250 kg par pied<\/strong>. Les versions extensibles des tables modulaires ont des <strong>supports r\u00e9glables <\/strong>dans les pieds suppl\u00e9mentaires. La hauteur des tables peut \u00eatre r\u00e9gl\u00e9e entre 850 mm et 1150 mm, P=50 mm.<\/p>\n<p class=\" translation-block\">Afin d'obtenir une plus grande surface de travail, les <strong>tables peuvent \u00eatre combin\u00e9es entre elles<\/strong>. En option, vous pouvez \u00e9galement acheter des plaques lat\u00e9rales.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ta aukcja dotyczy modu\u0142owego zestawu o du\u017cej powierzchni z p\u0142ytami blatu wykonanymi z materia\u0142u: S355J2+N o wymiarze 2630&#215;1770. Zestawy o du\u017cej powierzchni to po\u0142\u0105czone ze sob\u0105 za pomoc\u0105 \u0142\u0105cznik\u00f3w dwa roz\u0142o\u017cone sto\u0142y modu\u0142owe. Jest to idealne rozwi\u0105zanie dla konstrukcji przestrzennych. Wyst\u0119puj\u0105 w trzech wersjach wymiarowych: 2630&#215;1770, 3030&#215;2170, 4000&#215;2670. Blat sto\u0142\u00f3w modu\u0142owych sk\u0142ada si\u0119 z frezowanych, [&hellip;]<\/p>","protected":false},"featured_media":14980,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[68,86,81],"product_tag":[],"class_list":{"0":"post-14979","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stoly-spawalnicze","7":"product_cat-modulowe","8":"product_cat-mwt","9":"product_shipping_class-stol-spawalniczy-2400","10":"pa_grubosc-blatu-15mm","11":"pa_nosnosc-250kg-noga","12":"pa_otwory-frezowane-i-fazowane","13":"pa_rozmiar-2630x1770mm","14":"pa_seria-mwt","15":"pa_siatka-100x100mm","16":"pa_system-fi28","18":"first","19":"instock","20":"sale","21":"taxable","22":"shipping-taxable","23":"purchasable","24":"product-type-variable","25":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product\/14979","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/comments?post=14979"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/media\/14980"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/media?parent=14979"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_brand?post=14979"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_cat?post=14979"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_tag?post=14979"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}