﻿{"id":13222,"date":"2022-12-13T15:32:00","date_gmt":"2022-12-13T13:32:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stoper-225"},"modified":"2026-07-14T05:44:47","modified_gmt":"2026-07-14T03:44:47","slug":"butee-225","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/dz\/p\/outils\/plat\/butee-225\/","title":{"rendered":"But\u00e9e 225"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>But\u00e9e - positionnement et limitation pr\u00e9cis des pi\u00e8ces<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>But\u00e9e<\/strong> est un outil auxiliaire pratique con\u00e7u pour le <strong>positionnement, le calage et la limitation des pi\u00e8ces en acier<\/strong> sur la surface de la table de soudage.<br><br>Elle facilite le r\u00e9glage rapide et r\u00e9p\u00e9table des \u00e9l\u00e9ments et acc\u00e9l\u00e8re ainsi la pr\u00e9paration des structures pour le soudage ou le montage.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-1024x1024.png\" alt=\"Stoper PRO 225\" class=\"wp-image-4471 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-1024x1024.png 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-64x64.png 64w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2023\/09\/28_N.005PRO_-Stoper-PRO-225.png 1301w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Construction et fonctionnalit\u00e9<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">But\u00e9e sert de support stable pour les pi\u00e8ces et permet de d\u00e9terminer rapidement leur position sur la table.<br>Elle est \u00e9quip\u00e9e de <strong>trous de montage<\/strong>, gr\u00e2ce auxquels elle peut \u00eatre facilement fix\u00e9e et positionn\u00e9e exactement l\u00e0 o\u00f9 elle est n\u00e9cessaire pendant le travail.<br><br>Cette solution facilite le r\u00e9glage pr\u00e9cis des \u00e9l\u00e9ments avant le soudage et permet de les maintenir dans la position d\u00e9finie.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Syst\u00e8me et compatibilit\u00e9<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Les but\u00e9es sont disponibles en versions adapt\u00e9es \u00e0 diff\u00e9rents syst\u00e8mes de trous.<br><br>La variante <strong>EXPERT<\/strong> est propos\u00e9e uniquement dans le syst\u00e8me <strong>\u03c628 mm<\/strong>, tandis que les s\u00e9ries <strong>PRO, PLUS et ECO<\/strong> sont disponibles dans les syst\u00e8mes <strong>\u03c616 mm<\/strong> et <strong>\u03c628 mm<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">Selon la s\u00e9rie choisie, la but\u00e9e est compatible avec les tables suivantes :<br>- <strong>EXPERT<\/strong> - pour les tables de la s\u00e9rie <strong>EXPERT<\/strong> (plateau de 25 mm) et les tables <strong>XWT<\/strong> avec plateau de type EXPERT,<br>- <strong>PRO<\/strong> - pour les tables des s\u00e9ries <strong>PRO<\/strong>, <strong>XWT<\/strong> et <strong>MWT<\/strong> avec plateau de 15 mm d\u2019\u00e9paisseur,<br>- <strong>PLUS<\/strong> - pour les tables des s\u00e9ries <strong>PLUS<\/strong>, <strong>ECO<\/strong>, <strong>BASIC<\/strong>, <strong>DIY<\/strong> et <strong>XWT<\/strong> avec plateaux de 12 mm et 8 mm d\u2019\u00e9paisseur.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Mat\u00e9riau et fabrication<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">La but\u00e9e est fabriqu\u00e9e en <strong>acier au carbone de haute qualit\u00e9<\/strong>, ce qui assure une grande durabilit\u00e9 et un fonctionnement fiable au quotidien.<br><br>Gr\u00e2ce au contr\u00f4le qualit\u00e9 effectu\u00e9, chaque but\u00e9e r\u00e9pond \u00e0 des normes de fabrication \u00e9lev\u00e9es et garantit une longue dur\u00e9e de vie.<\/p>\n\n\n\n<p class=\" translation-block\">Le produit est <strong>enti\u00e8rement fabriqu\u00e9 en Pologne<\/strong>.<\/p>","protected":false},"excerpt":{"rendered":"<p>But\u00e9e 225 dans le syst\u00e8me est utilis\u00e9e pour le positionnement et le serrage des \u00e9l\u00e9ments soud\u00e9s sur la table de soudage.<\/p>","protected":false},"featured_media":13223,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[103,69],"product_tag":[],"class_list":{"0":"post-13222","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-plaskie","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-expert","11":"pa_seria-plus","12":"pa_seria-pro","13":"pa_srednica-otworow-28-lub-16","14":"pa_system-fi16","15":"pa_system-fi28","16":"pa_typ-narzedzia-plaskie","17":"pa_wymiar-narzedzia-225x50mm","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable","26":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product\/13222","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/comments?post=13222"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/media\/13223"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/media?parent=13222"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_brand?post=13222"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_cat?post=13222"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/dz\/wp-json\/wp\/v2\/product_tag?post=13222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}