﻿{"id":17251,"date":"2024-11-29T16:53:00","date_gmt":"2024-11-29T14:53:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=podpora-spawalnicza-trestle-expert-1000x200x200-mm"},"modified":"2026-06-01T00:03:17","modified_gmt":"2026-05-31T22:03:17","slug":"schweissstuetze-trestle-expert-1000x200x200-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de_ch\/p\/flachenvergroserung\/schweissstutzen\/schweissstuetze-trestle-expert-1000x200x200-mm\/","title":{"rendered":"Schwei\u00dfst\u00fctze TRESTLE EXPERT 1000x200x200 mm"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Schwei\u00dfst\u00fctze TRESTLE - Erweiterung des Arbeitsplatzes und sichere Abst\u00fctzung gro\u00dfer Werkst\u00fccke<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Schwei\u00dfst\u00fctze TRESTLE<\/strong> ist ein Werkzeug, das die Einsatzm\u00f6glichkeiten auf dem Schwei\u00dftisch deutlich erweitert.<\/p>\n\n\n\n<p class=\" translation-block\"><br>Du kannst sie als <strong>Verl\u00e4ngerung der Tischplatte<\/strong> oder als <strong>separate Arbeitsfl\u00e4che<\/strong> verwenden, wenn du mit Werkst\u00fccken arbeitest, die \u00fcber den Rand des Tisches hinausragen oder eine zus\u00e4tzliche Abst\u00fctzung ben\u00f6tigen. So richtest du gr\u00f6\u00dfere Bauteile leichter aus, h\u00e4ltst die Geometrie ein und bereitest Teile zum Schwei\u00dfen vor, ohne provisorische St\u00fctzen einsetzen zu m\u00fcssen.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20.png\" alt=\"Schwei\u00dfst\u00fctze TRESTLE EXPERT auf R\u00e4dern 1000x200x200 mm fi 28 mm diagonales Raster\" class=\"wp-image-27357 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20.png 1000w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/07\/28_DIAG_K_TRESTLE_EXPERT_100x20x20-64x64.png 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Konstruktion und Funktionalit\u00e4t<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Die Auflageplatte hat eine steife, <strong>mit Rippen verst\u00e4rkte<\/strong> Konstruktion, was bei der Arbeit mit schwereren Werkst\u00fccken f\u00fcr eine stabile Abst\u00fctzung sorgt.<br><br>TRESTLE bietet eine solide Basis f\u00fcr Montage und Schwei\u00dfen - du kannst ein Bauteil darauf auflegen, es an das Setup auf dem Tisch anpassen und w\u00e4hrend des gesamten Prozesses in dieser Position halten.<\/p>\n\n\n\n<p class=\" translation-block\">Die St\u00fctze eignet sich ebenfalls hervorragend als <strong>stabile Plattform f\u00fcr Montagearbeiten<\/strong>. Sie erm\u00f6glicht ein komfortables Vormontieren und Anpassen der Bauteile vor dem Schwei\u00dfen, insbesondere wenn du zus\u00e4tzliche Arbeitsfl\u00e4che neben dem Tisch ben\u00f6tigst.<\/p>\n\n\n\n<p class=\" translation-block\">In der Platte befinden sich <strong>Montagebohrungen<\/strong>, die <strong>gefr\u00e4st und angefast<\/strong> sind. Die Werkzeuge sitzen sicher, und die Montage sowie Demontage verl\u00e4uft reibungslos und ohne Verklemmen.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Lochsystem und Arbeitsvarianten<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Die TRESTLE-St\u00fctzen sind in mehreren Ausf\u00fchrungen erh\u00e4ltlich, damit du die passende Variante f\u00fcr deine Anforderungen w\u00e4hlen kannst:<br>- <strong>\u03c616 mm im diagonalen Raster<\/strong> und <strong>\u03c628 mm im diagonalen Raster<\/strong> - Varianten, die sich bei gr\u00f6\u00dferen Konstruktionen bew\u00e4hren, bei denen du h\u00e4ufig au\u00dferhalb der Tischmitte arbeitest,<br>- <strong>\u03c616 mm im 50x50 mm Raster<\/strong> - ein Layout mit engeren Spannpunkten, das die Arbeit bei h\u00e4ufigem Umr\u00fcsten des Arbeitsplatzes erleichtert.<\/p>\n\n\n\n<p>Jede Ausf\u00fchrung erm\u00f6glicht es dir, Werkzeuge und Werkst\u00fccke genau dort bequem zu positionieren, wo du sie brauchst - ganz gleich, ob die St\u00fctze als eigenst\u00e4ndiger Arbeitsplatz genutzt wird oder zusammen mit dem Tisch arbeitet.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Genauigkeit der Platte und der Bohrungen<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Die Schwei\u00dfst\u00fctze wird mit einer Pr\u00e4zision gefertigt, die in der Praxis entscheidend ist:<br>\u2013 <strong>Ebenheitstoleranz der Oberfl\u00e4che \u00fcber die gesamte Fl\u00e4che \u22640,15 mm<\/strong>,<br>wodurch eine gleichm\u00e4\u00dfige Auflage der Bauteile gew\u00e4hrleistet und das Einhalten der erforderlichen Ma\u00dfe w\u00e4hrend der Montage erleichtert wird.<\/p>\n\n\n\n<p class=\" translation-block\">Die Montagebohrungen werden mit hoher Pr\u00e4zision gefertigt:<br>- <strong>Bohrungstoleranz \u00b10,05 mm<\/strong>,<br>- in der Serie <strong>ECO \u00b10,1 mm<\/strong>.<br>Dadurch sitzen Werkzeuge und Stifte gleichm\u00e4\u00dfig, und die Einstellungen sind bei Folgeprojekten reproduzierbar.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Arbeitsma\u00dfskala<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Auf der Platte befindet sich eine <strong>gravierte Skala im 100x100 mm Raster<\/strong>.<br>Sie erleichtert das schnelle Ausrichten der Werkst\u00fccke zueinander, das \u00dcbertragen von Ma\u00dfen und die Lagekontrolle w\u00e4hrend der Montage.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Einsatz in der t\u00e4glichen Arbeit<\/strong><\/h3>\n\n\n\n<p>Die TRESTLE-St\u00fctze bew\u00e4hrt sich besonders bei:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Arbeiten mit langen und schweren Werkst\u00fccken, die eine Abst\u00fctzung au\u00dferhalb des Tisches erfordern,<\/li>\n\n\n\n<li>der Montage von r\u00e4umlichen Konstruktionen, bei denen feste Bezugspunkte wichtig sind,<\/li>\n\n\n\n<li>Erweiterung des Arbeitsplatzes, wenn du mehr Arbeitsfl\u00e4che ben\u00f6tigst, ohne den Tisch zu wechseln,<\/li>\n\n\n\n<li>Montagearbeiten, bei denen die Werkst\u00fccke vor dem Schwei\u00dfen stabil aufliegen m\u00fcssen.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Material und Ausf\u00fchrung<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Die St\u00fctze besteht aus <strong>hochwertigem Stahl<\/strong>, der Langlebigkeit und zuverl\u00e4ssige Leistung im t\u00e4glichen Einsatz gew\u00e4hrleistet.<br>Jedes Exemplar durchl\u00e4uft eine Qualit\u00e4tskontrolle, sodass du ein Werkzeug mit hohem Fertigungsstandard und langer Lebensdauer erh\u00e4ltst.<\/p>","protected":false},"excerpt":{"rendered":"<p>Podpora spawalnicza TRESTLE \u2013 rozszerzenie stanowiska i pewne podparcie du\u017cych detali Podpora spawalnicza TRESTLE to narz\u0119dzie, kt\u00f3re realnie zwi\u0119ksza mo\u017cliwo\u015bci pracy na stole spawalniczym. Mo\u017cesz u\u017cywa\u0107 jej jako przed\u0142u\u017cenia blatu albo jako oddzielnej powierzchni roboczej, kiedy pracujesz z detalami, kt\u00f3re wykraczaj\u0105 poza obrys sto\u0142u lub wymagaj\u0105 dodatkowego podparcia. Dzi\u0119ki temu \u0142atwiej ustawisz wi\u0119ksze elementy, utrzymasz [&hellip;]<\/p>","protected":false},"featured_media":27356,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[170,171],"product_tag":[],"class_list":{"0":"post-17251","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-podpory-spawalnicze","7":"product_cat-zwiekszanie-powierzchni","8":"product_shipping_class-stol-spawalniczy-2000","9":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","10":"pa_grubosc-blatu-25-mm","11":"pa_nogi-na-stopach","12":"pa_nogi-na-kolach","13":"pa_otwory-frezowane-i-fazowane","14":"pa_rozmiar-1000x200x200mm","15":"pa_seria-expert","16":"pa_siatka-diagonalna","17":"pa_system-fi28","18":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","19":"pa_tolerancja-wykonania-otworow-005-mm","20":"pa_wzmocnienie-zebrami-tak","22":"first","23":"instock","24":"sale","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-variable","29":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product\/17251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/comments?post=17251"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/media\/27356"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/media?parent=17251"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_brand?post=17251"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_cat?post=17251"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_tag?post=17251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}