﻿{"id":16056,"date":"2023-05-04T17:51:00","date_gmt":"2023-05-04T15:51:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stol-spawalniczy-pro-inox-1500x1000-mm-z-hydraulicznym-systemem-podnoszenia"},"modified":"2026-06-15T09:02:12","modified_gmt":"2026-06-15T07:02:12","slug":"schweistisch-fur-edelstahl-1500-x-1000-mm-mit-hydraulischem-hebesystem","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de_ch\/p\/schweistische\/angehoben\/schweistisch-fur-edelstahl-1500-x-1000-mm-mit-hydraulischem-hebesystem\/","title":{"rendered":"Schwei\u00dftisch PRO INOX 1500\u00d71000 mm mit hydraulischem Hebesystem"},"content":{"rendered":"<p class=\" translation-block\">Die Schwei\u00dftische GPPH mit hydraulischem Hebesystem sind Spezialtische mit automatischer H\u00f6henverstellung der Tischplatte.<br>Damit erreichen Sie schnell und einfach die ideale Arbeitsh\u00f6he der Tischplatte und sorgen f\u00fcr hohen Arbeitskomfort.<\/p>\n<p>Schwei\u00dftische mit hydraulischem Hebesystem verf\u00fcgen \u00fcber:<\/p>\n<ul>\n<li>\u00dcberlastventil, das das Anheben zu schwerer Lasten verhindert;<\/li>\n<li>Sicherheitsventil, das das Absenken bei Bruch der Hydraulikleitungen stoppt;<\/li>\n<li>Endschalter zum Schutz vor Quetschungen oder Verletzungen des Benutzers.<\/li>\n<\/ul>\n<p class=\" translation-block\">Tische mit einem hydraulischen Hebesystem sind <strong>in der <\/strong>GPPH-Serie<strong> von Schwei\u00dftischen zu <\/strong>finden:<\/p>\n<ul>\n<li><strong>PRO, PLUS <\/strong>und <strong>ECO, <\/strong>die aus dem Stahl S355J2+N hergestellt werden;<\/li>\n<li>PRO INOX und PLUS INOX, die aus rostfreiem Stahl der G\u00fcteklasse 1.4301 hergestellt sind.<\/li>\n<\/ul>\n<p>Jede Serie ist in 4 Gr\u00f6\u00dfen erh\u00e4ltlich.<\/p>\n<p>Jede Tischplatte ist mit \u00d6ffnungen von 28 mm Durchmesser in den Maschenweiten 100\u00d7100 mm und diagonal sowie mit \u00d6ffnungen von 16 mm Durchmesser in den Maschenweiten 50\u00d750 mm, 100\u00d7100 mm und diagonal erh\u00e4ltlich.<\/p>\n<p class=\" translation-block\"><strong>Der Schwei\u00dftisch muss eben sein!<\/strong> Die Platten der PRO-Tische mit einer St\u00e4rke von 15mm verf\u00fcgen \u00fcber eine <strong>dichte Verrippung<\/strong>, was zu einer perfekt ebenen Arbeitsfl\u00e4che f\u00fchrt. <strong>Die massive und steife Unterkonstruktion der Platte<\/strong> des Tisches gew\u00e4hrleistet h\u00f6chste Stabilit\u00e4t bei der Verwendung und sch\u00fctzt vor Verformung. Die Ebenheitstoleranz des Tisches \u00fcber die gesamte Platte betr\u00e4gt <strong>\u22640,3 mm <\/strong><span data-teams=\"true\">(kleiner oder gleich 0,3 mm)<\/span>.<\/p>\n<p class=\" translation-block\"><strong>Gefr\u00e4ste und angefaste<\/strong> Bohrungen in der Platte des Schwei\u00dftisches erm\u00f6glichen eine einfache Montage und Demontage der Spannmittel w\u00e4hrend Ihrer Arbeit, dank der exakten Passung der Bohrungen zu den Werkzeugen. Dies tr\u00e4gt auch zu einem geringeren Verschlei\u00df bei \u2013 f\u00fcr die Montage und Demontage ist keine gro\u00dfe Kraft erforderlich. Diese Ausf\u00fchrung ist die beste der verf\u00fcgbaren L\u00f6sungen auf dem Markt f\u00fcr Schwei\u00dftische! Die Fertigungstoleranz der Bohrungen des Schwei\u00dftisches <span class=\"ui-provider gp b c d e f g h i j k l m n o p q r s t u v w x y z ab ac ae af ag ah ai aj ak\" dir=\"ltr\">betr\u00e4gt <strong>\u2264<\/strong><\/span><strong>0,05 mm <\/strong>(kleiner oder gleich 0,05 mm).<\/p>\n<p class=\" translation-block\"><strong>Schwei\u00dftische  aus  rostfreiem  Edelstahl<\/strong>  der  Serie  INOX  sind  aus  rostfreiem  Edelstahl  der  G\u00fcte  1.4301 gefertigt, der sich durch eine bessere elektrische Leitf\u00e4higkeit als gew\u00f6hnlicher Stahl auszeichnet \u2013 elektrischer Widerstand bei 20 \u00b0C = 0,73 (\u03a9 mm\u00b2)\/m.  Sie k\u00f6nnen sie \u00fcberall dort einsetzen, wo pr\u00e4zises Schwei\u00dfen von Edelstahl erforderlich ist.<\/p>\n<p>Rostfreie Schwei\u00dftische zeichnen sich durch hohe Verarbeitungsqualit\u00e4t und Verschlei\u00dffestigkeit aus. Sie sind aus rostfreiem Stahl mit hohem Chromanteil gefertigt, was ihnen Langlebigkeit und Korrosionsbest\u00e4ndigkeit verleiht. Dank der GPPH INOX Schwei\u00dftische besteht beim Schwei\u00dfen von Edelstahlkonstruktionen keine Gefahr, dass Eisen ausf\u00e4llt und Korrosionsherde entstehen.<\/p>\n<p>Technische Daten der Basis mit hydraulischem Hebesystem:<\/p>\n<ul>\n<li>Versorgungsspannung: 400 V<\/li>\n<li>Drehzahl: 1400 U\/min<\/li>\n<li>Schutzklasse: IP54<\/li>\n<li>Isolationsklasse: F<\/li>\n<\/ul>\n<h4>Technische Parameter<\/h4>\n<ul>\n<li>Maximale Tragkraft [kg]: 1600<\/li>\n<li>Hubzeit mit Last [s]: 20-25<\/li>\n<li>Maximale Tischh\u00f6he [mm]: 1150<\/li>\n<li>Min. Tischh\u00f6he [mm]: 460<\/li>\n<li>Abmessungen der Hebeb\u00fchne [mm]: 1220\u00d7785<\/li>\n<li>Motorleistung [kW]: 2,2<\/li>\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>Sto\u0142y Spawalnicze GPPH z hydraulicznym systemem podnoszenia to specjalistyczne sto\u0142y z automatyczn\u0105 regulacj\u0105 wysoko\u015bci blatu. Dzi\u0119ki niemu szybko i \u0142atwo osi\u0105gniesz idealn\u0105 wysoko\u015b\u0107 robocz\u0105 blatu sto\u0142u, zapewniaj\u0105c wysoki komfort pracy. Sto\u0142y spawalnicze z hydraulicznym systemem podnoszenia posiadaj\u0105: zaw\u00f3r przeci\u0105\u017ceniowy uniemo\u017cliwiaj\u0105cy podnoszenie zbyt ci\u0119\u017ckich \u0142adunk\u00f3w; zaw\u00f3r bezpiecze\u0144stwa zatrzymuj\u0105cy opuszczanie w momencie p\u0119kni\u0119cia przewod\u00f3w hydraulicznych; wy\u0142\u0105czniki kra\u0144cowe [&hellip;]<\/p>","protected":false},"featured_media":16057,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[88,68,113,141,82],"product_tag":[],"class_list":{"0":"post-16056","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-podnoszone","7":"product_cat-stoly-spawalnicze","8":"product_cat-1500x1000-mm","9":"product_cat-stoly-spawalnicze-ze-stali-nierdzewnej","10":"product_cat-xwt","11":"product_shipping_class-stol-spawalniczy-2000","12":"pa_blat-pro-inox","13":"pa_max-wysokosc-stolu-mm-334","14":"pa_min-wysokosc-stolu-mm-335","15":"pa_moc-silnika-kw-322","16":"pa_nosnosc-max-kg-333","17":"pa_rozmiar-1500x1000mm","18":"pa_seria-xwt","19":"pa_siatka-100x100mm","20":"pa_siatka-50x50mm","21":"pa_siatka-diagonalna","22":"pa_system-fi16","23":"pa_system-fi28","24":"pa_tolerancja-plaskosci-03-mm","25":"pa_tolerancja-wykonania-otworow-005-mm","26":"pa_wymiary-podstawy-podnosnika-m-1220x785","28":"first","29":"instock","30":"sale","31":"taxable","32":"shipping-taxable","33":"purchasable","34":"product-type-variable","35":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product\/16056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/comments?post=16056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/media\/16057"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/media?parent=16056"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_brand?post=16056"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_cat?post=16056"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_tag?post=16056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}