﻿{"id":13644,"date":"2022-12-14T15:27:00","date_gmt":"2022-12-14T13:27:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=katownik-185x175mm"},"modified":"2026-08-17T11:52:17","modified_gmt":"2026-08-17T09:52:17","slug":"winkeleisen-185x175-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de_ch\/p\/werkzeuge\/raumlich\/winkeleisen-185x175-mm\/","title":{"rendered":"Winkeleisen 185x175 mm"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Schwei\u00dfwinkel \u2013 pr\u00e4zise Ausrichtung von Bauteilen im rechten Winkel<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile is-vertically-aligned-top\" style=\"grid-template-columns:auto 28%\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>Schwei\u00dfwinkel<\/strong> ist ein pr\u00e4zises Hilfsmittel zum Positionieren von Werkst\u00fccken beim Schwei\u00dfen, Montieren und Arbeiten auf Schwei\u00dftischen.<\/p>\n\n\n\n<p><br>Erm\u00f6glicht exaktes Positionieren und stabiles Halten von Elementen im rechten Winkel \u2013 ein wichtiger Faktor beim Anpassen und Verbinden von Profilen, Rohren und Stahlstrukturen.<\/p>\n\n\n\n<p><br>Der Winkel besitzt eine L-Form und wird mit hoher Pr\u00e4zision gefertigt, was eine exakte Winkeltreue und wiederholbare Positionierung der Teile erm\u00f6glicht.<\/p>\n\n\n\n<p><br>Montagel\u00f6cher erm\u00f6glichen eine schnelle Befestigung und eine einfache Anpassung an die aktuellen Arbeitsanforderungen.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/4\/1\/341.jpg\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/4\/1\/341.jpg\" alt=\"Winkeleisen 185x175 mm, System - \u03a628, Serie - PRO\" class=\"wp-image-13647 size-full\"\/><\/a><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Kompatibilit\u00e4t mit Schwei\u00dftischen<\/strong><\/h3>\n\n\n\n<p>Die Schwei\u00dfwinkel sind in drei Serien erh\u00e4ltlich, die auf die jeweiligen Schwei\u00dftischtypen abgestimmt sind:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\" translation-block\"><strong>EXPERT \u2013<\/strong> geeignet f\u00fcr Schwei\u00dftische mit einer 25 mm starken Arbeitsplatte.<\/li>\n\n\n\n<li class=\" translation-block\"><strong>PRO \u2013<\/strong> geeignet f\u00fcr Schwei\u00dftische mit einer 15 mm starken Arbeitsplatte.<\/li>\n\n\n\n<li class=\" translation-block\"><strong>PLUS \u2013<\/strong> geeignet f\u00fcr Schwei\u00dftische mit einer 12 mm und 8 mm starken Arbeitsplatte.<\/li>\n<\/ul>\n\n\n\n<p>Jede Serie bleibt vollst\u00e4ndig kompatibel mit dem jeweiligen Schwei\u00dftischtyp und gew\u00e4hrleistet eine korrekte Passform sowie eine stabile Positionierung der Werkst\u00fccke.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Konstruktion und Ausf\u00fchrung<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Der Schwei\u00dfwinkel besteht aus Baustahl <strong>S355J2+N<\/strong>, der gegen Verformungen und intensive Nutzung unter Werkstattbedingungen best\u00e4ndig ist.<br>Jede Arbeitsfl\u00e4che ist pr\u00e4zise bearbeitet, was eine stabile Auflage und sichere Positionierung der Werkst\u00fccke gew\u00e4hrleistet.<br>Die robuste Konstruktion bew\u00e4hrt sich sowohl im t\u00e4glichen Einsatz als auch bei Projekten, die hohe Pr\u00e4zision und Wiederholgenauigkeit erfordern.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vorteile der Verwendung eines Schwei\u00dfwinkels<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>pr\u00e4zise Positionierung der Werkst\u00fccke im rechten Winkel,<\/li>\n\n\n\n<li>stabile Abst\u00fctzung und sichere Fixierung der Werkst\u00fccke,<\/li>\n\n\n\n<li>schnelle Vorbereitung von Konstruktionen zum Schwei\u00dfen,<\/li>\n\n\n\n<li>robuste und langlebige Stahlkonstruktion,<\/li>\n\n\n\n<li>universelle Verwendung bei Schwei\u00df-, Montage- und Schlossereiarbeiten.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Verwenden - wo?<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Positionierung von Profilen, Rohren und Konstruktionselementen,<\/li>\n\n\n\n<li>Montage und Kontrolle von rechtwinkligen Verbindungen,<\/li>\n\n\n\n<li>Werkstattarbeiten, die eine genaue Ausrichtung und stabile Fixierung erfordern.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Zus\u00e4tzliche Informationen<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Der Schwei\u00dfwinkel wird in <strong>Polen<\/strong> aus Werkstoffen hergestellt, die die Qualit\u00e4tsnormen f\u00fcr Baust\u00e4hle erf\u00fcllen.<\/p>\n\n\n\n<p>Jedes Teil wird einer Qualit\u00e4tskontrolle unterzogen, um die h\u00f6chste Verarbeitungsqualit\u00e4t zu gew\u00e4hrleisten.<\/p>","protected":false},"excerpt":{"rendered":"<p>Das Winkeleisen 185x175 mm ist ein Werkzeug, das zum Positionieren und Spannen r\u00e4umlicher Schwei\u00dfbauteile auf dem Schwei\u00dftisch bestimmt ist.<\/p>","protected":false},"featured_media":39185,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[104,69],"product_tag":[],"class_list":{"0":"post-13644","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-przestrzenne","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-expert","11":"pa_seria-plus","12":"pa_seria-pro","13":"pa_srednica-otworow-28-lub-16","14":"pa_system-fi16","15":"pa_system-fi28","16":"pa_typ-narzedzia-przestrzenne","17":"pa_wymiar-narzedzia-185x175mm","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable","26":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product\/13644","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/comments?post=13644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/media\/39185"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/media?parent=13644"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_brand?post=13644"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_cat?post=13644"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de_ch\/wp-json\/wp\/v2\/product_tag?post=13644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}