﻿{"id":38583,"date":"2026-07-14T09:45:53","date_gmt":"2026-07-14T07:45:53","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=38583"},"modified":"2026-07-14T10:33:44","modified_gmt":"2026-07-14T08:33:44","slug":"outlet-schweisstisch-smart-15mm-2400x1200mm-system-%cf%8628-raster-100x100mm-w67","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de_at\/p\/outlet\/outlet-schweisstisch-smart-15mm-2400x1200mm-system-%cf%8628-raster-100x100mm-w67\/","title":{"rendered":"[OUTLET] Schwei\u00dftisch SMART 15 mm 2400x1200 mm \u2013 System \u03c628, 100x100 mm Raster"},"content":{"rendered":"<p>Schwei\u00dftische sind das ideale Werkzeug \u00fcberall dort, wo Pr\u00e4zision und Wiederholgenauigkeit gefordert sind. Die 15\u202fmm starke Tischplatte mit dichtem Rippenprofil gew\u00e4hrleistet Ebenheit und Stabilit\u00e4t selbst bei schweren Konstruktionen. Das System gefr\u00e4ster und angefasster \u03c628\u2011Bohrungen im 100\u00d7100\u2011mm\u2011Raster erleichtert die Werkzeugmontage und beschleunigt sowie vereinfacht die Arbeit.<\/p>\n<p><strong>Hauptmerkmale des Tisches:<\/strong><\/p>\n<ul>\n<li>Die 15\u202fmm starke Platte mit dichtem Rippenprofil sorgt f\u00fcr eine perfekt ebene Arbeitsfl\u00e4che.<\/li>\n<li>Abmessungen: 2400\u00d71200 mm, 1 L\u00e4ngsrippe und 3 L\u00e4ngsrippen, die Stabilit\u00e4t w\u00e4hrend der Nutzung und Widerstandsf\u00e4higkeit gegen Verformungen gew\u00e4hrleisten.<\/li>\n<li>Maschenweite 100 \u00d7 100 mm, System \u03c628<\/li>\n<\/ul>\n<p>Die Tischplatte ist zus\u00e4tzlich mit einer gravierten 100\u00d7100 mm Raster-Skala ausgestattet, die eine pr\u00e4zise Ausrichtung von Konstruktionen und die Montage von Werkzeugen erleichtert und h\u00f6chste Genauigkeit bei jeder Arbeit gew\u00e4hrleistet.<\/p>\n<p><strong>Beinvarianten:\u00a0<\/strong><\/p>\n<ul>\n<li>Mit festen F\u00fc\u00dfen \u2013 bieten Stabilit\u00e4t und hohe Tragf\u00e4higkeit.<\/li>\n<li>Mit Rollen \u2013 ideal f\u00fcr Arbeiten, bei denen Tischmobilit\u00e4t erforderlich ist.<\/li>\n<\/ul>\n<p>Beim Kauf dieses Produkts k\u00f6nnen Sie zwischen einer Variante mit festen F\u00fc\u00dfen oder mit Rollen w\u00e4hlen.<\/p>\n<p>Die Tischbeine aus 60\u00d760-mm-Profilen haben eine maximale Tragf\u00e4higkeit von 2500 kg. Dadurch bleibt der Tisch auch bei hohen Belastungen stabil.<\/p>\n<p class=\" translation-block\">Mit dem Kauf eines Outlet-Tisches erkl\u00e4ren Sie, dass Sie sich <strong>mit dessen tats\u00e4chlichem Zustand vertraut gemacht haben<\/strong> und ihn <strong>ohne Reklamationsrecht akzeptieren<\/strong>. Gem\u00e4\u00df Artikel 557 \u00a7 1 des polnischen Zivilgesetzbuches ist der Verk\u00e4ufer von der Gew\u00e4hrleistung befreit, wenn der K\u00e4ufer den Mangel zum Zeitpunkt des Vertragsschlusses kannte.<\/p>\n<p>M\u00f6chten Sie mehr \u00fcber die traditionellen Schwei\u00dftische von GPPH erfahren? Informieren Sie sich auf der entsprechenden Seite <a href=\"https:\/\/gpph-group.com\/de_at\/produkte\/traditionelle-schweisstische\/\">traditionellen Schwei\u00dftischen.<\/a><a href=\"https:\/\/gpph-group.com\/de_at\/\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a0<\/a><\/p>\n<p id=\"defekty\"><strong>ACHTUNG: Der Tisch weist einen Defekt auf:\u00a0<\/strong><\/p>\n<ul>\n<li>Kratzer auf der Tischplatte<\/li>\n<li>Ungleichm\u00e4\u00dfige Fasen<\/li>\n<\/ul>\n<p>Fotos der M\u00e4ngel sind unten dargestellt.<\/p>\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-scaled.jpg\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-1024x683.jpg\" alt=\"[OUTLET] Schwei\u00dftisch SMART 15 mm 2400x1200 mm \u2013 System \u03c628, 100x100 mm Raster\" class=\"wp-image-38595\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323147-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-scaled.jpg\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-1024x683.jpg\" alt=\"[OUTLET] Schwei\u00dftisch SMART 15 mm 2400x1200 mm \u2013 System \u03c628, 100x100 mm Raster\" class=\"wp-image-38589\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-1024x683.jpg 1024w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-300x200.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-768x512.jpg 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-1536x1024.jpg 1536w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-2048x1365.jpg 2048w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-18x12.jpg 18w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-600x400.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2026\/07\/P1323137-64x43.jpg 64w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>Wir laden Sie ein, sich selbst zu \u00fcberzeugen <a href=\"https:\/\/gpph-group.com\/pl\/p\/stoly-spawalnicze\/2400x1200-mm\/stol-spawalniczy-smart-15-2400-x-1200-mm\/\" target=\"_blank\" rel=\"noopener\">vollwertigen Produkts<\/a>. Das aktuelle Angebot betrifft ein Outlet-Exemplar,<strong> das nur in begrenzter St\u00fcckzahl und zu einem besonders attraktiven Preis erh\u00e4ltlich ist.<\/strong> <strong>ACHTUNG! Der Tisch weist einen Defekt auf:<\/strong><\/p>\n<ul>\n<li>Kratzer auf der Tischplatte<\/li>\n<li>Ungleichm\u00e4\u00dfige Fasen<\/li>\n<\/ul>","protected":false},"featured_media":38586,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[168],"product_tag":[],"class_list":{"0":"post-38583","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-outlet","7":"product_shipping_class-stol-spawalniczy-2000","8":"pa_nogi-na-kolach","9":"pa_nogi-na-stopach","10":"pa_seria-smart15","11":"pa_siatka-100x100mm","12":"pa_srednica-otworow-364","13":"pa_wymiar-stolu-2400x1200","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product\/38583","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/comments?post=38583"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/media\/38586"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/media?parent=38583"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_brand?post=38583"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_cat?post=38583"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_tag?post=38583"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}