﻿{"id":16957,"date":"2024-11-25T15:04:00","date_gmt":"2024-11-25T13:04:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=wozek-narzedziowy-gpph-l-z-zestawem-szuflad"},"modified":"2026-06-15T08:32:48","modified_gmt":"2026-06-15T06:32:48","slug":"gpph-werkzeugwagen-l-mit-schubladen-set","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de_at\/p\/werkzeuge\/werkzeugwagen-2\/gpph-werkzeugwagen-l-mit-schubladen-set\/","title":{"rendered":"Werkzeugwagen L mit Schubladen-Set"},"content":{"rendered":"<p><span style=\"font-size: inherit;\">Unser moderner Rollwagen mit Schubladen ist die ideale L\u00f6sung f\u00fcr alle, die Funktionalit\u00e4t und Benutzerkomfort sch\u00e4tzen. Er wurde unter ergonomischen Gesichtspunkten entwickelt, um den t\u00e4glichen Gebrauch einfach und bequem zu gestalten.<\/span><\/p>\n<p><span style=\"font-size: inherit;\">Vollauszugschubladen mit 450 mm langen F\u00fchrungen.<\/span><\/p>\n<p><span style=\"font-size: inherit;\">Der Werkzeugwagen L mit Schubladen ist eine zus\u00e4tzliche Option zur Aufbewahrung von Werkzeugen. Der Wagen L allein bietet Platz f\u00fcr den Werkzeugsatz selbst der anspruchsvollsten Handwerker und mit den Schubladen l\u00e4sst sich die Arbeitsausr\u00fcstung noch besser organisieren.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-size: inherit;\"><strong>HAUPTMERKMALE DES WERKZEUGWAGENS L MIT SCHUBLADENSYSTEM:<\/strong><\/span><\/p>\n<ul>\n<li class=\" translation-block\"><span style=\"font-size: inherit\"><strong>Leichtg\u00e4ngiges Ausziehen: <\/strong>Die Schubladen garantieren ein leichtg\u00e4ngiges und ger\u00e4uscharmes Ausziehen und sind f\u00fcr eine Belastung von bis zu 100 kg ausgelegt. Selbst bei voller Beladung lassen sich die Schubladen leicht und ohne Widerstand bewegen.<\/span><\/li>\n<li class=\" translation-block\"><strong style=\"font-size: inherit\">Vollauszug: <\/strong><span style=\"font-size: inherit\">Die Konstruktion der F\u00fchrungen erm\u00f6glicht einen Vollauszug der Schubladen, wodurch der gesamte Inhalt leicht zug\u00e4nglich ist und schwer erreichbare Stellen kein Problem mehr darstellen.<\/li>\n<li class=\" translation-block\"><strong style=\"font-size: inherit\">Leises Schlie\u00dfsystem: <\/strong><span style=\"font-size: inherit\">Dank moderner Mechanismen schlie\u00dfen die Schubladen sanft und ger\u00e4uschlos, was den Bedienkomfort erh\u00f6ht und Besch\u00e4digungen verhindert.<\/li>\n<\/ul>\n<p><span style=\"font-size: inherit;\">Tiefe Schubladen bieten viel Stauraum und erm\u00f6glichen die Aufbewahrung verschiedener Gegenst\u00e4nde, von Dokumenten bis hin zu gr\u00f6\u00dferen Accessoires. Zus\u00e4tzlich sind sie mit einer 3 mm dicken Gummimatte mit rutschfester Oberfl\u00e4che ausgestattet.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p><span style=\"font-size: inherit;\">Unser moderner Rollwagen mit Schubladen ist die ideale L\u00f6sung f\u00fcr alle, die Funktionalit\u00e4t und Benutzerkomfort sch\u00e4tzen. Er wurde unter ergonomischen Gesichtspunkten entwickelt, um den t\u00e4glichen Gebrauch einfach und bequem zu gestalten.<\/span><\/p>\n<p><span style=\"font-size: inherit;\">Vollauszugschubladen mit 450 mm langen F\u00fchrungen.<\/span><\/p>","protected":false},"featured_media":28040,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[100,69],"product_tag":[],"class_list":{"0":"post-16957","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-wozki","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_system-fi16","10":"pa_system-fi28","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-variable","19":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product\/16957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/comments?post=16957"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/media\/28040"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/media?parent=16957"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_brand?post=16957"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_cat?post=16957"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_tag?post=16957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}