﻿{"id":13934,"date":"2022-12-19T16:18:00","date_gmt":"2022-12-19T14:18:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stol-spawalniczo-montazowy-diy-1200-x-800-mm"},"modified":"2026-07-07T06:11:31","modified_gmt":"2026-07-07T04:11:31","slug":"schweiss-und-montagetisch-diy-1200-x-800-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de_at\/p\/schweistische\/diy\/schweiss-und-montagetisch-diy-1200-x-800-mm\/","title":{"rendered":"Schwei\u00df- und Montagetisch DIY 8 mm \u2013 1200 x 800 mm"},"content":{"rendered":"<p class=\" translation-block\">Schwei\u00dftische kommen \u00fcberall dort zum Einsatz, wo <strong>Pr\u00e4zision beim Schwei\u00dfen<\/strong> gefragt ist. Sie k\u00f6nnen sie f\u00fcr das manuelle oder robotergest\u00fctzte Schwei\u00dfen verwenden. <strong>Ihre Konstruktionen werden endlich pr\u00e4zise und ohne unn\u00f6tige Nachbesserungen ausgef\u00fchrt!<\/strong><br> Er gew\u00e4hrleistet au\u00dferdem ergonomisches und schnelles Arbeiten bei gleichbleibender Pr\u00e4zision und Wiederholbarkeit der ausgef\u00fchrten Konstruktionen.<\/p>\n<p class=\" translation-block\"><strong>Der Schwei\u00dftisch muss eben sein<\/strong>! Die Tischplatten der DIY-Tische sind <strong>8 mm dick<\/strong> und verf\u00fcgen \u00fcber eine <strong>dichte Verrippung<\/strong>, die f\u00fcr eine perfekt ebene Arbeitsfl\u00e4che sorgt. Der Tisch mit den Ma\u00dfen 1200\u00d7800 mm hat 1 L\u00e4ngsverrippung und 2 Querverrippungen. <strong>Die massive und starre Unterkonstruktion der Tischplatte garantiert h\u00f6chste Stabilit\u00e4t bei der Nutzung und sch\u00fctzt vor Verformungen. Die Ebenheitstoleranz der Tischplatte betr\u00e4gt \u00fcber die gesamte Fl\u00e4che <strong>\u00b10,5 mm*.<\/strong><\/p>\n<table class=\"description_table--thickness_and_ribbing\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/BLAT_DIY.jpg\" alt=\"Die Dicke der DIY-Tischplatte betr\u00e4gt 8 mm.\" width=\"500\" height=\"500\" \/><\/td>\n<td><img decoding=\"async\" class=\"mh-500\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/stoly\/ozebrowanie\/ozebrowanie_1200x800.jpg\" alt=\"Rippenprofil des 1200\u00d7800\u202fmm Tisches\" width=\"500\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<table class=\"descriptionSystemsTable\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td colspan=\"2\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/50x50_fi16.jpg\" alt=\"Maschenweite 50 x 50 mm, System fi16\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\" translation-block\">Die\u202f<strong>eingravierte Teilungsmarkierung<\/strong> der Tischplatte besteht aus vertikalen und horizontalen Linien im 100\u00d7100\u202fmm-Raster. Sie dient als Bezugspunkt beim Positionieren der Konstruktion und w\u00e4hrend der Montage der Werkzeuge. Mit Messwerkzeugen k\u00f6nnen Sie Ihre Konstruktion entsprechend ausrichten, um das ben\u00f6tigte Ma\u00df zu erreichen.<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/grawerowana_podzialka.jpg\" alt=\"Eingravierte Skala\" width=\"1000\" height=\"500\" \/><\/p>\n<p><strong>Die maximale Tragf\u00e4higkeit des DIY-Tisches betr\u00e4gt 500 kg.<\/strong><\/p>\n<p class=\" translation-block\">F\u00fcr wen ist der <strong>DIY-Schwei\u00dftisch<\/strong> geeignet?<\/p>\n<ul>\n<li><strong>F\u00dcR HEIMWERKER<\/strong> \u2013 Der DIY-Schwei\u00df- und Montagetisch eignet sich f\u00fcr die Verwirklichung Ihrer Hobbys, z. B. Heimwerken, Schwei\u00dfen. Er erleichtert die Arbeit mit allen Werkzeugen eines Heimwerkers.<\/li>\n<li><strong>ALS TISCH F\u00dcR CNC-MASCHINEN<\/strong> \u2013 Der Schwei\u00df- und Montagetisch DIY eignet sich ideal f\u00fcr Produktionsbetriebe als Hilfstisch zum Austausch von Werkzeugen in Halterungen und zum Messen der gefertigten Elemente.<\/li>\n<li><strong>F\u00dcR DEN TISCHLER<\/strong> \u2013 Erleichtert das Schneiden und Montieren von M\u00f6belelementen. Zus\u00e4tzliche Werkzeuge helfen dabei, die w\u00e4hrend der Arbeit verwendeten Elemente pr\u00e4ziser anzupassen und erleichtern die Arbeit f\u00fcr eine Person.<\/li>\n<li><strong>F\u00dcR MECHANIKER<\/strong> \u2013 Eignet sich f\u00fcr die Reparatur von Autoteilen sowie f\u00fcr Schwei\u00df-, Schleif- und andere mechanische Arbeiten.<\/li>\n<li><strong>F\u00dcR DIE WERKST\u00c4TTE<\/strong> \u2013 Der DIY-Schwei\u00df- und Montagetisch eignet sich ideal zur Befestigung einer Bohrmaschine, eines Schraubstocks und anderer Werkzeuge. Damit werden die zu bearbeitenden Teile stabil auf der Tischplatte fixiert.<\/li>\n<li><strong>F\u00dcR SCHWEISSER<\/strong> \u2013 Die zus\u00e4tzliche Ausstattung des DIY-Schwei\u00df- und Montagetisches macht die Schwei\u00dfarbeiten pr\u00e4zise, komfortabel und schnell. Die Fertigung kleiner und gro\u00dfer Schwei\u00dfserien war noch nie so einfach!<\/li>\n<li><strong>F\u00dcR BAUARBEITNEHMER<\/strong> \u2013 Es ist leicht und mobil, sodass es auf jede Baustelle mitgenommen werden kann. Mit seiner Hilfe k\u00f6nnen Sie Material schneiden und Elemente direkt auf der Baustelle verschwei\u00dfen.<\/li>\n<li><strong>F\u00dcR LANDWIRTE<\/strong> \u2013 Ideal als Schwei\u00df- und Montagetisch f\u00fcr die Herstellung und Reparatur von Bauteilen f\u00fcr Landmaschinen. Eignet sich auch hervorragend f\u00fcr die Wartung und Instandhaltung von Verschlei\u00dfteilen.<\/li>\n<\/ul>\n<p class=\" translation-block\">F\u00fcr die Arbeit auf dem DIY-Schwei\u00dftisch verwenden Sie gefr\u00e4ste Werkzeuge \u201e11\u201d, die mit einem verstellbaren Montagebolzen 19-22 montiert werden. Die Toleranz der Bohrungen des Schwei\u00dftisches betr\u00e4gt <strong>\u00b10,1 mm.<\/strong> Damit k\u00f6nnen Sie jede flache 2D- und r\u00e4umliche 3D-Konstruktion pr\u00e4zise ausf\u00fchren. Und das alles in deutlich k\u00fcrzerer Zeit!<\/p>\n<p>*vorausgesetzt, dass der Tisch richtig nivelliert ist.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Tisch verf\u00fcgt \u00fcber verschwei\u00dfte Verst\u00e4rkungsrippen. Dieses Produkt eignet sich nicht nur ideal f\u00fcr Schwei\u00dfer, sondern auch f\u00fcr Heimwerker, Tischler, Kfz-Mechaniker, als Hilfstisch f\u00fcr CNC-Maschinen sowie f\u00fcr verschiedene Werkst\u00e4tten. Die Beine des DIY-Tisches sind mit schwenkbaren F\u00fc\u00dfen ausgestattet, die Unebenheiten des Bodens ausgleichen.<\/p>","protected":false},"featured_media":28151,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[76,87,68,116],"product_tag":[],"class_list":{"0":"post-13934","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-diy","7":"product_cat-montazowe","8":"product_cat-stoly-spawalnicze","9":"product_cat-1200x800-mm","10":"product_shipping_class-narzedzia","11":"pa_grubosc-blatu-8mm","12":"pa_nosnosc-500kg","13":"pa_seria-diy","14":"pa_tolerancja-plaskosci-05-mm","15":"pa_tolerancja-wykonania-otworow-01-mm","17":"first","18":"instock","19":"sale","20":"taxable","21":"shipping-taxable","22":"purchasable","23":"product-type-simple"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product\/13934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/comments?post=13934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/media\/28151"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/media?parent=13934"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_brand?post=13934"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_cat?post=13934"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de_at\/wp-json\/wp\/v2\/product_tag?post=13934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}