﻿{"id":25474,"date":"2025-09-09T11:24:00","date_gmt":"2025-09-09T09:24:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=25474"},"modified":"2026-06-01T00:03:05","modified_gmt":"2026-05-31T22:03:05","slug":"verbinder-block-800x100x100-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de\/p\/flachenvergroserung\/verbinder-block-800x100x100-mm\/","title":{"rendered":"Verbinder, Block 800x100x100 mm"},"content":{"rendered":"<p>Verbinder, Block 800x100x100 mm in Lochversion mm, Raster:<\/p>\n<p>Der Verbinder, Block 800x100x100, ist ein Werkzeug, das zum Verbinden von zwei Schwei\u00dftischen entwickelt wurde, wobei deren Funktionalit\u00e4t erhalten bleibt \u2013 wie die Tischplatte verf\u00fcgt er \u00fcber ein Raster und Montagebohrungen. Damit kann ein Schwei\u00dfarbeitsplatz in einer nicht standardm\u00e4\u00dfigen Form geschaffen werden, indem beliebig viele Tische miteinander verbunden werden, um einen an das jeweilige Projekt angepassten Arbeitsplatz zu bilden.<\/p>\n<p>Der Verbinder, Block 800x100x100, ist in den folgenden Systemen und Lochrastern erh\u00e4ltlich:<\/p>\n<ul>\n<li>Lochsystem \u03c616 mm, Lochraster 50 x 50 mm, Dicke 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<li>Lochsystem \u03c616 mm, diagonales Lochraster, Dicke 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<li>Lochsystem \u03c628 mm, diagonales Lochraster, Dicke 8 mm, 12 mm, 15 mm, 25 mm<\/li>\n<\/ul>\n<p>Der Verbinder, W\u00fcrfel aus der EXPERT-Werkzeugserie kann f\u00fcr Schwei\u00dftische aus der EXPERT-Serie verwendet werden.<\/p>\n<p>Der Verbinder, W\u00fcrfel aus der PRO-Werkzeugserie kann f\u00fcr Schwei\u00dftische der PRO-Serie, XWT mit Tischplatte der PRO-Serie sowie f\u00fcr modulare Schwei\u00dftische verwendet werden.<\/p>\n<p>Der Verbinder, W\u00fcrfel aus der PLUS-Werkzeugserie kann f\u00fcr Schwei\u00dftische der Serien PLUS, ECO, BASIC, XWT mit Tischplatte der Serie PLUS verwendet werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Der Verbinder, Block 800x100x100 im Raster, ist ein Werkzeug, das zum Verbinden von zwei Schwei\u00dftischen entwickelt wurde, wobei deren Funktionalit\u00e4t erhalten bleibt \u2013 wie die Tischplatte verf\u00fcgt er \u00fcber ein Raster und Montagebohrungen. Damit kann ein Schwei\u00dfarbeitsplatz in einer nicht standardm\u00e4\u00dfigen Form geschaffen werden, indem beliebig viele Tische miteinander verbunden werden, um einen an das jeweilige Projekt angepassten Arbeitsplatz zu bilden.<\/p>","protected":false},"featured_media":26546,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[171,105],"product_tag":[],"class_list":{"0":"post-25474","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-zwiekszanie-powierzchni","7":"product_cat-kostki-i-przedluzenia","8":"product_shipping_class-narzedzia","9":"pa_dla-stolu-eco","10":"pa_dla-stolu-plus","11":"pa_dla-stolu-pro","12":"pa_dla-stolu-expert","13":"pa_grubosc-narzedzia-8mm-11mm-15mm-25mm","14":"pa_seria-eco","15":"pa_seria-plus","16":"pa_seria-pro","17":"pa_seria-expert","18":"pa_siatka-100x100mm","19":"pa_siatka-50x50mm","20":"pa_srednica-otworow-28-lub-16","21":"pa_system-fi28","22":"pa_system-fi16","23":"pa_typ-narzedzia-kostki-i-przedluzenia","24":"pa_wymiar-narzedzia-800x100x100mm","26":"first","27":"instock","28":"sale","29":"taxable","30":"shipping-taxable","31":"purchasable","32":"product-type-variable","33":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product\/25474","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/comments?post=25474"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/media\/26546"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/media?parent=25474"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_brand?post=25474"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_cat?post=25474"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_tag?post=25474"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}