﻿{"id":24506,"date":"2025-08-28T13:56:00","date_gmt":"2025-08-28T11:56:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=24506"},"modified":"2026-06-15T08:25:22","modified_gmt":"2026-06-15T06:25:22","slug":"prism-%cf%86120-mm-157-verstellbar-170-230","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de\/p\/werkzeuge\/prismen\/prism-%cf%86120-mm-157-verstellbar-170-230\/","title":{"rendered":"Prisma \u03c6120 mm 157\u00b0 verstellbar 170-230"},"content":{"rendered":"<h2 class=\"wp-block-heading\"><strong>Verstellbare Schwei\u00dfprisma \u2013 stabile Unterst\u00fctzung der Werkst\u00fccke beim Schwei\u00dfen<\/strong><\/h2>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\">Die <strong>verstellbare Schwei\u00dfprisma<\/strong> ist ein Hilfselement, das f\u00fcr die <strong>stabile Abst\u00fctzung und Positionierung<\/strong> von Rohren, St\u00e4ben, Profilen und anderen Werkst\u00fccken beim Schwei\u00dfen, Montieren oder in der Werkstatt entwickelt wurde.<\/p>\n\n\n\n<p class=\" translation-block\">Die Arbeitsfl\u00e4che in Form eines <strong>\u201eV\u201c mit festem Winkel<\/strong> gew\u00e4hrleistet eine sichere und wiederholgenaue Positionierung des Werkst\u00fccks, erleichtert die Einhaltung der richtigen Lage w\u00e4hrend der Arbeit und verbessert die Genauigkeit der Verbindungen.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005.png\" alt=\"Prisma \u03c6120 mm 157\u00b0 verstellbar 170-230\" class=\"wp-image-24505 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005.png 1000w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005-300x300.png 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005-150x150.png 150w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005-768x768.png 768w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005-12x12.png 12w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005-600x600.png 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/2025\/08\/28_P_005-64x64.png 64w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Konstruktion und Fertigungspr\u00e4zision<\/strong><\/h3>\n\n\n\n<p>Die Prisma besteht aus hochwertigem Stahl, der gegen Besch\u00e4digungen und intensive Werkstattnutzung best\u00e4ndig ist. Die pr\u00e4zise bearbeitete Oberfl\u00e4che sorgt daf\u00fcr, dass das Werkst\u00fcck gut an der Prisma anliegt und w\u00e4hrend des Schwei\u00dfens in Position bleibt.<\/p>\n\n\n\n<p>Die einfache und langlebige Konstruktion bew\u00e4hrt sich sowohl in der Serienproduktion als auch bei einzelnen Schwei\u00dfprojekten.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>H\u00f6henverstellung<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Die verstellbare Version der Prisma erm\u00f6glicht eine pr\u00e4zise Anpassung der St\u00fctzh\u00f6he an die Art der Arbeit und die Abmessungen des Werkst\u00fccks.<br>Der Einstellbereich erlaubt es, das Element auf die richtige H\u00f6he zu bringen, wodurch die Ausrichtung von Konstruktionsteilen, deren Positionierung und das Halten des richtigen Winkels beim Schwei\u00dfen erleichtert werden. Diese L\u00f6sung erh\u00f6ht den Arbeitskomfort und optimiert die Nutzung der Arbeitsfl\u00e4che des Schwei\u00dftisches.<\/p>\n\n\n\n<p class=\" translation-block\">Der Verstellmechanismus besteht aus pr\u00e4zise aufeinander abgestimmten Komponenten, wodurch er gleichm\u00e4\u00dfig arbeitet und in jeder Position stabil bleibt.<br>Dies erm\u00f6glicht eine schnelle H\u00f6henanpassung, ohne die Einstellgenauigkeit zu verlieren.<br>Die verstellbare Prisma eignet sich besonders f\u00fcr Montagearbeiten und das Schwei\u00dfen von Bauteilen unterschiedlicher H\u00f6he.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vorteile der Verwendung einer Schwei\u00dfprisma<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>stabile und wiederholgenaue Abst\u00fctzung von Rohren, St\u00e4ben und Profilen,<\/li>\n\n\n\n<li>Verbesserung der Schwei\u00dfgenauigkeit und -qualit\u00e4t,<\/li>\n\n\n\n<li>schnelles und bequemes Positionieren der Werkst\u00fccke,<\/li>\n\n\n\n<li>robuste Stahlkonstruktion, best\u00e4ndig gegen intensive Nutzung,<\/li>\n\n\n\n<li>universelle Anwendung bei Schwei\u00df-, Montage- und Kontrollarbeiten.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Verwenden - wo?<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Abst\u00fctzung von Rohren, St\u00e4ben und Profilen beim Schwei\u00dfen und Montieren,<\/li>\n\n\n\n<li>Positionierung von Konstruktionselementen vor dem F\u00fcgen,<\/li>\n\n\n\n<li>Werkstattarbeiten, die eine pr\u00e4zise und stabile Positionierung des Werkst\u00fccks erfordern.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Wartung der Prismen<\/strong><\/h3>\n\n\n\n<p>Die Prisma sollte regelm\u00e4\u00dfig von Schwei\u00dfspritzern und Verunreinigungen gereinigt und regelm\u00e4\u00dfig mit PROTECTOR, erh\u00e4ltlich in unserem Online-Shop, vor Korrosion gesch\u00fctzt werden.<\/p>","protected":false},"excerpt":{"rendered":"<p>Prisma \u03c6120 mm 157\u00b0 verstellbar 170-230<\/p>","protected":false},"featured_media":24505,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[542,69],"product_tag":[],"class_list":{"0":"post-24506","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pryzmy","7":"product_cat-narzedzia","8":"product_shipping_class-narzedzia","9":"pa_material-wykonania-stal-malowana-proszkowo","10":"pa_material-wykonania-stal-s355j2-n","11":"pa_system-fi16","12":"pa_system-fi28","13":"pa_typ-narzedzia-pryzma-regulowana","15":"first","16":"instock","17":"sale","18":"taxable","19":"shipping-taxable","20":"purchasable","21":"product-type-variable","22":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product\/24506","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/comments?post=24506"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/media\/24505"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/media?parent=24506"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_brand?post=24506"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_cat?post=24506"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_tag?post=24506"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}