﻿{"id":14955,"date":"2023-01-25T16:36:00","date_gmt":"2023-01-25T14:36:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=modulowy-stol-spawalniczy-podwojny-2000x1000-mm"},"modified":"2026-06-10T12:20:55","modified_gmt":"2026-06-10T10:20:55","slug":"modularer-schweisstisch-doppelt-2000x1000-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/de\/p\/schweistische\/modularer-schweisstisch-doppelt-2000x1000-mm\/","title":{"rendered":"Modularer Doppelschwei\u00dftisch 2000\u00d71000 mm"},"content":{"rendered":"<p>Diese Auktion betrifft einen doppelten modularen Schwei\u00dftisch mit Tischplatten aus dem Material S355J2+N mit den Abmessungen 2000\u00d71000.<\/p>\n<p>Doppelte Modultische sind die beliebtesten Sets \u2013 es handelt sich um Tandems, die aus zwei Einzeltischen bestehen. Die Konstruktion der Tische erm\u00f6glicht eine Erweiterung in jede Richtung. Doppeltische sind, wie andere modulare Schwei\u00dftische auch, in drei Gr\u00f6\u00dfen erh\u00e4ltlich: 2000\u00d71000, 2400\u00d71200, 3200\u00d71500.<\/p>\n<p class=\" translation-block\">Die Tischplatten der modularen Tische bestehen aus gefr\u00e4sten, verschiebbaren Platten mit einer St\u00e4rke von 15 mm, die durch ihre verstellbare Oberfl\u00e4che eine ideale Ebenheit gew\u00e4hrleisten. Sie sind mit einem Lochsystem von 28 mm im Raster 100\u00d7100 mm versehen.\nSie verf\u00fcgen \u00fcber gefr\u00e4ste und abgeschr\u00e4gte L\u00f6cher, die die Montage der Werkzeuge erleichtern. Die Modultische sind mit den Werkzeugen der PRO-Serie kompatibel. Dar\u00fcber hinaus erm\u00f6glicht die Konstruktion unserer Modultische eine Erh\u00f6hung der Anzahl der Werkzeugbefestigungspunkte in den Schlitzen zwischen den Tischplatten \u2013 f\u00fcr mehr Ergonomie bei der Arbeit.<\/p>\n<p class=\" translation-block\">Die modularen Tische haben R\u00e4der mit einem Fu\u00df in den Grundbeinen, mit einer <strong>Tragf\u00e4higkeit von 250 kg pro Bein<\/strong>. Die ausziehbaren Versionen der Modultische haben <strong>verstellbare St\u00fctzen <\/strong>in den Zusatzbeinen. Die H\u00f6he der Tische kann zwischen 850 mm und 1150 mm verstellt werden, P=50 mm.<\/p>\n<p class=\" translation-block\">Um eine gr\u00f6\u00dfere Arbeitsfl\u00e4che zu erhalten, <strong>k\u00f6nnen die Tische miteinander kombiniert werden<\/strong>. Als Option k\u00f6nnen Sie auch Seitenplatten erwerben.<\/p>","protected":false},"excerpt":{"rendered":"<p>Ta aukcja dotyczy podw\u00f3jnego modu\u0142owego sto\u0142u spawalniczego z p\u0142ytami blatu wykonanymi z materia\u0142u: S355J2+N o wymiarze 2000&#215;1000. Podw\u00f3jne sto\u0142y modu\u0142owe to najpopularniejsze zestawy &#8211; s\u0105 to tandemy z\u0142o\u017cone z dw\u00f3ch pojedynczych sto\u0142\u00f3w. Konstrukcja sto\u0142\u00f3w umo\u017cliwia rozbudow\u0119 w ka\u017cdym kierunku. Sto\u0142y podw\u00f3jne, podobnie jak inne rodzaje modu\u0142owych sto\u0142\u00f3w spawalniczych, wyst\u0119puj\u0105 w trzech wersjach wymiarowych: 2000&#215;1000, 2400&#215;1200, [&hellip;]<\/p>","protected":false},"featured_media":14956,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[68,86,81,111],"product_tag":[],"class_list":{"0":"post-14955","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-stoly-spawalnicze","7":"product_cat-modulowe","8":"product_cat-mwt","9":"product_cat-2000x1000-mm","10":"product_shipping_class-stol-spawalniczy-2000","11":"pa_grubosc-blatu-15mm","12":"pa_nosnosc-250kg-noga","13":"pa_otwory-frezowane-i-fazowane","14":"pa_rozmiar-2000x1000mm","15":"pa_seria-mwt","16":"pa_siatka-100x100mm","17":"pa_system-fi28","19":"first","20":"instock","21":"sale","22":"taxable","23":"shipping-taxable","24":"purchasable","25":"product-type-variable","26":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product\/14955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/comments?post=14955"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/media\/14956"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/media?parent=14955"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_brand?post=14955"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_cat?post=14955"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/de\/wp-json\/wp\/v2\/product_tag?post=14955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}