﻿{"id":32745,"date":"2026-02-24T09:26:00","date_gmt":"2026-02-24T07:26:00","guid":{"rendered":"https:\/\/gpph-group.com\/?post_type=product&#038;p=32745"},"modified":"2026-06-15T08:49:52","modified_gmt":"2026-06-15T06:49:52","slug":"equerre-de-soudage-300x190mm-fi28-pro-gauche-m","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/be\/p\/entrepot\/narzedzia-przestrzenne\/equerre-de-soudage-300x190mm-fi28-pro-gauche-m\/","title":{"rendered":"\u00c9querre de soudage 300x190 mm - \u03c628 - PRO - Gauche"},"content":{"rendered":"<h3 class=\"wp-block-heading\"><strong>\u00c9querre de soudage \u2013 positionnement pr\u00e9cis des \u00e9l\u00e9ments \u00e0 angle droit<\/strong><\/h3>\n\n\n\n<div class=\"wp-block-media-text has-media-on-the-right is-stacked-on-mobile\"><div class=\"wp-block-media-text__content\">\n<p class=\" translation-block\"><strong>\u00c9querre de soudage<\/strong> est un \u00e9l\u00e9ment de positionnement pr\u00e9cis utilis\u00e9 lors du soudage, de l\u2019assemblage et des travaux de m\u00e9tallerie sur des tables de soudage.<\/p>\n\n\n\n<p><br>Permet un positionnement pr\u00e9cis et un maintien stable des pi\u00e8ces \u00e0 angle droit, essentiel pour l\u2019ajustement et l\u2019assemblage de profils, de tuyaux ou de structures en acier.<\/p>\n<\/div><figure class=\"wp-block-media-text__media\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/7\/0\/370.jpg\" alt=\"\u00c9querre de soudage 300x190 mm, Syst\u00e8me - \u03a628, S\u00e9rie - PRO\" class=\"wp-image-13739 size-full\" srcset=\"https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/7\/0\/370.jpg 800w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/7\/0\/370-600x600.jpg 600w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/7\/0\/370-300x300.jpg 300w, https:\/\/gpph-group.com\/wp-content\/uploads\/nc\/p\/3\/7\/0\/370-64x64.jpg 64w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Structure renforc\u00e9e avec paroi lat\u00e9rale suppl\u00e9mentaire<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">Cette version de l\u2019\u00e9querre de soudage est \u00e9quip\u00e9e d\u2019une <strong>paroi lat\u00e9rale renforc\u00e9e suppl\u00e9mentaire<\/strong> qui augmente consid\u00e9rablement sa <strong>rigidit\u00e9 et sa stabilit\u00e9<\/strong> pendant le travail.<br>Ainsi, l\u2019\u00e9querre conserve un <strong>angle droit parfait<\/strong> m\u00eame sous de fortes charges et permet un <strong>positionnement tr\u00e8s pr\u00e9cis des pi\u00e8ces<\/strong>.<\/p>\n\n\n\n<p class=\" translation-block\">L\u2019\u00e9querre de soudage a une forme en \u201cL\u201d avec un renforcement structurel suppl\u00e9mentaire et est fabriqu\u00e9e avec une grande pr\u00e9cision dimensionnelle.<br>Chaque surface de travail est soigneusement usin\u00e9e, garantissant un <strong>contact parfait<\/strong> et un <strong>positionnement reproductible<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Compatibilit\u00e9 avec les tables de soudage<\/strong><\/h3>\n\n\n\n<p>Les \u00e9querres de soudage sont disponibles en trois s\u00e9ries, adapt\u00e9es aux diff\u00e9rents types de tables de soudage :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li class=\" translation-block\"><strong>EXPERT<\/strong> \u2013 pour tables de soudage avec plateau de <strong>25 mm<\/strong> d\u2019\u00e9paisseur (EXPERT, XWT)<\/li>\n\n\n\n<li class=\" translation-block\"><strong>PRO<\/strong> \u2013 pour tables de soudage avec plateau de <strong>15 mm<\/strong> d\u2019\u00e9paisseur (PRO, MWT, XWT)<\/li>\n\n\n\n<li class=\" translation-block\"><strong>PLUS<\/strong> \u2013 pour tables de soudage avec plateau de <strong>12 mm et 8 mm<\/strong> d\u2019\u00e9paisseur (ECO, PLUS, BASIC, DIY, XWT)<\/li>\n<\/ul>\n\n\n\n<p class=\" translation-block\">Chaque s\u00e9rie conserve une compatibilit\u00e9 totale avec son type de table, garantissant un <strong>ajustement parfait<\/strong> et une <strong>fixation stable<\/strong> des \u00e9l\u00e9ments.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Conception et fabrication<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">L\u2019\u00e9querre est fabriqu\u00e9e en <strong>acier de construction S355J2+N<\/strong>, r\u00e9sistant \u00e0 une utilisation intensive dans des conditions d\u2019atelier.<\/p>\n\n\n\n<p>La paroi lat\u00e9rale suppl\u00e9mentaire augmente la r\u00e9sistance de l\u2019\u00e9querre \u00e0 la torsion et \u00e0 la flexion, lui conf\u00e9rant une plus grande rigidit\u00e9 et stabilit\u00e9 pendant le travail.<\/p>\n\n\n\n<p>La construction soud\u00e9e et durable s\u2019av\u00e8re efficace dans le travail quotidien ainsi que lors de la r\u00e9alisation de projets exigeants. <strong>du\u017cej precyzji i powtarzalno\u015bci<\/strong>.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Avantages de l\u2019utilisation d\u2019une \u00e9querre de soudage renforc\u00e9e<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>positionnement pr\u00e9cis des \u00e9l\u00e9ments \u00e0 angle droit,<\/li>\n\n\n\n<li>Rigidit\u00e9 accrue gr\u00e2ce au renfort lat\u00e9ral<\/li>\n\n\n\n<li>soutien stable et maintien s\u00fbr des pi\u00e8ces,<\/li>\n\n\n\n<li>pr\u00e9paration rapide des structures pour le soudage,<\/li>\n\n\n\n<li>structure en acier durable et r\u00e9sistante<\/li>\n\n\n\n<li>utilisation universelle pour les travaux de soudage, de montage et de m\u00e9tallerie.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Applications<\/strong><\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>positionnement des profil\u00e9s, des tuyaux et des \u00e9l\u00e9ments de structure,<\/li>\n\n\n\n<li>montage et contr\u00f4le des assemblages \u00e0 angle droit,<\/li>\n\n\n\n<li>travaux d\u2019atelier n\u00e9cessitant une grande pr\u00e9cision et une stabilit\u00e9 de positionnement.<\/li>\n<\/ul>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Informations compl\u00e9mentaires<\/strong><\/h3>\n\n\n\n<p class=\" translation-block\">L\u2019\u00e9querre est fabriqu\u00e9e en <strong>Pologne<\/strong> \u00e0 partir de mat\u00e9riaux r\u00e9pondant aux normes de qualit\u00e9 pour les aciers de construction.<\/p>\n\n\n\n<p class=\" translation-block\">Chaque \u00e9l\u00e9ment est soumis \u00e0 un <strong>contr\u00f4le de qualit\u00e9<\/strong>, garantissant le plus haut niveau de fabrication et une longue dur\u00e9e de vie du produit.<\/p>","protected":false},"excerpt":{"rendered":"<p>L\u2019\u00e9querre de soudage 300x190 mm est un outil con\u00e7u pour le positionnement et le serrage d\u2019\u00e9l\u00e9ments soud\u00e9s tridimensionnels sur la table de soudage.<\/p>","protected":false},"featured_media":33288,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":true},"product_brand":[],"product_cat":[441,438],"product_tag":[],"class_list":{"0":"post-32745","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-narzedzia-przestrzenne","7":"product_cat-magazyn","8":"product_shipping_class-narzedzia","9":"pa_grubosc-narzedzia-11mm-15mm-lub-25mm","10":"pa_seria-pro","11":"pa_srednica-otworow-28-lub-16","12":"pa_system-fi28","13":"pa_typ-narzedzia-przestrzenne","14":"pa_wymiar-narzedzia-300x190x65mm","16":"first","17":"instock","18":"sale","19":"taxable","20":"shipping-taxable","21":"purchasable","22":"product-type-variable","23":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product\/32745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/comments?post=32745"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/media\/33288"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/media?parent=32745"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product_brand?post=32745"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product_cat?post=32745"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product_tag?post=32745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}