﻿{"id":13665,"date":"2022-12-14T15:37:00","date_gmt":"2022-12-14T13:37:00","guid":{"rendered":"https:\/\/gpph-group.com\/?product=stol-spawalniczy-plus-2000-x-1000-mm"},"modified":"2026-06-21T09:08:39","modified_gmt":"2026-06-21T07:08:39","slug":"table-de-soudage-plus-2000-x-1000-mm","status":"publish","type":"product","link":"https:\/\/gpph-group.com\/be\/p\/tables-de-soudage\/plus\/table-de-soudage-plus-2000-x-1000-mm\/","title":{"rendered":"Table de soudage PLUS 12 mm \u2013 2000x1000 mm"},"content":{"rendered":"<p class=\" translation-block\">Tu utiliseras les tables de soudage partout o\u00f9 <strong>la pr\u00e9cision lors du soudage<\/strong> est requise. Tu les utiliseras pour le soudage manuel ou robotis\u00e9. <strong>Tes constructions seront enfin r\u00e9alis\u00e9es avec exactitude, sans retouches inutiles\u202f!<\/strong><\/p>\n<p>Il assure \u00e9galement un travail ergonomique et rapide tout en conservant la pr\u00e9cision et la r\u00e9p\u00e9tabilit\u00e9 des structures r\u00e9alis\u00e9es.<\/p>\n<p class=\" translation-block\"><strong>La table de soudage doit \u00eatre plane !<\/strong> Les plateaux des tables PLUS, d\u2019une \u00e9paisseur de 12 mm, pr\u00e9sentent un nervurage dense, ce qui garantit une surface de travail parfaitement plane. Une table de dimensions 2000x1000 mm poss\u00e8de 2 nervures longitudinales et 4 nervures transversales. La structure massive et rigide du plateau garantit une stabilit\u00e9 maximale lors de l\u2019utilisation ainsi qu\u2019une protection contre la d\u00e9formation. La tol\u00e9rance de plan\u00e9it\u00e9 sur toute la surface de la table est de \u2264<strong>0,15<\/strong><strong> mm<\/strong>*.<\/p>\n<table class=\"description_table--thickness_and_ribbing\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img fetchpriority=\"high\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/BLAT_PLUS.jpg\" alt=\"Plateau de table de soudage\" width=\"500\" height=\"500\" \/><\/td>\n<td><img decoding=\"async\" class=\"mh-500\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/stoly\/ozebrowanie\/ozebrowanie_2000x1000.jpg\" alt=\"C\u00f4tes de table 2000 x 1000 mm\" width=\"500\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>C\u2019est toi qui d\u00e9cides\u202f! <\/strong><\/p>\n<table class=\"descriptionSystemsTable\" style=\"margin-left: auto; margin-right: auto;\">\n<tbody>\n<tr>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/100x100_fi28.jpg\" alt=\"Maille 100\u00d7100\u202fmm, syst\u00e8me fi28\" width=\"500\" height=\"188\" \/><\/td>\n<td><img decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/100x100_fi16.jpg\" alt=\"Maille 100 x 100 mm, syst\u00e8me fi16\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<tr>\n<td style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/diagonal_fi28.jpg\" alt=\"Grille diagonale, syst\u00e8me fi28\" width=\"500\" height=\"188\" \/><\/td>\n<td><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/diagonal_fi16.jpg\" alt=\"Grille diagonale, syst\u00e8me fi28\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<tr>\n<td colspan=\"2\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/50x50_fi16.jpg\" alt=\"Maille 50 x 50 mm, syst\u00e8me fi16\" width=\"500\" height=\"188\" \/><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p class=\" translation-block\"><strong>Les trous frais\u00e9s et chanfrein\u00e9s<\/strong> dans la surface de la table facilitent le montage et le d\u00e9montage des outils pendant votre travail, gr\u00e2ce \u00e0 l\u2019ajustement appropri\u00e9 des trous aux outils. Cela contribue \u00e9galement \u00e0 r\u00e9duire leur usure\u202f\u2013 vous n\u2019avez pas besoin d\u2019une grande force pour les monter ou les d\u00e9monter. Cette r\u00e9alisation est la meilleure des solutions disponibles sur le march\u00e9 des tables de soudage\u202f! La tol\u00e9rance d\u2019ex\u00e9cution des trous de la table de soudage est de <strong>\u00b10,05\u202fmm<\/strong>.<\/p>\n<p class=\" translation-block\">La\u202f<strong>graduation grav\u00e9e<\/strong> du plateau de la table correspond \u00e0 des lignes verticales et horizontales dans une grille de 100\u00d7100\u202fmm. Elle sert de point de r\u00e9f\u00e9rence lors du positionnement de la construction et pendant le montage des outils. \u00c0 l\u2019aide d\u2019instruments de mesure, vous pouvez ajuster votre construction de mani\u00e8re appropri\u00e9e pour obtenir la dimension requise.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/grawerowana_podzialka.jpg\" alt=\"\u00c9chelle grav\u00e9e\" width=\"1000\" height=\"500\" \/><\/p>\n<p>Nogi w Sto\u0142ach Spawalniczych PLUS, wykonane z profilu 80&#215;80 mm, maj\u0105 no\u015bno\u015b\u0107 7500 kg\/noga. W przypadku wymiaru 3000&#215;1480 mm, kt\u00f3ry ma 8 n\u00f3g, otrzymujesz maksymaln\u0105 no\u015bno\u015b\u0107 6 000 kg.<\/p>\n<p>Tu as le choix\u202f: pied avec socle ou sur roulettes\u202f\u2013 d\u00e9couvre ce qui sera le mieux pour toi.<\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/gpph-group.com\/wp-content\/uploads\/pl\/sklep\/img\/cms\/nosnosc_nogi_PLUS.jpg\" alt=\"Capacit\u00e9 de charge du pied de la table de soudage PLUS\" width=\"500\" height=\"500\" \/><\/p>\n<p>Pour travailler sur les tables de soudage de la s\u00e9rie PLUS, vous utiliserez les outils frais\u00e9s PLUS. Gr\u00e2ce \u00e0 eux, vous r\u00e9aliserez avec pr\u00e9cision toutes les constructions planes en 2D et spatiales en 3D. Et tout cela en beaucoup moins de temps !<\/p>\n<p>*\u00e0 condition que la table soit correctement mise \u00e0 niveau.<\/p>","protected":false},"excerpt":{"rendered":"<p>Sto\u0142y Spawalnicze wykorzystasz wsz\u0119dzie tam, gdzie potrzebna jest precyzja podczas spawania. U\u017cyjesz go do spawania manualnego lub zrobotyzowanego. Twoje konstrukcje nareszcie b\u0119d\u0105 wykonane dok\u0142adnie, bez zb\u0119dnego poprawiania! Zapewnia on tak\u017ce ergonomiczn\u0105 i szybk\u0105 prac\u0119 przy zachowaniu precyzji oraz powtarzalno\u015b\u0107 wykonywanych konstrukcji. St\u00f3\u0142 Spawalniczy musi by\u0107 p\u0142aski! Blaty Sto\u0142\u00f3w PLUS, maj\u0105ce grubo\u015b\u0107 12mm, posiadaj\u0105 g\u0119ste o\u017cebrowanie, [&hellip;]<\/p>","protected":false},"featured_media":31511,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[426,68,111,85],"product_tag":[],"class_list":{"0":"post-13665","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-plus","7":"product_cat-stoly-spawalnicze","8":"product_cat-2000x1000-mm","9":"product_cat-tradycyjne","10":"product_shipping_class-stol-spawalniczy-2000","11":"pa_grawerowana-podzialka-tak-siatka-100x100-mm","12":"pa_grubosc-blatu-12-mm","13":"pa_nogi-na-kolach","14":"pa_nogi-na-stopach","15":"pa_nosnosc-750kg-noga","16":"pa_otwory-frezowane-i-fazowane","17":"pa_profil-nog-80x80x4-mm","18":"pa_rozmiar-2000x1000mm","19":"pa_seria-plus","20":"pa_siatka-100x100mm","21":"pa_siatka-50x50mm","22":"pa_siatka-diagonalna","23":"pa_system-fi16","24":"pa_system-fi28","25":"pa_tolerancja-plaskosci-015-mm-mniejsze-lub-rowne-0-15-mm","26":"pa_tolerancja-wykonania-otworow-005-mm","27":"pa_wzmocnienie-zebrami-tak","29":"first","30":"instock","31":"sale","32":"taxable","33":"shipping-taxable","34":"purchasable","35":"product-type-variable","36":"has-default-attributes"},"acf":[],"_links":{"self":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product\/13665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/comments?post=13665"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/media\/31511"}],"wp:attachment":[{"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/media?parent=13665"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product_brand?post=13665"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product_cat?post=13665"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/gpph-group.com\/be\/wp-json\/wp\/v2\/product_tag?post=13665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}